{"id":10447,"date":"2025-06-10T06:31:55","date_gmt":"2025-06-10T09:31:55","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10447"},"modified":"2025-06-10T06:31:56","modified_gmt":"2025-06-10T09:31:56","slug":"prefeitura-de-socorro-inicia-construcao-de-escola-municipal-no-parque-dos-farois","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/10\/prefeitura-de-socorro-inicia-construcao-de-escola-municipal-no-parque-dos-farois\/","title":{"rendered":"Prefeitura de Socorro inicia constru\u00e7\u00e3o de escola municipal no Parque dos Far\u00f3is"},"content":{"rendered":"\n<p>Atendendo a um antigo anseio da comunidade do Parque dos Far\u00f3is, a Prefeitura de Nossa Senhora Socorro, por meio da Secretaria Municipal da Educa\u00e7\u00e3o, iniciou a obra de constru\u00e7\u00e3o do novo pr\u00e9dio da Escola Municipal Jo\u00e3o Vasconcelos Prado. A obra foi oficialmente autorizada nesta segunda-feira (9), com a assinatura da ordem de servi\u00e7o pelo prefeito Samuel Carvalho. O novo pr\u00e9dio est\u00e1 sendo erguido no mesmo terreno onde, h\u00e1 anos atr\u00e1s, funcionava a escola, que, ap\u00f3s desmoronar, passou a operar em um pr\u00e9dio tempor\u00e1rio e alugado, sem a infraestrutura adequada.<\/p>\n\n\n\n<p>Com um investimento de R$ 4.375.493,80, a escola ter\u00e1 capacidade para atender cerca de 360 alunos, e contar\u00e1 com seis salas de aula, refeit\u00f3rio, cozinha, dep\u00f3sito, banheiros, diretoria, sala dos professores e coordena\u00e7\u00e3o.<\/p>\n\n\n\n<p>Ao assinar a ordem de servi\u00e7o, o prefeito Samuel Carvalho refor\u00e7ou seu compromisso com a educa\u00e7\u00e3o do munic\u00edpio. &#8220;Essa escola, com quase 50 anos de hist\u00f3ria, foi o ponto de partida para a forma\u00e7\u00e3o de muitas crian\u00e7as da nossa cidade. Infelizmente, precisou ser realocada, mas isso est\u00e1 prestes a mudar. Vamos reconstru\u00ed-la aqui, no seu local de origem, para que volte a acolher centenas de alunos e continue contribuindo com o futuro da nossa educa\u00e7\u00e3o. A mudan\u00e7a come\u00e7a agora&#8221;, discursou o gestor.<\/p>\n\n\n\n<p>Durante sua fala, a secret\u00e1ria da Educa\u00e7\u00e3o, Adriana Carvalho, afirmou que esta reconstru\u00e7\u00e3o era um pedido antigo da comunidade. &#8220;Nossa educa\u00e7\u00e3o n\u00e3o para, sempre temos uma novidade, porque nossos alunos merecem. No primeiro m\u00eas visitei as escolas e quando fui na Jo\u00e3o Vasconcelos, que est\u00e1 no momento em um espa\u00e7o alugado, vi que n\u00e3o era o local ideal para as nossas crian\u00e7as. Ent\u00e3o, a partir da\u00ed, verifiquei a urg\u00eancia da constru\u00e7\u00e3o. O nosso povo merece o melhor, nossas crian\u00e7as, que s\u00e3o o futuro do amanh\u00e3, merecem o melhor&#8221;, disse.<\/p>\n\n\n\n<p>O momento de assinatura da ordem de servi\u00e7o foi prestigiado pela comunidade escolar, alunos, pais, professores e a equipe educacional acompanharam a solenidade. &#8220;Eu e tamb\u00e9m os pais est\u00e1vamos ansiosos para mudar de escola, porque eu digo sempre, a educa\u00e7\u00e3o precisa de bons profissionais e tamb\u00e9m precisa do espa\u00e7o f\u00edsico que lhes d\u00ea condi\u00e7\u00f5es para desenvolver o trabalho. Fiquei muito ansiosa, e a primeira coisa que falei quando vi Adriana foi &#8216;precisamos mudar de escola&#8217;. Ent\u00e3o, agrade\u00e7o, de cora\u00e7\u00e3o, por mim, pelos pais e pelos alunos&#8221;, disse a diretora da unidade escolar, Luziete Rodrigues.<\/p>\n\n\n\n<p>Para Lucia Santos, moradora da localidade e m\u00e3e de tr\u00eas filhos, a sensa\u00e7\u00e3o \u00e9 de felicidade. &#8220;Estou me sentindo realizada, porque \u00e9 uma obra h\u00e1 muito tempo esperada e que agora vai sair do papel, estou muito satisfeita&#8221;, disse ela, que tem um filho j\u00e1 matriculado na Escola Municipal Jo\u00e3o Vasconcelos Prado e relata que o pr\u00e9dio onde hoje a escola opera \u00e9 distante da sua resid\u00eancia. &#8220;Aqui \u00e9 mais perto, vai ter mais espa\u00e7o para as crian\u00e7as brincarem do que l\u00e1 onde eles estudam agora, vai ser uma maravilha&#8221;.<\/p>\n\n\n\n<p>Esse \u00e9 mais um avan\u00e7o na educa\u00e7\u00e3o municipal, demonstrando o compromisso da gest\u00e3o com o futuro das crian\u00e7as e adolescentes. Apenas nestes seis meses, j\u00e1 foram mais de 1.500 vagas abertas, diminuindo a quantidade de alunos no cadastro reserva e ofertando melhores condi\u00e7\u00f5es de ensino e aprendizado.<\/p>\n\n\n\n<p>Foto: Milton Carvalho<\/p>\n\n\n\n<p>Fonte: Assessoria de Comunica\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atendendo a um antigo anseio da comunidade do Parque dos Far\u00f3is, a Prefeitura de Nossa Senhora Socorro, por meio da Secretaria Municipal da Educa\u00e7\u00e3o, iniciou a obra de constru\u00e7\u00e3o do novo pr\u00e9dio da Escola Municipal Jo\u00e3o Vasconcelos Prado. A obra foi oficialmente autorizada nesta segunda-feira (9), com a assinatura da ordem de servi\u00e7o pelo prefeito [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-10447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10447"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10447\/revisions"}],"predecessor-version":[{"id":10449,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10447\/revisions\/10449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10448"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}