{"id":10496,"date":"2025-06-10T11:16:01","date_gmt":"2025-06-10T14:16:01","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10496"},"modified":"2025-06-10T11:16:02","modified_gmt":"2025-06-10T14:16:02","slug":"cinema-e-cultura-quilombola-abrem-a-rota-dos-quilombos-em-sergipe","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/10\/cinema-e-cultura-quilombola-abrem-a-rota-dos-quilombos-em-sergipe\/","title":{"rendered":"Cinema e cultura quilombola abrem a Rota dos Quilombos em Sergipe"},"content":{"rendered":"\n<p>Circuito realizado pelo Cineclube Candeeiro estreia no dia 14 de junho, na comunidade da Mussuca (Laranjeiras), com sess\u00f5es de cinema ao ar livre<\/p>\n\n\n\n<p>No pr\u00f3ximo s\u00e1bado, 14 de junho, a comunidade quilombola Mussuca, localizada no munic\u00edpio de Laranjeiras (SE), recebe a abertura da Rota dos Quilombos \u2014 circuito cineclubista realizado pelo Cineclube Candeeiro, que promove sess\u00f5es gratuitas de cinema e rodas de conversa em territ\u00f3rios negros do estado. A estreia faz parte do Arrai\u00e1 Cultur\u00e1 da Cozinha de V\u00f3, tradicional celebra\u00e7\u00e3o local que une arte, mem\u00f3ria e saberes quilombolas.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o come\u00e7a \u00e0s 18h, com a sess\u00e3o infantil Mostrinha Vunji, dedicada \u00e0s crian\u00e7as da comunidade. \u00c0s 19h, ser\u00e1 exibida a sess\u00e3o Rota dos Quilombos + EGB\u00c9, voltada ao p\u00fablico jovem, adulto e idoso. Toda a curadoria de filmes \u00e9 assinada pela EGB\u00c9 \u2013 Mostra de Cinema Negro, que selecionou obras de diferentes regi\u00f5es do Brasil \u2014 incluindo produ\u00e7\u00f5es sergipanas \u2014 com tem\u00e1ticas como quilombismo, cosmologias negras, tradi\u00e7\u00f5es populares e subjetividades perif\u00e9ricas.<\/p>\n\n\n\n<p>A Mussuca \u00e9 o maior quilombo de Sergipe e ber\u00e7o de uma das express\u00f5es culturais mais potentes do estado. Com um rico bioma entre mata atl\u00e2ntica e manguezais, o territ\u00f3rio abriga tradi\u00e7\u00f5es como o samba de coco, o tambor dos terreiros e pr\u00e1ticas agr\u00edcolas ancestrais. \u00c9 nesse ch\u00e3o, onde vivem mestras e mestres da cultura popular, que a Cozinha de V\u00f3 se tornou refer\u00eancia ao retomar pr\u00e1ticas de culin\u00e1ria, constru\u00e7\u00e3o e saberes coletivos. A presen\u00e7a da Rota dos Quilombos nesse espa\u00e7o reafirma o papel central da comunidade na preserva\u00e7\u00e3o da identidade negra em Sergipe.<\/p>\n\n\n\n<p>Com foco na interioriza\u00e7\u00e3o do cinema negro e na valoriza\u00e7\u00e3o da identidade afro-brasileira, a Rota dos Quilombos transforma pra\u00e7as, escolas e espa\u00e7os comunit\u00e1rios em locais de encontro, pertencimento e forma\u00e7\u00e3o cr\u00edtica. A iniciativa \u00e9 inspirada no pensamento da historiadora sergipana Beatriz Nascimento, que dizia: &#8220;\u00e9 preciso a imagem para recuperar a identidade&#8221;.<\/p>\n\n\n\n<p>Ap\u00f3s a Mussuca, a Rota segue para Brej\u00e3o dos Negros (Brejo Grande), no dia 19 de julho, e finaliza no Povoado Aguada (Carm\u00f3polis), em 26 de julho \u2014 sempre com sess\u00f5es ao ar livre e rodas de conversa com a comunidade.<\/p>\n\n\n\n<p>Mussuca \u2013 Laranjeiras<\/p>\n\n\n\n<p>Sexta-feira, 14 de junho<\/p>\n\n\n\n<p>18h \u2013 Sess\u00e3o infantil Mostrinha Vunji<\/p>\n\n\n\n<p>19h \u2013 Sess\u00e3o Rota dos Quilombos + EGB\u00c9 + roda de conversa<\/p>\n\n\n\n<p>Texto e foto: Ayalla Anjos &#8211; Comunica\u00e7\u00e3o e Marketing<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Circuito realizado pelo Cineclube Candeeiro estreia no dia 14 de junho, na comunidade da Mussuca (Laranjeiras), com sess\u00f5es de cinema ao ar livre No pr\u00f3ximo s\u00e1bado, 14 de junho, a comunidade quilombola Mussuca, localizada no munic\u00edpio de Laranjeiras (SE), recebe a abertura da Rota dos Quilombos \u2014 circuito cineclubista realizado pelo Cineclube Candeeiro, que promove [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,10],"tags":[],"class_list":["post-10496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10496"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10496\/revisions"}],"predecessor-version":[{"id":10498,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10496\/revisions\/10498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10497"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}