{"id":10502,"date":"2025-06-10T11:33:33","date_gmt":"2025-06-10T14:33:33","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10502"},"modified":"2025-06-10T11:33:34","modified_gmt":"2025-06-10T14:33:34","slug":"inicio-dos-festejos-juninos-traz-o-alerta-para-o-combate-ao-crime-de-vandalismo","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/10\/inicio-dos-festejos-juninos-traz-o-alerta-para-o-combate-ao-crime-de-vandalismo\/","title":{"rendered":"In\u00edcio dos festejos juninos traz o alerta para o combate ao crime de vandalismo"},"content":{"rendered":"\n<p>Com altos \u00edndices de depreda\u00e7\u00e3o no per\u00edodo junino de 2024, setor de transporte alerta sobre preju\u00edzos e consequ\u00eancias do crime<\/p>\n\n\n\n<p>Sergipe \u00e9 considerado o \u2018pa\u00eds\u2019 do forr\u00f3, e nos meses dos festejos juninos essa consagra\u00e7\u00e3o ganha vida no solado das botas de quem est\u00e1 no estado. As ruas ficam mais coloridas, e as cidades da Grande Aracaju ainda mais convidativas. Contudo, o que deveria ser apenas motivo de festejo revela um problema: o expressivo aumento dos casos de vandalismo no transporte p\u00fablico, comprometendo inclusive a mobilidade de quem deseja aproveitar a tradi\u00e7\u00e3o das cidades.<\/p>\n\n\n\n<p>No ano passado, entre os meses de junho e julho, em apenas uma das empresas que prestam o servi\u00e7o de transporte p\u00fablico em Aracaju e regi\u00e3o metropolitana, foram registrados mais de 20 casos de vandalismo. Ainda em 2024, o setor teve um preju\u00edzo de mais de 37,7 mil reais, referente ao investimento necess\u00e1rio para reparar a depreda\u00e7\u00e3o dos ve\u00edculos, um custo que, ao ser inclu\u00eddo no c\u00e1lculo tarif\u00e1rio, pode contribuir para o aumento no valor da tarifa.<\/p>\n\n\n\n<p>&nbsp;\u201cO ato de vandalismo no transporte afeta diretamente o passageiro que utiliza o servi\u00e7o. Quando um ve\u00edculo \u00e9 depredado, ele precisa retornar \u00e0 garagem, a fim de n\u00e3o expor os passageiros a qualquer risco ao seu bem-estar. Al\u00e9m de impactar a distribui\u00e7\u00e3o da frota, essa a\u00e7\u00e3o criminosa tamb\u00e9m prejudica os passageiros que utilizam os \u00f4nibus de forma adequada, pois o expressivo custo anual gerado por esses atos pode influenciar no c\u00e1lculo tarif\u00e1rio, com possibilidade de ser adicionado no reajuste da passagem\u201d, explica a presidente do Setransp, Raissa Cruz.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Mesmo com o aumento consider\u00e1vel dos casos de vandalismo nos per\u00edodos festivos, o crime \u00e9 recorrente durante todo o ano, gerando transtornos e receio nos passageiros que est\u00e3o dentro do ve\u00edculo. Somente este ano, no per\u00edodo de janeiro a abril, foram contabilizados mais de 34 casos.<\/p>\n\n\n\n<p>Breno Souder \u00e9 estudante de jornalismo e j\u00e1 presenciou um caso de vandalismo, acompanhado de agress\u00e3o ao motorista, causando transtornos e p\u00e2nico aos passageiros que estavam dentro do ve\u00edculo. Ele relata com detalhes o que aconteceu.<\/p>\n\n\n\n<p>&nbsp;\u201cUma vez, na Bar\u00e3o de Maruim, vi dois jovens entrarem no \u00f4nibus e pularem a catraca. Na Ad\u00e9lia Franco, eles deram sinal para descer, mas o motorista passou do ponto, sem querer. Revoltados, come\u00e7aram a xing\u00e1-lo com palavras de baixo cal\u00e3o, pularam de novo a catraca para a parte da frente e o agrediram com socos. Os passageiros, apavorados, pediam para o motorista abrir a porta. Quando ele conseguiu, os agressores desceram, pegaram uma pedra e quebraram o vidro do \u00f4nibus, o mesmo que poderia servir aos pr\u00f3prios familiares deles. Para mim, o vandalismo exige uma resposta firme do poder p\u00fablico\u201d, explica o passageiro.<\/p>\n\n\n\n<p>Al\u00e9m do crime de vandalismo, outro problema recorrente no transporte p\u00fablico e que se agrava nos per\u00edodos festivos s\u00e3o os pulos de catraca. No ano passado, foi registrada uma m\u00e9dia de 2 mil pulos di\u00e1rios no m\u00eas de junho, o que interfere diretamente na identifica\u00e7\u00e3o da demanda de passageiros.<\/p>\n\n\n\n<p>\u201cQuando acontece o pulo de catraca, as empresas n\u00e3o conseguem registrar a quantidade exata de passageiros das linhas. Isso provoca uma distor\u00e7\u00e3o na distribui\u00e7\u00e3o da frota, o que pode resultar em superlota\u00e7\u00e3o e atrasos na presta\u00e7\u00e3o do servi\u00e7o. Isso ocorre porque, todas as vezes que algu\u00e9m pula a catraca, essa pessoa n\u00e3o \u00e9 identificada como passageira nos registros, sendo contabilizada uma quantidade menor do que a real\u201d, relata o diretor da Via\u00e7\u00e3o Atalaia, Emmanuel Lima.<\/p>\n\n\n\n<p>Consequ\u00eancias dos crimes<\/p>\n\n\n\n<p>Quem comete deteriora\u00e7\u00e3o no transporte p\u00fablico pode enfrentar pris\u00e3o e multa, de acordo com o artigo 163 do C\u00f3digo Penal Brasileiro. A pena pode variar de seis meses a tr\u00eas anos de deten\u00e7\u00e3o. J\u00e1 o artigo 176 do C\u00f3digo Penal estabelece como fraude o ato de utilizar-se do meio de transporte sem dispor de recursos necess\u00e1rios para efetuar o pagamento, o que pode resultar em pena de deten\u00e7\u00e3o de 15 dias a 2 meses, ou multa.<\/p>\n\n\n\n<p>Texto e foto ascom Setransp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com altos \u00edndices de depreda\u00e7\u00e3o no per\u00edodo junino de 2024, setor de transporte alerta sobre preju\u00edzos e consequ\u00eancias do crime Sergipe \u00e9 considerado o \u2018pa\u00eds\u2019 do forr\u00f3, e nos meses dos festejos juninos essa consagra\u00e7\u00e3o ganha vida no solado das botas de quem est\u00e1 no estado. As ruas ficam mais coloridas, e as cidades da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,4,6],"tags":[],"class_list":["post-10502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-economia","category-letreiro"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10502"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10502\/revisions"}],"predecessor-version":[{"id":10504,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10502\/revisions\/10504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10503"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}