{"id":10522,"date":"2025-06-10T13:16:45","date_gmt":"2025-06-10T16:16:45","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10522"},"modified":"2025-06-10T13:16:45","modified_gmt":"2025-06-10T16:16:45","slug":"gincana-junina-reune-45-escolas-em-celebracao-a-cultura-sergipana","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/10\/gincana-junina-reune-45-escolas-em-celebracao-a-cultura-sergipana\/","title":{"rendered":"Gincana Junina re\u00fane 45 escolas em celebra\u00e7\u00e3o \u00e0 cultura sergipana"},"content":{"rendered":"\n<p>Evento transforma o Arrai\u00e1 do Povo em uma aula viva de tradi\u00e7\u00e3o<\/p>\n\n\n\n<p>No ritmo contagiante do forr\u00f3 e com o cheiro da comida t\u00edpica no ar, o Arrai\u00e1 do Povo, na Orla da Atalaia, foi tomado pela energia e criatividade de estudantes, professores, servidores e merendeiras das escolas da rede estadual de ensino em Aracaju. Com o tema &#8216;Forr\u00f3, Arte e Tradi\u00e7\u00e3o&#8217;, a 4\u00aa Gincana Junina da Diretoria de Educa\u00e7\u00e3o de Aracaju (DEA) transformou a tarde da \u00faltima segunda-feira, 9, em uma verdadeira celebra\u00e7\u00e3o da Sergipanidade, integrando 45 escolas em um grande mosaico de tradi\u00e7\u00e3o nordestina, aprendizagem e pertencimento.<\/p>\n\n\n\n<p>A a\u00e7\u00e3o faz parte da programa\u00e7\u00e3o do Festival Junino Estudantil da Secretaria de Estado da Educa\u00e7\u00e3o (Fejune 2025) e reuniu sete equipes interescolares para cumprir cinco tarefas que exploraram diferentes express\u00f5es da cultura nordestina. Com apresenta\u00e7\u00f5es de pratos t\u00edpicos, desfiles juninos, coreografias, gritos de guerra e interpreta\u00e7\u00f5es musicais de artistas regionais, a gincana encantou o p\u00fablico e reafirmou o compromisso da educa\u00e7\u00e3o com a valoriza\u00e7\u00e3o das tradi\u00e7\u00f5es populares.<\/p>\n\n\n\n<p>A diretora da DEA, Gilv\u00e2nia Guimar\u00e3es, destacou a import\u00e2ncia do evento para o fortalecimento da sergipanidade e o envolvimento de toda a comunidade escolar. \u201cFazemos parte do Fejune 2025 e realizamos a nossa tradicional gincana que, neste ano, chega \u00e0 sua quarta edi\u00e7\u00e3o. Foram 45 escolas divididas em sete equipes, com especial aten\u00e7\u00e3o aos alunos do Ensino Fundamental \u2013 Anos Iniciais. Foi uma tarde maravilhosa, com tarefas que envolveram desde as merendeiras, passando pelos professores, at\u00e9 chegar aos estudantes. Uma celebra\u00e7\u00e3o completa da nossa identidade cultural\u201d, afirmou.<\/p>\n\n\n\n<p>Pela primeira vez no evento, as primas e alunas do 5\u00ba ano da Escola Estadual Wolney Leal de Melo, Alessandra e Marcela, ambas com 10 anos, torceram muito pela equipe &#8216;Tu Guenta?&#8217;, sobretudo durante a realiza\u00e7\u00e3o da tarefa &#8216;Forrozinho danado de bom&#8217;, uma novidade desta edi\u00e7\u00e3o, que privilegiou a apresenta\u00e7\u00e3o de uma coreografia em ritmo junino por um grupo de estudantes dos anos iniciais do Ensino Fundamental. \u201cEstou gostando muito das apresenta\u00e7\u00f5es\u201d, disse Alessandra. \u201cCom certeza, a mais bonita foi a da nossa equipe\u201d, completou Marcela.<\/p>\n\n\n\n<p>Outro destaque da gincana, a tarefa &#8216;Del\u00edcia Junina&#8217; deu um sabor especial \u00e0 competi\u00e7\u00e3o. As equipes apresentaram pratos criados pelas merendeiras, valorizando ingredientes regionais e a criatividade gastron\u00f4mica. A merendeira Anne Karoline Machado Santos, da Escola Estadual Senador Leite Neto, levou \u00e0 banca de jurados um escondidinho de milho recheado com carne do sol, calabresa e bacon, ma\u00e7aricado com queijo coalho e acompanhado por um brigadeiro mole de pa\u00e7oca com caramelo. \u201cEsse evento valoriza a cultura e tamb\u00e9m o trabalho de quem est\u00e1 nos bastidores. Fizemos tudo com muito carinho, pesquisamos e testamos receitas. Foi um orgulho participar\u201d, disse Anne.<\/p>\n\n\n\n<p>A criatividade tamb\u00e9m esteve presente na equipe do Instituto Educacional Santa Terezinha do Menino Jesus, que encantou o p\u00fablico com um tradicional xer\u00e9m com galinha. A merendeira Denira dos Santos destacou a simplicidade e o sabor como os diferenciais do prato. \u201cFizemos um teste na escola e todos aprovaram. \u00c9 muito bom poder demonstrar um pouco da nossa criatividade e participar desse momento com a comunidade escolar\u201d, afirmou.<\/p>\n\n\n\n<p>Mais do que competi\u00e7\u00e3o, a gincana foi um espa\u00e7o de integra\u00e7\u00e3o entre unidades escolares. Para Silvio Ricardo Ferreira Chagas, coordenador pedag\u00f3gico da&nbsp; Escola Estadual Professor Valnir Chagas e integrante da equipe Cangaceiros da DEA, eventos como esse s\u00e3o oportunidades de fortalecer la\u00e7os e promover o trabalho coletivo. \u201c\u00c9 um momento riqu\u00edssimo, que proporciona intera\u00e7\u00e3o entre alunos, professores e servidores de diferentes unidades, al\u00e9m de valorizar a cultura do nosso estado\u201d, ressaltou.<\/p>\n\n\n\n<p>Al\u00e9m das apresenta\u00e7\u00f5es das equipes, o evento contou com abertura e encerramento animados pelas quadrilhas juninas Xod\u00f3 do Sert\u00e3o e Joaquim no Arrasta P\u00e9, formadas por estudantes da rede estadual. O j\u00fari foi composto por personalidades ligadas \u00e0 cultura sergipana, como o sanfoneiro Mimi do Acordeon; a estilista de quadrilhas juninas Jeane Teixeira; a professora de dan\u00e7a Dayanne Alves e os atores e pesquisadores da cultura popular Manoel Cerqueira e Jad Rocha.<\/p>\n\n\n\n<p>Para o vice-governador e secret\u00e1rio de Estado da Educa\u00e7\u00e3o, Zezinho Sobral, a gincana \u00e9 um exemplo de como a educa\u00e7\u00e3o pode ser uma ferramenta de preserva\u00e7\u00e3o e promo\u00e7\u00e3o cultural. \u201cA gente revive de forma educacional a nossa hist\u00f3ria, as nossas m\u00fasicas e tradi\u00e7\u00f5es. Que todas essas manifesta\u00e7\u00f5es sejam reiteradas a cada ano, para que estejam fortalecidas em todo o estado. Esse \u00e9 o papel da educa\u00e7\u00e3o: florescer a nossa cultura e identidade em nossas crian\u00e7as e jovens\u201d, declarou.<\/p>\n\n\n\n<p>A 4\u00aa Gincana Junina da DEA mostrou que, quando a escola valoriza a cultura local, ela se torna ainda mais significativa na vida dos estudantes. Em cada tarefa, um gesto de pertencimento; em cada sorriso, a certeza de que a educa\u00e7\u00e3o sergipana tamb\u00e9m abra\u00e7a o forr\u00f3, a arte e a tradi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Mais Fejune<\/p>\n\n\n\n<p>O Festival Junino da Educa\u00e7\u00e3o segue com vasta programa\u00e7\u00e3o nesta semana. Nesta ter\u00e7a-feira, 10, ser\u00e1 a vez de as diretorias regionais de educa\u00e7\u00e3o do baixo S\u00e3o Francisco (DRE 6) e leste sergipano (DRE 4) festejarem o S\u00e3o Jo\u00e3o. Na quarta-feira, 11, o Fejune desembarca no alto sert\u00e3o sergipano, contemplando as comunidades escolares das DREs 7 e 9.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Foto: Maria Od\u00edlia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento transforma o Arrai\u00e1 do Povo em uma aula viva de tradi\u00e7\u00e3o No ritmo contagiante do forr\u00f3 e com o cheiro da comida t\u00edpica no ar, o Arrai\u00e1 do Povo, na Orla da Atalaia, foi tomado pela energia e criatividade de estudantes, professores, servidores e merendeiras das escolas da rede estadual de ensino em Aracaju. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,6,10],"tags":[],"class_list":["post-10522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-letreiro","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10522"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10522\/revisions"}],"predecessor-version":[{"id":10524,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10522\/revisions\/10524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10523"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}