{"id":10696,"date":"2025-06-11T14:33:00","date_gmt":"2025-06-11T17:33:00","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10696"},"modified":"2025-06-11T14:59:13","modified_gmt":"2025-06-11T17:59:13","slug":"cma-aprova-13-proposituras-sendo-uma-frente-parlamentar-que-busca-prevenir-e-tratar-a-diabetes-mellitus-1","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/11\/cma-aprova-13-proposituras-sendo-uma-frente-parlamentar-que-busca-prevenir-e-tratar-a-diabetes-mellitus-1\/","title":{"rendered":"CMA aprova 13 proposituras, sendo uma frente parlamentar que busca prevenir e tratar a diabetes mellitus 1"},"content":{"rendered":"\n<p>Nesta quarta-feira (11\/06), por meio da 45\u00aa Sess\u00e3o Ordin\u00e1ria, a C\u00e2mara de Vereadores de Aracaju apreciou 13 proposituras. Confira o que foi aprovado na Casa do Povo.&nbsp;<\/p>\n\n\n\n<p>Projeto de resolu\u00e7\u00e3o<\/p>\n\n\n\n<p>De autoria do vereador Elber Batalha, o Projeto de Resolu\u00e7\u00e3o n\u00ba 8\/2024 foi aprovado em reda\u00e7\u00e3o final. Ele cria, na C\u00e2mara Municipal de Aracaju, a Frente Parlamentar para Preven\u00e7\u00e3o, Diagn\u00f3stico e Tratamento da Diabetes Mellitus Tipo 1 \u2013 DM1. Outros vereadores tamb\u00e9m est\u00e3o participando da iniciativa. Segundo o vereador Elber Batalha, o objetivo dessa frente parlamentar \u00e9 garantir solu\u00e7\u00f5es na \u00e1rea da sa\u00fade para crian\u00e7as com essa doen\u00e7a. Atualmente, cerca de 200 crian\u00e7as em Aracaju est\u00e3o sendo beneficiadas por meio das emendas impositivas dos vereadores, que somam cerca de R$ 1 milh\u00e3o.<\/p>\n\n\n\n<p>Projeto de lei&nbsp;<\/p>\n\n\n\n<p>De autoria da vereadora S\u00f4nia Meire, foi aprovado em primeira discuss\u00e3o o Projeto de Lei n\u00ba 146\/2024. Ele disp\u00f5e sobre a inclus\u00e3o da tem\u00e1tica &#8220;trabalho escravo contempor\u00e2neo&#8221; em atividades extracurriculares da rede municipal de ensino de Aracaju.<\/p>\n\n\n\n<p>Projetos de decreto legislativo<\/p>\n\n\n\n<p>De autoria do vereador Rodrigo Fontes, o Projeto de Decreto Legislativo n\u00ba 26\/2025 concede T\u00edtulo de Cidadania Aracajuana ao Sr. Lineu Henriques Carmagos. \u201cO doutor Lineu \u00e9 um m\u00e9dico apaixonado por esta terra. Tenho certeza de que ele ficar\u00e1 muito feliz com essa a\u00e7\u00e3o\u201d, destacou Rodrigo.<\/p>\n\n\n\n<p>Requerimentos&nbsp;<\/p>\n\n\n\n<p>De autoria da vereadora S\u00f4nia Meire, o Requerimento n\u00ba 200\/2025 solicita \u00e0 prefeita de Aracaju, Em\u00edlia Corr\u00eaa, que disponibilize informa\u00e7\u00f5es sobre a aplica\u00e7\u00e3o, nos anos de 2024 e 2025, dos recursos oriundos da concess\u00e3o da Companhia de Saneamento do Estado de Sergipe (DESO), bem como qual a proje\u00e7\u00e3o para a destina\u00e7\u00e3o do montante restante desses recursos.<\/p>\n\n\n\n<p>O Requerimento n\u00ba 203\/2025, tamb\u00e9m de autoria da vereadora, solicita ao superintendente municipal de Transportes e Tr\u00e2nsito, Nelson Felipe, que informe o quantitativo de ve\u00edculos pr\u00f3prios, alugados e cedidos por outros \u00f3rg\u00e3os para a SMTT.<\/p>\n\n\n\n<p>J\u00e1 o Requerimento n\u00ba 213\/2025, de autoria do presidente da Casa, vereador Ricardo Vasconcelos, solicita a realiza\u00e7\u00e3o de Audi\u00eancia P\u00fablica a ser realizada no dia 12 de junho de 2025, \u00e0s 15h, para debater o tema \u201cTodos juntos contra o trabalho infantil\u201d.<\/p>\n\n\n\n<p>Outros quatro requerimentos foram apreciados fora da pauta. Tr\u00eas deles foram de autoria do vereador Iran Barbosa. O Requerimento n\u00ba 216\/2025 solicitou prefer\u00eancia para discuss\u00e3o, redu\u00e7\u00e3o de interst\u00edcios regimentais e urg\u00eancia para a tramita\u00e7\u00e3o do Projeto de Decreto Legislativo n\u00ba 39\/2025, que prop\u00f5e o T\u00edtulo de Cidadania Aracajuana ao Sr. Carlos Alberto Santos. J\u00e1 o n\u00ba 217\/2025 tamb\u00e9m solicitou prefer\u00eancia para a tramita\u00e7\u00e3o do projeto que prop\u00f5e o T\u00edtulo de Cidadania Aracajuana ao Sr. Helison Santos Macedo. Por fim, o de n\u00ba 218\/2025 solicita a entrega de T\u00edtulo de Cidadania ao Sr. Gildo Alves de Oliveira.<\/p>\n\n\n\n<p>O Requerimento n\u00ba 206\/2025, de autoria do vereador L\u00facio Fl\u00e1vio, solicitou a realiza\u00e7\u00e3o de uma Sess\u00e3o Especial, no dia 16 de junho de 2025, \u00e0s 15h, em alus\u00e3o ao Dia da Pastora. A presente solicita\u00e7\u00e3o est\u00e1 em conson\u00e2ncia com a Lei Federal n\u00ba 14.970, de 13 de setembro de 2024, que institui o Dia Nacional da Pastora Evang\u00e9lica e do Pastor Evang\u00e9lico.<\/p>\n\n\n\n<p>Mo\u00e7\u00f5es&nbsp;<\/p>\n\n\n\n<p>Os vereadores apreciaram tr\u00eas mo\u00e7\u00f5es. A primeira, de autoria do vereador Anderson de Tuca (Mo\u00e7\u00e3o n\u00ba 51\/2025), solicita aplausos \u00e0 valorosa guarni\u00e7\u00e3o do Batalh\u00e3o de Pol\u00edcia de Choque da Pol\u00edcia Militar de Sergipe, pelo ato de bravura e humanidade demonstrado no salvamento de um homem em situa\u00e7\u00e3o de tentativa de suic\u00eddio. O reconhecimento ser\u00e1 destinado ao trabalho exemplar do sargento Frederico, sargento Assis, cabo Vitor e soldado Gama.<\/p>\n\n\n\n<p>De autoria do vereador Levi Oliveira, foi aprovada a Mo\u00e7\u00e3o de Aplausos n\u00ba 57\/2025 ao Grupamento T\u00e1tico A\u00e9reo (GTA) do Estado de Sergipe, em homenagem ao seu 16\u00ba anivers\u00e1rio de funda\u00e7\u00e3o, celebrado no dia 19 de maio de 2025.<\/p>\n\n\n\n<p>J\u00e1 a Mo\u00e7\u00e3o n\u00ba 58\/2025, de autoria do vereador Iran Barbosa, apela \u00e0 secret\u00e1ria da Educa\u00e7\u00e3o de Aracaju, Edna Quit\u00e9ria do Amorim Costa, para que sejam adotadas as medidas cab\u00edveis visando ao cumprimento do que determina a Lei Municipal n\u00ba 3.380\/2006, que instituiu a obrigatoriedade da inclus\u00e3o da L\u00edngua Brasileira de Sinais no curr\u00edculo escolar em Aracaju.<\/p>\n\n\n\n<p>Por &nbsp;Camila Farias &#8211; Foto: Luanna Pinheiro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira (11\/06), por meio da 45\u00aa Sess\u00e3o Ordin\u00e1ria, a C\u00e2mara de Vereadores de Aracaju apreciou 13 proposituras. Confira o que foi aprovado na Casa do Povo.&nbsp; Projeto de resolu\u00e7\u00e3o De autoria do vereador Elber Batalha, o Projeto de Resolu\u00e7\u00e3o n\u00ba 8\/2024 foi aprovado em reda\u00e7\u00e3o final. Ele cria, na C\u00e2mara Municipal de Aracaju, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,7],"tags":[],"class_list":["post-10696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10696"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10696\/revisions"}],"predecessor-version":[{"id":10698,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10696\/revisions\/10698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10697"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}