{"id":10702,"date":"2025-06-11T15:05:43","date_gmt":"2025-06-11T18:05:43","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10702"},"modified":"2025-06-11T15:05:44","modified_gmt":"2025-06-11T18:05:44","slug":"operacao-simulatio-cumpre-mandados-de-busca-e-apreensao-contra-empresa-por-fraudes-em-financiamentos-na-capital","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/11\/operacao-simulatio-cumpre-mandados-de-busca-e-apreensao-contra-empresa-por-fraudes-em-financiamentos-na-capital\/","title":{"rendered":"\u201cOpera\u00e7\u00e3o Simulatio\u201d cumpre mandados de busca e apreens\u00e3o contra empresa por fraudes em financiamentos na capital"},"content":{"rendered":"\n<p>A Delegacia Especializada de Defesa do Consumidor e da Ordem Econ\u00f4mica (Decon), em parceria com a 2\u00aa Delegacia Metropolitana, Departamento de Crimes contra o Patrim\u00f4nio (Depatri) e Instituto de Criminal\u00edstica, desencadeou a \u2018Opera\u00e7\u00e3o Simulatio\u2019 na manh\u00e3 desta quarta-feira (11), na capital.<\/p>\n\n\n\n<p>A iniciativa busca cumprir mandados de busca e apreens\u00e3o em dois endere\u00e7os de uma empresa investigada por diversos golpes.<\/p>\n\n\n\n<p>A partir do registro de diversos Boletins de Ocorr\u00eancia pelos clientes lesados por uma empresa do ramo de financiamento, a Decon iniciou investiga\u00e7\u00e3o, em parceria com outras unidades da Pol\u00edcia Civil, constatando que as v\u00edtimas procuraram a institui\u00e7\u00e3o alvo da opera\u00e7\u00e3o para obter um financiamento, mas, de modo enganoso, acabaram aderindo a cons\u00f3rcios. Os levantamentos policiais mostram que existem v\u00edtimas em v\u00e1rias cidades do estado.<\/p>\n\n\n\n<p>&nbsp;\u201cA Opera\u00e7\u00e3o teve in\u00edcio quando uma v\u00edtima que procura a Delegacia do Consumidor, noticiando que foi a uma empresa, com a finabilidade de adquirir um financiamento, porque desejava ter uma motocicleta, uma vez que ela fazia \u2018motor Uber\u2019. E, ao fazer o contrato, certa de que receberia o bem m\u00f3vel em dois dias, passado algum tempo, esse bem n\u00e3o chegou. Outras v\u00edtimas come\u00e7aram a surgir e, a partir de uma busca nos bancos de dados oficiais, percebemos que mais de uma centena de v\u00edtimas havia ca\u00eddo nesse golpe\u201d, citou a delegada Georlize Teles, que est\u00e1 \u00e0 frente da Decon.<\/p>\n\n\n\n<p>Segundo o que foi apurado pela Pol\u00edcia Civil, durante os tr\u00e2mites junto \u00e0 empresa suspeita da fraude, as pessoas eram informadas de que estavam obtendo um financiamento e, diante disso, levadas a acreditar que, em dois dias, teriam acesso ao bem. Ap\u00f3s o prazo, as v\u00edtimas descobriram que, na verdade, tinham adquirido um cons\u00f3rcio, incorrendo assim em preju\u00edzos financeiros e na impossibilidade de precisar quando o objeto pretendido seria recebido.<\/p>\n\n\n\n<p>&nbsp;\u201cDiante desse fato, foi instaurado o procedimento policial e, ap\u00f3s v\u00e1rias dilig\u00eancias, decidimos por representar uma busca e apreens\u00e3o, que foi concedida e, no dia de hoje, devidamente cumprida\u201d, completou a delegada Georlize Teles, em meio ao cumprimento dos mandados em dois endere\u00e7os da empresa investigada, situados na capital sergipana.<\/p>\n\n\n\n<p>Com a execu\u00e7\u00e3o das determina\u00e7\u00f5es judiciais, a Pol\u00edcia Civil apreendeu documentos, celulares, computadores, entre outras provas para robustecer as investiga\u00e7\u00f5es. A Decon orienta que, caso existam outras v\u00edtimas, elas podem comparecer em qualquer unidade da Pol\u00edcia Civil no estado. O Disque-Den\u00fancia, via telefone 181, tamb\u00e9m \u00e9 um canal para envio de informa\u00e7\u00f5es sobre a apura\u00e7\u00e3o.<\/p>\n\n\n\n<p>Durante o cumprimento dos mandados, um casal de clientes, al\u00e9m de um candidato a emprego, chegaram \u00e0 empresa, sendo surpreendidos pela not\u00edcia da fraude. \u201cA gente ia dar uma entrada, um valor de R$ 3 mil, em parcelas de R$ 200. Ele pediu em dinheiro. Na mensagem, ele diz, trazer os documentos e o dinheiro. \u00c9 uma conversa muito bonita, qualquer um cai\u201d, falou casal de clientes que esteve no escrit\u00f3rio em meio \u00e0 a\u00e7\u00e3o policial.<\/p>\n\n\n\n<p>Com informa\u00e7\u00f5es e foto da SSP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia Especializada de Defesa do Consumidor e da Ordem Econ\u00f4mica (Decon), em parceria com a 2\u00aa Delegacia Metropolitana, Departamento de Crimes contra o Patrim\u00f4nio (Depatri) e Instituto de Criminal\u00edstica, desencadeou a \u2018Opera\u00e7\u00e3o Simulatio\u2019 na manh\u00e3 desta quarta-feira (11), na capital. A iniciativa busca cumprir mandados de busca e apreens\u00e3o em dois endere\u00e7os de uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,3],"tags":[],"class_list":["post-10702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-letreiro","category-policia"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10702"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10702\/revisions"}],"predecessor-version":[{"id":10704,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10702\/revisions\/10704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10703"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}