{"id":10746,"date":"2025-06-12T06:14:49","date_gmt":"2025-06-12T09:14:49","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=10746"},"modified":"2025-06-12T06:14:50","modified_gmt":"2025-06-12T09:14:50","slug":"equipe-do-nucleo-psicossocial-do-ajuprev-apresenta-acoes-a-coordenadoria-permanente-de-autocomposicao","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/12\/equipe-do-nucleo-psicossocial-do-ajuprev-apresenta-acoes-a-coordenadoria-permanente-de-autocomposicao\/","title":{"rendered":"Equipe do N\u00facleo Psicossocial do AjuPrev apresenta a\u00e7\u00f5es \u00e0 Coordenadoria Permanente de Autocomposi\u00e7\u00e3o"},"content":{"rendered":"\n<p>A equipe do N\u00facleo Psicossocial do Instituto de Previd\u00eancia do Munic\u00edpio de Aracaju (AjuPrev) esteve reunida na manh\u00e3 de quarta-feira (11), com a procuradora de Justi\u00e7a, Concei\u00e7\u00e3o Figueiredo, respons\u00e1vel pela Coordenadoria Permanente de Autocomposi\u00e7\u00e3o e Paz (Coapaz), do Minist\u00e9rio P\u00fablico de Sergipe (MPSE). A proposta do encontro foi estreitar a rela\u00e7\u00e3o entre os dois \u00f3rg\u00e3os e apresentar o rec\u00e9m-criado n\u00facleo do instituto e o trabalho que o setor est\u00e1 come\u00e7ando a desenvolver.<\/p>\n\n\n\n<p>O coordenador do n\u00facleo, Wagner Mendon\u00e7a, fez a apresenta\u00e7\u00e3o das integrantes da equipe e explicou como est\u00e1 sendo formatado o trabalho. &#8220;Temos a psic\u00f3loga Simone Barbosa, a assistente social Ana Caroline Trindade e a especialista em legisla\u00e7\u00e3o previdenci\u00e1ria, Helena Nascimento. Estamos conhecendo um pouco a realidade dos benefici\u00e1rios do instituto para tra\u00e7ar a\u00e7\u00f5es efetivas que possam auxili\u00e1-los a ter uma vida melhor, seja vendo necessidades de sa\u00fade ou de assist\u00eancia, para que possamos encaminhar para os \u00f3rg\u00e3os de cada setor&#8221;.<\/p>\n\n\n\n<p>Algumas situa\u00e7\u00f5es j\u00e1 vivenciadas dentro no instituto e em visitas a aposentados para fazer a Prova de Vida foram descritas por Wagner Mendon\u00e7a. &#8220;Temos situa\u00e7\u00f5es extremas, como uma servidora que se aposentou recentemente porque o filho sofreu um atentado, ficou acamado e ela \u00e9 quem cuida. Ela tem medo de sair de casa, abrir as janelas e teve sucessivos afastamentos do trabalho, por problemas depressivos. Esse \u00e9 um dos muitos casos que nos deparamos no dia a dia. Temos aposentado em situa\u00e7\u00e3o de rua e um acamado, a esposa tem alzheimer e a filha que cuida dos dois apresenta um quadro de depress\u00e3o&#8221;.<\/p>\n\n\n\n<p>O trabalho do N\u00facleo Psicossocial n\u00e3o se restringe somente a quem \u00e9 aposentado ou pensionista, mas ser\u00e3o desenvolvidas a\u00e7\u00f5es para os servidores que est\u00e3o pr\u00f3ximos \u00e0 aposentadoria. &#8220;Queremos atuar para que eles se aposentem com tranquilidade, com sa\u00fade mental e tamb\u00e9m financeira. Para isso, vamos realizar palestras sobre legisla\u00e7\u00e3o previdenci\u00e1ria e mostrar atividades que podem desenvolver ap\u00f3s se aposentarem, dentre outras a\u00e7\u00f5es&#8221;, relatou Wagner Mendon\u00e7a.<\/p>\n\n\n\n<p>Os t\u00e9cnicos do AjuPrev foram recebidos pelo chefe da Central de Media\u00e7\u00e3o da Coapaz, Caio Rubens Castiliano Santos, que participou da reuni\u00e3o. &#8220;O encontro foi produtivo, pela iniciativa que o AjuPrev traz, com esse trabalho inovador e que agrega valor para seus benefici\u00e1rios. Tenho certeza que vai contribuir muito para a melhoria da qualidade de vida dessas pessoas. E abriu-se essa possibilidade de parceria conosco, para a forma\u00e7\u00e3o de membros do n\u00facleo em facilitadores de c\u00edrculos de constru\u00e7\u00e3o de paz, o que certamente vai auxiliar a equipe no acolhimento dos casos que chegam ao instituto&#8221;.<\/p>\n\n\n\n<p>A coordenadora da Coapaz, a procuradora Concei\u00e7\u00e3o Figueiredo, se colocou \u00e0 inteira disposi\u00e7\u00e3o para firmar parceria com o AjuPrev. &#8220;Temos boas perspectivas, porque pelo desenho que foi falado aqui, dessa forma\u00e7\u00e3o bem estruturada, pronta para deflagrar a\u00e7\u00f5es que v\u00e3o auxiliar na melhoria da vida dos aposentados e pensionistas e dos que est\u00e3o para se aposentar, nos mostra que o AjuPrev quer humanizar esse atendimento ao seu p\u00fablico. E o Minist\u00e9rio P\u00fablico, atrav\u00e9s da Coapaz, est\u00e1 aqui de bra\u00e7os abertos, para dar uma forma\u00e7\u00e3o mais ampliada de cuidado desses v\u00ednculos, de restaura\u00e7\u00e3o de relacionamentos, de conviv\u00eancia humanizada que todos n\u00f3s precisamos ter&#8221;.<\/p>\n\n\n\n<p>Texto e foto: Ascom\/AjuPrev<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe do N\u00facleo Psicossocial do Instituto de Previd\u00eancia do Munic\u00edpio de Aracaju (AjuPrev) esteve reunida na manh\u00e3 de quarta-feira (11), com a procuradora de Justi\u00e7a, Concei\u00e7\u00e3o Figueiredo, respons\u00e1vel pela Coordenadoria Permanente de Autocomposi\u00e7\u00e3o e Paz (Coapaz), do Minist\u00e9rio P\u00fablico de Sergipe (MPSE). A proposta do encontro foi estreitar a rela\u00e7\u00e3o entre os dois \u00f3rg\u00e3os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-10746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10746"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10746\/revisions"}],"predecessor-version":[{"id":10748,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10746\/revisions\/10748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/10747"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}