{"id":11357,"date":"2025-06-17T17:01:44","date_gmt":"2025-06-17T20:01:44","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=11357"},"modified":"2025-06-17T17:01:45","modified_gmt":"2025-06-17T20:01:45","slug":"prefeita-emilia-correa-estende-prazo-para-regularizacao-de-alvaras","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/17\/prefeita-emilia-correa-estende-prazo-para-regularizacao-de-alvaras\/","title":{"rendered":"Prefeita Em\u00edlia Corr\u00eaa \u00a0estende prazo para regulariza\u00e7\u00e3o de alvar\u00e1s"},"content":{"rendered":"\n<p>A prefeita Em\u00edlia Corr\u00eaa recebeu, nesta ter\u00e7a-feira, 17, membros do Sindicato dos Taxistas de Aracaju em seu gabinete. O encontro teve como pauta principal o pedido da categoria para a extens\u00e3o do prazo de regulariza\u00e7\u00e3o dos alvar\u00e1s de t\u00e1xis.<\/p>\n\n\n\n<p>Demonstrando aten\u00e7\u00e3o \u00e0s demandas dos trabalhadores e compromisso com a categoria, a gestora municipal decidiu prorrogar o prazo em mais 15 dias, a contar a partir desta quarta-feira, 18.<\/p>\n\n\n\n<p>A prefeita destacou que a decis\u00e3o foi baseada nas dificuldades relatadas pelos representantes dos taxistas, que informaram que 183 permission\u00e1rios n\u00e3o conseguiram cumprir o prazo anterior.<\/p>\n\n\n\n<p>\u201cEntendi o problema de cada taxista, pois cada um tem uma realidade diferente e dif\u00edcil, e estendemos um pouco mais o prazo, por mais 15 dias, contados a partir de amanh\u00e3, que j\u00e1 tinha sido estendido recentemente. Acredito que isso vem beneficiar e n\u00e3o prejudica a administra\u00e7\u00e3o, porque \u00e9 um prazo relativamente curto\u201d, explicou.<\/p>\n\n\n\n<p>O presidente do Sindicato dos Taxistas, Jo\u00e3o Batista da Silva, avaliou positivamente a medida, ressaltando o impacto da prorroga\u00e7\u00e3o na tranquilidade dos profissionais que enfrentavam a possibilidade de perder suas permiss\u00f5es.<\/p>\n\n\n\n<p>\u201cEu acredito que muita gente agora j\u00e1 resolve a situa\u00e7\u00e3o. Ficamos at\u00e9 agradecidos pela recep\u00e7\u00e3o. D\u00e1 uma tranquilidade para aqueles que estavam perdendo a sua permiss\u00e3o. Ent\u00e3o, essas pessoas v\u00e3o ter condi\u00e7\u00f5es de resolver o problema e trabalhar mais sossegados\u201d, destacou.<\/p>\n\n\n\n<p>No in\u00edcio do ano, a Superintend\u00eancia Municipal de Transportes e Tr\u00e2nsito de Aracaju (SMTT) j\u00e1 havia concedido um prazo de 30 dias \u00fateis para que os permission\u00e1rios de t\u00e1xis com alvar\u00e1s vencidos regularizassem sua situa\u00e7\u00e3o. A medida, adotada em fevereiro, visava garantir a transpar\u00eancia e a qualidade dos servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o aracajuana.<\/p>\n\n\n\n<p>Segundo o superintendente da SMTT, Nelson Felipe, a nova prorroga\u00e7\u00e3o representa uma oportunidade significativa para a categoria. \u201cA gente espera que a categoria, ap\u00f3s toda essa luta, essa necessidade que eles visualizaram de vir pedir \u00e0 prefeita essa dila\u00e7\u00e3o de prazo, que aproveite para regularizar as pend\u00eancias. \u00c9 esse o intuito da prefeita em beneficiar a classe dos taxistas e fazer com que eles realmente possam exercer o direito da permiss\u00e3o do t\u00e1xi\u201d, afirmou.<\/p>\n\n\n\n<p>Os taxistas em situa\u00e7\u00e3o irregular n\u00e3o haviam solicitado a renova\u00e7\u00e3o do alvar\u00e1 dentro do prazo legal de 90 dias ap\u00f3s o vencimento, conforme determina o Regulamento dos T\u00e1xis do Munic\u00edpio de Aracaju (artigo 7\u00ba; inciso II do Decreto 61, de 13 de mar\u00e7o de 2022).<\/p>\n\n\n\n<p>A lista dos profissionais convocados para a regulariza\u00e7\u00e3o foi divulgada por meio da Portaria n\u00ba 95\/2025, publicada em 29 de janeiro no Di\u00e1rio Oficial do Munic\u00edpio.<\/p>\n\n\n\n<p>Foto: Felipe Bass<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A prefeita Em\u00edlia Corr\u00eaa recebeu, nesta ter\u00e7a-feira, 17, membros do Sindicato dos Taxistas de Aracaju em seu gabinete. O encontro teve como pauta principal o pedido da categoria para a extens\u00e3o do prazo de regulariza\u00e7\u00e3o dos alvar\u00e1s de t\u00e1xis. Demonstrando aten\u00e7\u00e3o \u00e0s demandas dos trabalhadores e compromisso com a categoria, a gestora municipal decidiu prorrogar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11358,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,2],"tags":[],"class_list":["post-11357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11357"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11357\/revisions"}],"predecessor-version":[{"id":11359,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11357\/revisions\/11359"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/11358"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}