{"id":11721,"date":"2025-06-21T08:20:36","date_gmt":"2025-06-21T11:20:36","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=11721"},"modified":"2025-06-21T08:20:37","modified_gmt":"2025-06-21T11:20:37","slug":"concurso-ruas-decoradas-segue-com-votacao-aberta-ate-o-dia-23","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/21\/concurso-ruas-decoradas-segue-com-votacao-aberta-ate-o-dia-23\/","title":{"rendered":"Concurso \u2018Ruas Decoradas\u2019 segue com vota\u00e7\u00e3o aberta at\u00e9 o dia 23"},"content":{"rendered":"\n<p>As tr\u00eas finalistas do concurso \u2018Ruas Decoradas\u2019 j\u00e1 foram escolhidas e, agora, \u00e9 hora do p\u00fablico escolher sua favorita. A competi\u00e7\u00e3o, promovida pela TV Sergipe, foi iniciada no \u00faltimo dia 27 com o apoio cultural do Governo do Estado, e segue com a vota\u00e7\u00e3o aberta at\u00e9 as 11h da segunda-feira, 23, por meio do site&nbsp;<a href=\"https:\/\/g1.globo.com\/se\/sergipe\/votacao\/concurso-ruas-decoradas-vote-na-rua-mais-bonita-de-sergipe-sZrRfyVdNV.ghtml\">G1 Sergipe<\/a>. A iniciativa refor\u00e7a as tradi\u00e7\u00f5es juninas e as manifesta\u00e7\u00f5es da cultura popular do estado e vai premiar a rua mais bonita do S\u00e3o Jo\u00e3o de Sergipe.<\/p>\n\n\n\n<p>Para o secret\u00e1rio de Estado da Comunica\u00e7\u00e3o, Cleon Nascimento, o apoio dado pelo Governo de Sergipe \u00e9 mais uma a\u00e7\u00e3o de fomento \u00e0s tradi\u00e7\u00f5es. \u201cAl\u00e9m da realiza\u00e7\u00e3o de grandes eventos para atrair o p\u00fablico para as nossas manifesta\u00e7\u00f5es culturais, \u00e9 extremamente importante envolver a popula\u00e7\u00e3o diretamente na execu\u00e7\u00e3o de projetos que fortale\u00e7am as nossas ra\u00edzes, e \u00e9 tamb\u00e9m por isso que o Governo presta esse apoio ao concurso que, de fato, incentiva as pessoas a participarem ainda mais das nossas tradi\u00e7\u00f5es e festejos\u201d, ressalta.<\/p>\n\n\n\n<p>Ap\u00f3s o per\u00edodo de inscri\u00e7\u00e3o, as escolhidas para concorrer ao pr\u00eamio foram: Rua Ruth Santos (antiga avenida S\u00e3o Carlos), no Bairro Industrial, em Aracaju; Rua Ant\u00f4nio Marques, no povoado Tanque Novo, em Riach\u00e3o do Dantas; e Rua 18, no bairro Fernando Collor, em Nossa Senhora do Socorro. O resultado final ser\u00e1 divulgado no dia 23, por meio da programa\u00e7\u00e3o da TV Sergipe e dos canais oficiais do Governo do Estado.<\/p>\n\n\n\n<p>O concurso vai premiar a rua vitoriosa com certificado, trof\u00e9u, placa decorativa e uma comemora\u00e7\u00e3o junina em celebra\u00e7\u00e3o ao t\u00edtulo de vencedora do \u2018Concurso Ruas Decoradas\u2019. A premia\u00e7\u00e3o ser\u00e1 entregue no dia 26 de junho, e vai ser acompanhada de uma apresenta\u00e7\u00e3o de trio p\u00e9 de serra, quadrilha junina e buf\u00ea junino para 200 pessoas. As apresenta\u00e7\u00f5es art\u00edsticas decorrentes da premia\u00e7\u00e3o ser\u00e3o gratuitas e abertas ao p\u00fablico geral.<\/p>\n\n\n\n<p>Foto: Igor Matias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As tr\u00eas finalistas do concurso \u2018Ruas Decoradas\u2019 j\u00e1 foram escolhidas e, agora, \u00e9 hora do p\u00fablico escolher sua favorita. A competi\u00e7\u00e3o, promovida pela TV Sergipe, foi iniciada no \u00faltimo dia 27 com o apoio cultural do Governo do Estado, e segue com a vota\u00e7\u00e3o aberta at\u00e9 as 11h da segunda-feira, 23, por meio do site&nbsp;G1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[],"class_list":["post-11721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11721"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11721\/revisions"}],"predecessor-version":[{"id":11723,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11721\/revisions\/11723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/11722"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}