{"id":11936,"date":"2025-09-10T13:00:39","date_gmt":"2025-09-10T16:00:39","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=11936"},"modified":"2025-09-10T13:00:39","modified_gmt":"2025-09-10T16:00:39","slug":"mpse-expede-recomendacao-para-que-o-municipio-de-aracaju-coiba-ocupacao-irregular-de-espacos-publicos-para-garantir-mobilidade-urbana","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/09\/10\/mpse-expede-recomendacao-para-que-o-municipio-de-aracaju-coiba-ocupacao-irregular-de-espacos-publicos-para-garantir-mobilidade-urbana\/","title":{"rendered":"MPSE expede Recomenda\u00e7\u00e3o para que o Munic\u00edpio de Aracaju co\u00edba ocupa\u00e7\u00e3o irregular de espa\u00e7os p\u00fablicos para garantir mobilidade urbana"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico de Sergipe (MPSE), por meio da 5\u00aa Promotoria de Justi\u00e7a dos Direitos do Cidad\u00e3o,&nbsp;com atua\u00e7\u00e3o nas \u00e1reas&nbsp;do Meio Ambiente&nbsp;e&nbsp;Urbanismo, expediu a&nbsp;Recomenda\u00e7\u00e3o n\u00ba 01\/2025, orientando o Munic\u00edpio de Aracaju, a&nbsp;Empresa Municipal de Servi\u00e7os Urbanos (Emsurb)&nbsp;e a Superintend\u00eancia&nbsp;Municipal de Transporte e Tr\u00e2nsito (SMTT)&nbsp;a adotarem medidas para coibir a&nbsp;ocupa\u00e7\u00e3o irregular de espa\u00e7os p\u00fablicos&nbsp;por estabelecimentos comerciais.<\/p>\n\n\n\n<p>A iniciativa tem como objetivo garantir&nbsp;o direito \u00e0 mobilidade urbana, \u00e0 acessibilidade e \u00e0 seguran\u00e7a dos pedestres, assegurando que cal\u00e7adas, passeios e vias p\u00fablicas sejam utilizados de forma adequada e segura. Entre as a\u00e7\u00f5es recomendadas est\u00e3o: a fiscaliza\u00e7\u00e3o direta dos estabelecimentos, a aplica\u00e7\u00e3o de san\u00e7\u00f5es administrativas quando necess\u00e1rio, e campanhas de conscientiza\u00e7\u00e3o sobre o uso correto do espa\u00e7o p\u00fablico.<\/p>\n\n\n\n<p>A recomenda\u00e7\u00e3o cita especificamente casos de ocupa\u00e7\u00e3o irregular em estabelecimentos&nbsp;localizados em Aracaju, que t\u00eam comprometido a circula\u00e7\u00e3o de pedestres e ve\u00edculos, bem como a seguran\u00e7a e a acessibilidade urbana.<\/p>\n\n\n\n<p>No documento expedido pela Promotora de Justi\u00e7a Ana Paula Machado Costa Meneses, titular da 5\u00aa Promotoria de Justi\u00e7a, o&nbsp;MP&nbsp;sergipano&nbsp;estabelece prazo de&nbsp;60 dias&nbsp;para que as autoridades municipais adotem as medidas indicadas e prestem informa\u00e7\u00f5es sobre o cumprimento da recomenda\u00e7\u00e3o. O descumprimento poder\u00e1 resultar na&nbsp;ado\u00e7\u00e3o de medidas judiciais cab\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico de Sergipe (MPSE), por meio da 5\u00aa Promotoria de Justi\u00e7a dos Direitos do Cidad\u00e3o,&nbsp;com atua\u00e7\u00e3o nas \u00e1reas&nbsp;do Meio Ambiente&nbsp;e&nbsp;Urbanismo, expediu a&nbsp;Recomenda\u00e7\u00e3o n\u00ba 01\/2025, orientando o Munic\u00edpio de Aracaju, a&nbsp;Empresa Municipal de Servi\u00e7os Urbanos (Emsurb)&nbsp;e a Superintend\u00eancia&nbsp;Municipal de Transporte e Tr\u00e2nsito (SMTT)&nbsp;a adotarem medidas para coibir a&nbsp;ocupa\u00e7\u00e3o irregular de espa\u00e7os p\u00fablicos&nbsp;por estabelecimentos comerciais. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6],"tags":[],"class_list":["post-11936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letreiro"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11936"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11936\/revisions"}],"predecessor-version":[{"id":11938,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11936\/revisions\/11938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/11937"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}