{"id":2476,"date":"2025-04-02T04:33:33","date_gmt":"2025-04-02T07:33:33","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=2476"},"modified":"2025-04-02T04:33:34","modified_gmt":"2025-04-02T07:33:34","slug":"valmir-de-francisquinho-comeca-a-construir-uma-alternativa-para-a-oposicao","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/02\/valmir-de-francisquinho-comeca-a-construir-uma-alternativa-para-a-oposicao\/","title":{"rendered":"Valmir de Francisquinho come\u00e7a a construir uma alternativa para a oposi\u00e7\u00e3o"},"content":{"rendered":"\n<p>Atacado por diversos setores da imprensa sergipana, o prefeito de Itabaiana, Valmir de Francisquinho (PL), mesmo ineleg\u00edvel, momentaneamente, continua sendo protagonista da cena pol\u00edtica do nosso Estado. Os ataques ao &#8220;Pato&#8221; s\u00e3o continuados, simult\u00e2neos e, muitas vezes, &#8220;orquestrados&#8221;! Mas ele segue resistindo, consolidando sua lideran\u00e7a na regi\u00e3o Agreste. A viagem para Bras\u00edlia (DF) e as visitas institucionais que vem fazendo no Congresso Nacional demonstram que ele segue &#8220;vivo&#8221;, politicamente falando.<\/p>\n\n\n\n<p>Olhando para o futuro de Itabaiana, o prefeito foi recebido pelos senadores La\u00e9rcio Oliveira (PP) e Rog\u00e9rio Carvalho (PT), quando possivelmente trataram da libera\u00e7\u00e3o de recursos no Or\u00e7amento da Uni\u00e3o para serem investidos no munic\u00edpio serrano. S\u00f3 estes dois encontros, nessa ter\u00e7a-feira (1\u00ba), para quem conhece os bastidores da pol\u00edtica de Sergipe, n\u00e3o seria exagero dizer que o prefeito serrano vai continuar incomodando muita gente.<\/p>\n\n\n\n<p>Mas Valmir de Francisquinho, acompanhado de seus filhos, o deputado federal \u00cdcaro (PL), e o prefeito de Areia Branca, Talysson (PP) \u2013 que tamb\u00e9m viajou em busca de recursos e parcerias \u2013 se consolida enquanto lideran\u00e7a pol\u00edtica ao ser recebido pelo presidente da C\u00e2mara dos Deputados, Hugo Motta (Republicanos). O encontro gerou muita repercuss\u00e3o e muitas especula\u00e7\u00f5es nos bastidores da pol\u00edtica sergipana, em especial sobre uma poss\u00edvel mudan\u00e7a de partido em breve.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 segredo para ningu\u00e9m que Valmir de Francisquinho e o agrupamento que ele lidera n\u00e3o est\u00e3o vivendo em &#8220;festa&#8221; dentro do PL sergipano e para muitos seria essencial que o prefeito de Itabaiana buscasse outra legenda, mesmo mantendo sua linha pol\u00edtica e algumas de suas concep\u00e7\u00f5es. E os bastidores de sua viagem para BSB comprovam que n\u00e3o lhes faltam convites para novas filia\u00e7\u00f5es. Partidos que, inclusive, em Sergipe apoiam a reelei\u00e7\u00e3o do atual governador.<\/p>\n\n\n\n<p>Quando abre o di\u00e1logo com senadores e deputados federais, Valmir de Francisquinho amplia suas articula\u00e7\u00f5es pensando no desenvolvimento de Itabaiana e se mant\u00e9m vivo politicamente para 2026. At\u00e9 l\u00e1 ningu\u00e9m sabe se ele ficar\u00e1 no PL ou migra para uma nova legenda. Sobre a inexigibilidade, h\u00e1 quem entenda que \u00e9 algo irrevers\u00edvel at\u00e9 o pr\u00f3ximo ano; mas j\u00e1 h\u00e1 quem aposte todas as fichas em uma mudan\u00e7a no cen\u00e1rio pol\u00edtico de Sergipe.<\/p>\n\n\n\n<p>Em s\u00edntese, Valmir se mant\u00e9m como uma grande esperan\u00e7a para quem est\u00e1 posicionado contra o governo de F\u00e1bio Mitidieri. A oposi\u00e7\u00e3o ainda n\u00e3o abriu o di\u00e1logo para discutir o cen\u00e1rio para 2026, e isso passa a impress\u00e3o de que o governo n\u00e3o tem advers\u00e1rio. Mas tem sim, ao ponto de ele ficar preocupado com o risco de seus advers\u00e1rios crescerem politicamente at\u00e9 o pr\u00f3ximo ano. Valmir tem dimens\u00e3o sobre o seu &#8220;tamanho&#8221; e acerta quando se coloca \u00e0 disposi\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Veja essa!<\/strong><\/p>\n\n\n\n<p>&nbsp;Ap\u00f3s o encontro com o deputado e presidente da C\u00e2mara, Hugo Motta, Valmir de Francisquinho conversou por telefone direto de BSB e disse a este colunista que seu foco no momento \u00e9 seguir administrando Itabaiana e continuar dialogando em busca de recursos para o seu munic\u00edpio.<\/p>\n\n\n\n<p><strong>E essa!<\/strong><\/p>\n\n\n\n<p>&#8220;Gra\u00e7as ao comportamento do deputado federal \u00cdcaro de Valmir, estamos sendo muito bem tratados em BSB. Isso tem acontecido com o ex-prefeito Ada\u00edlton, com o deputado Marcos Oliveira, o prefeito Talysson e o deputado federal \u00cdcaro. Quem n\u00e3o gostaria de ter esse agrupamento consolidado em sua legenda?&#8221;, questiona.<\/p>\n\n\n\n<p><strong>Exclusiva!<\/strong><\/p>\n\n\n\n<p>Direto de BSB, Valmir externou suas preocupa\u00e7\u00f5es e demonstrou muita confian\u00e7a em sua capacidade de liderar o processo eleitoral em Sergipe, seja como protagonista, seja atuando nos bastidores. &#8220;Nosso agrupamento est\u00e1 sendo cortejado por diversos partidos aqui em BSB. Muita gente est\u00e1 consciente do que vem acontecendo em Sergipe&#8221;.<\/p>\n\n\n\n<p><strong>Republicanos!<\/strong><\/p>\n\n\n\n<p>O encontro com Hugo Motta aumentou os rumores sobre uma poss\u00edvel sa\u00edda de Valmir e do seu agrupamento do PL para se filiarem no Republicanos, partido que est\u00e1 em processo de fus\u00e3o com o PSDB, no cen\u00e1rio nacional. Valmir n\u00e3o confirmou a mudan\u00e7a, mas pontuou que os convites representam o reconhecimento do perfil adotado por \u00cdcaro dentro do Congresso Nacional.<\/p>\n\n\n\n<p><strong>Al\u00f4 Itabaiana!<\/strong><\/p>\n\n\n\n<p>Nas reuni\u00f5es com os senadores La\u00e9rcio Oliveira (PP) e Rog\u00e9rio Carvalho (PT), Valmir apresentou demandas voltadas para a constru\u00e7\u00e3o de novas avenidas perimetrais, amplia\u00e7\u00e3o da rede de creches em bairros de Itabaiana e investimentos no setor da sa\u00fade. O gestor destacou a import\u00e2ncia da parceria com os parlamentares para garantir melhorias \u00e0 cidade. &#8220;Eu espero que todos os parlamentares possam ajudar. Fa\u00e7o quest\u00e3o de divulgar o nome dos 11 representantes de Sergipe e visitarei a todos, sem distin\u00e7\u00e3o partid\u00e1ria. A bandeira maior \u00e9 a do povo de Itabaiana&#8221;, afirmou Valmir.<\/p>\n\n\n\n<p><strong>Al\u00f4 Areia Branca!<\/strong><\/p>\n\n\n\n<p>J\u00e1 o prefeito de Areia Branca, Talysson de Valmir, solicitou recursos para pavimenta\u00e7\u00e3o asf\u00e1ltica nos povoados, amplia\u00e7\u00e3o dos servi\u00e7os de sa\u00fade com a constru\u00e7\u00e3o de novas unidades b\u00e1sicas de sa\u00fade e constru\u00e7\u00e3o de casas populares para reduzir o d\u00e9ficit habitacional do munic\u00edpio. &#8220;Ao lado do meu pai e do meu irm\u00e3o, pretendemos percorrer diversos gabinetes para conseguirmos os recursos necess\u00e1rios para fazermos uma boa administra\u00e7\u00e3o em Areia Branca. O povo que nos confiou o mandato vai ter o seu voto honrado e respeitado&#8221;, declarou Talysson.<\/p>\n\n\n\n<p><strong>Bomba!<\/strong><\/p>\n\n\n\n<p>O juiz eleitoral Lu\u00eds Gustavo Almeida, da 28\u00aa Zona Eleitoral de Canind\u00e9 do S\u00e3o Francisco, julgou improcedente a representa\u00e7\u00e3o eleitoral movida pelo candidato a prefeito de Canind\u00e9, Kak\u00e1 Andrade (PSD) contra a coliga\u00e7\u00e3o do prefeito eleito Machadinho (Uni\u00e3o) e a R\u00e1dio Xing\u00f3 FM, por suposto abuso do Poder de Comunica\u00e7\u00e3o. O magistrado julgou improcedente o pedido, reconhecendo o resultados das urnas em 2024.<\/p>\n\n\n\n<p><strong>Olha a PMA!<\/strong><\/p>\n\n\n\n<p>A prefeita de Aracaju, Em\u00edlia Corr\u00eaa, sancionou a Lei n\u00ba 6.146\/2025, que autoriza a contrata\u00e7\u00e3o de um cr\u00e9dito de at\u00e9 R$ 161 milh\u00f5es para a aquisi\u00e7\u00e3o de 30 \u00f4nibus el\u00e9tricos e a implanta\u00e7\u00e3o da infraestrutura necess\u00e1ria, incluindo carregadores, uma usina de energia solar, terminal el\u00e9trico exclusivo e melhorias na rede el\u00e9trica da cidade. O financiamento foi aprovado pela C\u00e2mara Municipal de Aracaju em 25 de mar\u00e7o, por maioria.<\/p>\n\n\n\n<p><strong>Em\u00edlia Corr\u00eaa I<\/strong><\/p>\n\n\n\n<p>&#8220;Esta gest\u00e3o tem um compromisso forte de levar adiante tudo o que for bom para o povo. Agrade\u00e7o \u00e0 C\u00e2mara Municipal e aos vereadores pelo apoio, uma Casa que votou a favor do povo&#8221;, destacou a prefeita Em\u00edlia Corr\u00eaa durante a san\u00e7\u00e3o da lei. &#8220;Uma cidade moderna. \u00c9 isso que teremos para Aracaju. Uma mobilidade adequada, uma mobilidade que a popula\u00e7\u00e3o merece. N\u00e3o s\u00f3 na quest\u00e3o do modal \u00f4nibus el\u00e9trico, mas tamb\u00e9m nos patinetes, nas bicicletas el\u00e9tricas, nas ecobikes&#8221;, frisou a gestora.<\/p>\n\n\n\n<p><strong>Em\u00edlia Corr\u00eaa II<\/strong><\/p>\n\n\n\n<p>Durante a assinatura, a prefeita destacou a import\u00e2ncia de adotar alternativas para proteger o meio ambiente, come\u00e7ando pela substitui\u00e7\u00e3o dos \u00f4nibus a combust\u00e3o por el\u00e9tricos. De acordo com ela, cada ve\u00edculo el\u00e9trico equivale ao plantio de seis mil \u00e1rvores. Al\u00e9m disso, ressaltou os benef\u00edcios desse modelo, como a aus\u00eancia de ru\u00eddo.<\/p>\n\n\n\n<p><strong>Em\u00edlia Corr\u00eaa III<\/strong><\/p>\n\n\n\n<p>&#8220;O sil\u00eancio tamb\u00e9m \u00e9 bom para a nossa sa\u00fade mental. Sem falar no ar-condicionado, na seguran\u00e7a, no Wi-Fi, nas entradas USB e nas tomadas para carregar celulares, garantindo mais qualidade no transporte p\u00fablico. \u00c9 um investimento alto? Sim, mas tamb\u00e9m \u00e9 mais econ\u00f4mico. Em oito anos, a economia ser\u00e1 significativa, bem diferente dos \u00f4nibus a combust\u00e3o, que geram um custo mensal de R$ 24 mil&#8221;, complementou Em\u00edlia.<\/p>\n\n\n\n<p><strong>Terminal Pesqueiro I<\/strong><\/p>\n\n\n\n<p>Os comerciantes de pescados que atuam na regi\u00e3o do&nbsp;Terminal Pesqueiro de Aracaju agora exercer\u00e3o suas atividades em um novo espa\u00e7o estruturado pela Prefeitura de Aracaju, por meio da Empresa Municipal de Servi\u00e7os Urbanos (Emsurb). A mudan\u00e7a marca o in\u00edcio das atividades no novo local, preparado para oferecer melhores condi\u00e7\u00f5es de trabalho aos vendedores e mais conforto e higiene para os consumidores.<\/p>\n\n\n\n<p><strong>Terminal Pesqueiro II<\/strong><\/p>\n\n\n\n<p>A nova \u00e1rea, localizada no estacionamento em frente ao antigo ponto de venda, conta com uma grande estrutura que inclui: Bancas padronizadas, Cobertura com tendas, Paisagismo, Lixeiras e Banheiros. Tudo foi planejado para garantir mais organiza\u00e7\u00e3o, seguran\u00e7a e dignidade na comercializa\u00e7\u00e3o dos pescados.<\/p>\n\n\n\n<p><strong>Bertulino Menezes<\/strong><\/p>\n\n\n\n<p>Segundo o&nbsp;diretor de Espa\u00e7os P\u00fablicos e Abastecimento da Emsurb, Bertulino Menezes, a medida visa resolver de forma imediata parte dos problemas enfrentados pelos trabalhadores do setor. &#8220;Estamos entregando um espa\u00e7o mais estruturado, com divis\u00f5es adequadas, para garantir seguran\u00e7a, limpeza e dignidade tanto para os comerciantes quanto para quem compra&#8221;, destacou.<\/p>\n\n\n\n<p><strong>Al\u00f4 Propri\u00e1!<\/strong><\/p>\n\n\n\n<p>A gest\u00e3o do prefeito Luciano de Menininha segue dando exemplo de responsabilidade e compromisso com os servidores municipais e com a economia de Propri\u00e1. Pelo terceiro m\u00eas consecutivo, a Prefeitura realizou o pagamento dos sal\u00e1rios dentro do m\u00eas trabalhado, com o dep\u00f3sito efetuado j\u00e1 no dia 27 de mar\u00e7o.<\/p>\n\n\n\n<p><strong>Luciano de Menininha I<\/strong><\/p>\n\n\n\n<p>Essa medida, al\u00e9m de garantir a tranquilidade dos servidores, aquece o com\u00e9rcio e os servi\u00e7os da cidade, movimentando a economia local e beneficiando toda a popula\u00e7\u00e3o. O pagamento em dia \u00e9 um reflexo do planejamento financeiro e da seriedade da atual gest\u00e3o, que tem priorizado a valoriza\u00e7\u00e3o dos trabalhadores e a efici\u00eancia na administra\u00e7\u00e3o dos recursos p\u00fablicos.<\/p>\n\n\n\n<p><strong>Luciano de Menininha II<\/strong><\/p>\n\n\n\n<p>Luciano de Menininha refor\u00e7ou que essa \u00e9 uma diretriz central de seu governo: &#8220;Nosso compromisso \u00e9 com a responsabilidade e a transpar\u00eancia. Garantir que os servidores recebam seus sal\u00e1rios em dia \u00e9 uma forma de reconhecer o trabalho de cada um e tamb\u00e9m de fortalecer a economia de Propri\u00e1&#8221;.<\/p>\n\n\n\n<p><strong>Luciano de Menininha III<\/strong><\/p>\n\n\n\n<p>Com a\u00e7\u00f5es concretas como essa, o prefeito segue consolidando uma gest\u00e3o eficiente, equilibrada e voltada para o progresso do munic\u00edpio, demonstrando que o planejamento e o respeito com o servidor fazem toda a diferen\u00e7a na administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p><strong>Alessandro Vieira I<\/strong><\/p>\n\n\n\n<p>Os senadores da Comiss\u00e3o de Assuntos Econ\u00f4micos (CAE) v\u00e3o avaliar a concess\u00e3o de benef\u00edcios fiscais e tribut\u00e1rios a certos setores da economia (subs\u00eddios) durante o ano de 2025. Para isso, ser\u00e1 realizado um pente fino nos contratos firmados pelo governo federal, para possibilitar a revoga\u00e7\u00e3o de contratos obsoletos ou supervalorizados, que geram preju\u00edzo \u00e0 m\u00e1quina p\u00fablica. No total, segundo levantamento, esses gastos somam cerca de R$ 650 bilh\u00f5es. O senador Alessandro Vieira (MDB\/SE) ser\u00e1 o respons\u00e1vel por analisar esses gastos e apresentar um relat\u00f3rio ao final do levantamento.<\/p>\n\n\n\n<p><strong>Alessandro Vieira II<\/strong><\/p>\n\n\n\n<p>A sugest\u00e3o (REQ 13\/2025) de autoria do senador Renan Calheiros (MDB\/AL), foi aprovada na reuni\u00e3o dessa ter\u00e7a-feira (01). Segundo Renan, os subs\u00eddios favorecem inicialmente empresas que devem oferecer, como contrapartida, benef\u00edcios sociais por meio de empregos e crescimento econ\u00f4mico. O papel dos senadores ser\u00e1 de monitorar e avaliar se esse objetivo est\u00e1 sendo alcan\u00e7ado. Os subs\u00eddios n\u00e3o s\u00e3o gastos diretos, mas representam ren\u00fancia de receitas por parte da Uni\u00e3o.<\/p>\n\n\n\n<p><strong>Alessandro Vieira III<\/strong><\/p>\n\n\n\n<p>O senador Alessandro Vieira apontou que o controle dos gastos \u00e9 um meio importante para equilibrar as contas p\u00fablicas. Segundo ele, a CAE poder\u00e1 oferecer sugest\u00f5es de ajustes e economias que, ao final, &#8220;v\u00e3o propiciar investimento adequado nas pol\u00edticas de desenvolvimento do pa\u00eds&#8221;. A avalia\u00e7\u00e3o de pol\u00edticas p\u00fablicas pelas comiss\u00f5es do Senado ao longo do ano \u00e9 uma das formas pelas quais os senadores exercem a fun\u00e7\u00e3o de fiscaliza\u00e7\u00e3o das atividades do Poder Executivo, conforme previsto no Regimento Interno do Senado. Todas as comiss\u00f5es tem\u00e1ticas escolhem, a cada ano, uma pol\u00edtica p\u00fablica da sua \u00e1rea de compet\u00eancia para acompanhar.<\/p>\n\n\n\n<p><strong>&#8220;Abuelitas Songs&#8221;<\/strong><\/p>\n\n\n\n<p>No pr\u00f3ximo dia 12 de abril, no per\u00edodo de 14h \u00e0s 18h, ser\u00e1 realizada em Aracaju a Oficina &#8220;Abuelitas Songs \u2013 Uma Viagem aos Corpos Ancestrais&#8221;, com a doutoranda em artes c\u00eanicas pela Universidade Federal da Bahia, Fel\u00edcia de Castro. A viv\u00eancia acontece na Casa Encanto (antigo Espa\u00e7o Humanos), localizada no povoado de Areia Branca (Aracaju\/SE). De modo amplo, &#8220;abuelitas&#8221; \u00e9 uma express\u00e3o que se refere \u00e0 sabedoria das mulheres mais velhas.<\/p>\n\n\n\n<p><strong>Fel\u00edcia de Castro<\/strong><\/p>\n\n\n\n<p>&#8220;As av\u00f3s, as abuelas, as abuelitas, s\u00e3o dimens\u00f5es dentro e fora de n\u00f3s. Podem ser nossas av\u00f3s de linhagem materna e paterna, podem ser anci\u00e3s, mulheres s\u00e1bias, mulheres medicina, entidades e figuras femininas maduras, que nos acompanham nas nossas trilhas criativas, curativas, intelectuais e espirituais, podem ser entidades velhas, podem ser a dimens\u00e3o da terra e da natureza. S\u00e3o guardi\u00e3s de mist\u00e9rios e conhecimentos que est\u00e3o no sangue, nas c\u00e9lulas, nos corpos, na hist\u00f3ria da terra&#8221;, informa Fel\u00edcia de Castro, idealizadora da Oficina Abuelitas Songs.<\/p>\n\n\n\n<p><strong>Impulsos criativos<\/strong><\/p>\n\n\n\n<p>Abuelitas Songs \u00e9 um trabalho para todas as mulheres que desejam conhecer seus impulsos criativos por meio das corporalidades c\u00eanicas. N\u00e3o precisa ser atriz profissional para fazer essa imers\u00e3o. &#8220;Fecharemos nossa tarde m\u00e1gica com uma deliciosa sopa ao redor da fogueira, cantando e brindando a lua cheia&#8221;, revela Fel\u00edcia.<\/p>\n\n\n\n<p><strong>Emanuella Tarqu\u00ednio<\/strong><\/p>\n\n\n\n<p>A Casa Encanto, cuidada hoje pela guardi\u00e3 Emanuella Tarqu\u00ednio, \u00e9 tida como um espa\u00e7o sagrado para mulheres e tem o compromisso firme de proporcionar viv\u00eancias art\u00edsticas que possam vir a despertar inclusive processos de curas emocionais, consequentemente f\u00edsicas. Segundo informa\u00e7\u00f5es de Emanuella, na viv\u00eancia Abuelitas Songs, as abuelas convidam as mulheres a abrirem fendas para um tempo fora do tempo, espiralar e c\u00edclico, no qual podemos nos experimentar criativa e afetivamente, ampliando senti pensares para nossas pot\u00eancias internas e de sens\u00edvel caminhar em nossa biografia.<\/p>\n\n\n\n<p><strong>CR\u00cdTICAS E SUGEST\u00d5ES<\/strong><\/p>\n\n\n\n<p><strong><a href=\"mailto:habacuquevillacorte@gmail.com\">habacuquevillacorte@gmail.com<\/a>&nbsp;e&nbsp;<a href=\"https:\/\/mail.google.com\/mail\/u\/0\/h\/k42y0k3pyp4m\/?&amp;cs=wh&amp;v=b&amp;to=habacuquevillacorte@hotmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">habacuquevillacorte@hotmail.com<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atacado por diversos setores da imprensa sergipana, o prefeito de Itabaiana, Valmir de Francisquinho (PL), mesmo ineleg\u00edvel, momentaneamente, continua sendo protagonista da cena pol\u00edtica do nosso Estado. Os ataques ao &#8220;Pato&#8221; s\u00e3o continuados, simult\u00e2neos e, muitas vezes, &#8220;orquestrados&#8221;! Mas ele segue resistindo, consolidando sua lideran\u00e7a na regi\u00e3o Agreste. A viagem para Bras\u00edlia (DF) e as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politizando"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2476"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2476\/revisions"}],"predecessor-version":[{"id":2478,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2476\/revisions\/2478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/2477"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}