{"id":2557,"date":"2025-04-02T11:50:22","date_gmt":"2025-04-02T14:50:22","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=2557"},"modified":"2025-04-02T11:50:23","modified_gmt":"2025-04-02T14:50:23","slug":"ibrain-celebra-criacao-da-secretaria-de-inclusao-das-pessoas-com-deficiencia-em-lagarto","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/02\/ibrain-celebra-criacao-da-secretaria-de-inclusao-das-pessoas-com-deficiencia-em-lagarto\/","title":{"rendered":"Ibrain celebra cria\u00e7\u00e3o da Secretaria de Inclus\u00e3o das Pessoas com Defici\u00eancia em Lagarto"},"content":{"rendered":"\n<p>Durante a Sess\u00e3o plen\u00e1ria desta quarta-feira (2), o deputado Ibrain de Valmir (PV) destacou a inaugura\u00e7\u00e3o (pr\u00f3ximo s\u00e1bado, 5)&nbsp; no munic\u00edpio de Lagarto, da Secretaria Municipal de Inclus\u00e3o das Pessoas com Defici\u00eancia, Acessibilidade e Direitos Humanos (Seminc), visando a garantia de direitos.<\/p>\n\n\n\n<p>\u201c\u00c9 a primeira do estado de Sergipe e um grande avan\u00e7o para o munic\u00edpio de Lagarto, que cria essa Secretaria de Inclus\u00e3o voltada para as Pessoas Com Defici\u00eancia, visando dar uma condi\u00e7\u00e3o melhor a todas as pessoas que precisam dos cuidados por parte do poder p\u00fablico\u201d, comemora.<\/p>\n\n\n\n<p>A nova secretaria municipal funcionar\u00e1 \u00e0 Rua Pedro Ribeiro de Souza, 157 \u2013 Centro, devendo funcionar das 8h \u00e0s 14h, tendo como compet\u00eancia o planejamento, implanta\u00e7\u00e3o e execu\u00e7\u00e3o de pol\u00edticas p\u00fablicas voltadas \u00e0s pessoas com defici\u00eancia, promovendo bem-estar e inclus\u00e3o. A titular ser\u00e1 a secret\u00e1ria Manoela Cassemira Dias de Souza, conhecida como Manoela da Lagartense.<\/p>\n\n\n\n<p>Foto: Jadilson Sim\u00f5es<\/p>\n\n\n\n<p>Por Aldaci de Souza<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a Sess\u00e3o plen\u00e1ria desta quarta-feira (2), o deputado Ibrain de Valmir (PV) destacou a inaugura\u00e7\u00e3o (pr\u00f3ximo s\u00e1bado, 5)&nbsp; no munic\u00edpio de Lagarto, da Secretaria Municipal de Inclus\u00e3o das Pessoas com Defici\u00eancia, Acessibilidade e Direitos Humanos (Seminc), visando a garantia de direitos. \u201c\u00c9 a primeira do estado de Sergipe e um grande avan\u00e7o para o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,2],"tags":[],"class_list":["post-2557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2557"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2557\/revisions"}],"predecessor-version":[{"id":2559,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2557\/revisions\/2559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/2558"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}