{"id":2570,"date":"2025-04-02T12:45:07","date_gmt":"2025-04-02T15:45:07","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=2570"},"modified":"2025-04-02T12:45:08","modified_gmt":"2025-04-02T15:45:08","slug":"autismo-sargento-byron-reforca-leis-municipais-que-asseguram-protecao-e-inclusao","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/02\/autismo-sargento-byron-reforca-leis-municipais-que-asseguram-protecao-e-inclusao\/","title":{"rendered":"Autismo: Sargento Byron refor\u00e7a leis municipais que asseguram prote\u00e7\u00e3o e inclus\u00e3o"},"content":{"rendered":"\n<p>Autismo: Sargento Byron refor\u00e7a leis municipais que asseguram prote\u00e7\u00e3o e inclus\u00e3o<\/p>\n\n\n\n<p>Para fortalecer a inclus\u00e3o social,&nbsp; bem como a import\u00e2ncia da propaga\u00e7\u00e3o de conhecimentos sobre o Transtorno do Espectro Autista (TEA), o vereador sargento Byron &#8211; Estrelas do Mar refor\u00e7a a data de 02 de Abril, Dia Mundial de Conscientiza\u00e7\u00e3o do Autismo, que integra a Campanha Abril Azul .<\/p>\n\n\n\n<p>O parlamentar \u00e9 reconhecido na pol\u00edtica enquanto defensor dos direitos da pessoa com defici\u00eancia, bandeira de atua\u00e7\u00e3o antes mesmo de estar vereador, quando, h\u00e1 14 anos, idealizou o projeto social Estrelas do Mar. &#8220;A data de hoje n\u00e3o deve se tornar algo c\u00f4modo, mas, sim, um momento impulsionador para que toda a sociedade receba as informa\u00e7\u00f5es necess\u00e1rias sobre a pauta, independentemente se convive ou n\u00e3o com algu\u00e9m com autismo. Fa\u00e7o quest\u00e3o de refor\u00e7ar, em minhas falas, que ser emp\u00e1tico n\u00e3o \u00e9 abra\u00e7ar uma causa por viv\u00ea-la, mas, sim, defender toda e qualquer pauta por ser cidad\u00e3o. N\u00e3o \u00e9 preciso doer em mim para que me fa\u00e7a agir&#8221;, declarou Byron.<\/p>\n\n\n\n<p>Na Legisla\u00e7\u00e3o Brasileira, o autismo \u00e9 reconhecido como defici\u00eancia, sendo assegurados direitos legais que garantam prote\u00e7\u00e3o, inclus\u00e3o e suporte para a pessoa com diagn\u00f3stico e sua&nbsp; fam\u00edlia. &#8220;Sabemos que o TEA ainda \u00e9 um diagn\u00f3stico relativamente novo para a nossa sociedade, entretanto, temos grandes conquistas a celebrar. Quando falamos em leis municipais, me orgulho do trabalho que temos realizado na C\u00e2mara Municipal de Aracaju, pois nada se faz sozinho. Cada projeto de lei protocolado sempre foi bem estudado e com participa\u00e7\u00e3o das partes representadas. Agrade\u00e7o a cada parlamentar que tem se somado e aprovado os nosso projetos, permitindo que a nossa sociedade avance com inclus\u00e3o, protagonismo e&nbsp; acolhimento. Ainda temos muito a lutar, por isso devemos falar sobre a pauta incansavelmente&#8221;, refor\u00e7ou o vereador.<\/p>\n\n\n\n<p>Das leis em vigor na capital, que garantem direitos da pessoa com defici\u00eancia, o vereador Sargento Byron comemora a san\u00e7\u00e3o de leis como a 5482\/2022, origin\u00e1ria de propositura de sua autoria, que determina como permanente, sem prazo de validade, o laudo m\u00e9dico \u2013 pericial que atesta o diagn\u00f3stico de defici\u00eancias permanentes de car\u00e1ter n\u00e3o transit\u00f3rio, a exemplo do autismo. &#8221; Sem d\u00favidas, a Lei do Laudo Permanente \u00e9 um marco para a nossa sociedade . Entretanto, ainda seguimos na luta pela melhoria dos servi\u00e7os de sa\u00fade para que o diagn\u00f3stico tenha cada vez mais celeridade . Sabemos que com o laudo em m\u00e3os uma nova trajet\u00f3ria tamb\u00e9m \u00e9 iniciada, a qual tamb\u00e9m necessita de melhorias urgentes, \u00e9 quando me refiro \u00e0 linha de cuidado. Tudo isso \u00e9 um conjunto que exige pol\u00edticas p\u00fablicas e empenho dos Poderes Legislativo, Executivo e Judici\u00e1rio&#8221;, afirmou.<\/p>\n\n\n\n<p>Outra lei municipal, com Projeto de Lei (PL) de autoria do vereador, foi a 5784\/2023, que promoveu a atualiza\u00e7\u00e3o no Fundo Municipal de Apoio aos Portadores de Defici\u00eancia, criado pela Lei 2.340, de 1995. A mudan\u00e7a constitui a altera\u00e7\u00e3o do nome do fundo para Fundo Municipal de Apoio \u00e0s Pessoas com Defici\u00eancia, refletindo uma vis\u00e3o mais inclusiva das pol\u00edticas p\u00fablicas de assist\u00eancia e apoio. O parlamentar defende a efetiva\u00e7\u00e3o do Fundo para garantir recursos e a cria\u00e7\u00e3o do Centro de Refer\u00eancia Educacional Especial para atender necessidades educacionais espec\u00edficas de crian\u00e7as e jovens com defici\u00eancia, proporcionando acesso \u00e0 educa\u00e7\u00e3o inclusiva e de qualidade.<\/p>\n\n\n\n<p>No tocante \u00e0 educa\u00e7\u00e3o, Sargento Byron tamb\u00e9m levou \u00e0 C\u00e2mara de Aracaju a propositura que deu origem \u00e0 Lei 5778\/2023, que assegura \u00e0 pessoa com defici\u00eancia matr\u00edcula&nbsp; na escola municipal mais pr\u00f3xima da sua resid\u00eancia. &#8220;Quando falamos em autismo e outras defici\u00eancias, devemos entender todo o contexto e direitos sociais que permitir\u00e3o a melhor qualidade de vida para essas pessoas. \u00c9 nosso dever promover equidade, sem qualquer brecha para preconceitos em nossa sociedade &#8220;, frisou.<\/p>\n\n\n\n<p>APROVADO<\/p>\n\n\n\n<p>Das proposituras rec\u00e9m-aprovadas pela C\u00e2mara de Aracaju, Byron tamb\u00e9m \u00e9 autor do PL 176\/2024, que torna obrigat\u00f3ria a presen\u00e7a de acompanhantes para pessoas com defici\u00eancia, autismo, s\u00edndrome de Down e doen\u00e7as raras, independentemente da idade; durante consultas, exames e interna\u00e7\u00f5es em institui\u00e7\u00f5es integrantes do Sistema \u00danico de Sa\u00fade (SUS), na rede privada ou conveniada, ou em qualquer situa\u00e7\u00e3o em que a pessoa estiver total ou parcialmente privada de sua autonomia.&nbsp;<\/p>\n\n\n\n<p>Por Jacqueline Reis &#8211; Foto: Luanna Pinheiro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autismo: Sargento Byron refor\u00e7a leis municipais que asseguram prote\u00e7\u00e3o e inclus\u00e3o Para fortalecer a inclus\u00e3o social,&nbsp; bem como a import\u00e2ncia da propaga\u00e7\u00e3o de conhecimentos sobre o Transtorno do Espectro Autista (TEA), o vereador sargento Byron &#8211; Estrelas do Mar refor\u00e7a a data de 02 de Abril, Dia Mundial de Conscientiza\u00e7\u00e3o do Autismo, que integra a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,2],"tags":[],"class_list":["post-2570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2570"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2570\/revisions"}],"predecessor-version":[{"id":2572,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2570\/revisions\/2572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/2571"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}