{"id":3448,"date":"2025-04-09T15:13:03","date_gmt":"2025-04-09T18:13:03","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=3448"},"modified":"2025-04-09T15:13:05","modified_gmt":"2025-04-09T18:13:05","slug":"senador-alessandro-defende-endurecimento-da-lei-contra-corrupcao-e-comemora-aprovacao-na-csp","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/09\/senador-alessandro-defende-endurecimento-da-lei-contra-corrupcao-e-comemora-aprovacao-na-csp\/","title":{"rendered":"Senador Alessandro defende endurecimento da lei contra corrup\u00e7\u00e3o e comemora aprova\u00e7\u00e3o na CSP"},"content":{"rendered":"\n<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica (CSP) do Senado aprovou, na ter\u00e7a-feira (9), o projeto de lei que inclui os crimes de corrup\u00e7\u00e3o ativa e passiva no rol de crimes hediondos. A proposta, que agora segue para a Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ), endurece a legisla\u00e7\u00e3o contra um dos delitos que mais prejudicam o Brasil. O senador Alessandro Vieira (MD\u1e04\/SE), membro da CSP, celebrou a aprova\u00e7\u00e3o e reafirmou sua postura firme no combate \u00e0 corrup\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;Corrup\u00e7\u00e3o n\u00e3o \u00e9 erro t\u00e9cnico. \u00c9 crime doloso, grave e deve ter a resposta penal adequada&#8221;, afirmou Alessandro. Ele destacou que a medida representa um avan\u00e7o necess\u00e1rio para garantir que esses crimes sejam tratados com a severidade que merecem, sem margens para interpreta\u00e7\u00f5es judiciais que possam favorecer condenados por desvio de dinheiro p\u00fablico.<\/p>\n\n\n\n<p>O projeto altera a Lei dos Crimes Hediondos para incluir a corrup\u00e7\u00e3o ativa e passiva, crimes que, se aprovados nessa nova categoria, n\u00e3o poder\u00e3o receber indulto, anistia ou fian\u00e7a. Al\u00e9m disso, os condenados dever\u00e3o cumprir pena inicialmente em regime fechado. Para Alessandro Vieira, essa mudan\u00e7a fortalece a integridade das institui\u00e7\u00f5es e responde a um anseio da sociedade por um combate mais efetivo \u00e0 corrup\u00e7\u00e3o.<\/p>\n\n\n\n<p>Durante a vota\u00e7\u00e3o, o senador sergipano foi enf\u00e1tico ao afirmar que o Congresso tem o dever de reagir sempre que interpreta\u00e7\u00f5es judiciais distorcem o sentido original das leis e acabam beneficiando corruptos. &#8220;Esse projeto \u00e9 um passo firme nessa dire\u00e7\u00e3o&#8221;, ressaltou.<\/p>\n\n\n\n<p>A corrup\u00e7\u00e3o no Brasil tem impacto direto na vida da popula\u00e7\u00e3o, desviando recursos essenciais para \u00e1reas como sa\u00fade, educa\u00e7\u00e3o e infraestrutura. Dados da Transpar\u00eancia Internacional apontam que o Brasil ocupa uma posi\u00e7\u00e3o preocupante no \u00cdndice de Percep\u00e7\u00e3o da Corrup\u00e7\u00e3o, evidenciando a necessidade de medidas rigorosas para reverter esse cen\u00e1rio.<\/p>\n\n\n\n<p>Com a aprova\u00e7\u00e3o na CSP, a proposta agora ser\u00e1 analisada pela CCJ, onde poder\u00e1 receber parecer final antes de seguir para o plen\u00e1rio do Senado. Para Alessandro Vieira, essa \u00e9 uma batalha que precisa ser vencida com a uni\u00e3o do Congresso e da sociedade: &#8220;O Brasil n\u00e3o pode mais tolerar a corrup\u00e7\u00e3o. O sistema de justi\u00e7a precisa responder \u00e0 altura desse crime que tanto destr\u00f3i nosso pa\u00eds&#8221;, concluiu o senador.<\/p>\n\n\n\n<p>Por Laisa Bomfim \u2013 Foto Pedro Fran\u00e7a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica (CSP) do Senado aprovou, na ter\u00e7a-feira (9), o projeto de lei que inclui os crimes de corrup\u00e7\u00e3o ativa e passiva no rol de crimes hediondos. A proposta, que agora segue para a Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a (CCJ), endurece a legisla\u00e7\u00e3o contra um dos delitos que mais prejudicam o Brasil. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6,2],"tags":[],"class_list":["post-3448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3448"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3448\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3448\/revisions\/3450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/3449"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}