{"id":450,"date":"2025-03-14T16:41:38","date_gmt":"2025-03-14T19:41:38","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=450"},"modified":"2025-03-14T16:41:38","modified_gmt":"2025-03-14T19:41:38","slug":"prefeitura-disponibiliza-onibus-para-shows-do-aniversario-de-aracaju","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/03\/14\/prefeitura-disponibiliza-onibus-para-shows-do-aniversario-de-aracaju\/","title":{"rendered":"Prefeitura disponibiliza \u00f4nibus para shows do Anivers\u00e1rio de Aracaju"},"content":{"rendered":"\n<p>A Prefeitura de Aracaju vai disponibilizar \u00f4nibus gratuitos para facilitar o acesso da popula\u00e7\u00e3o aos shows que acontecem na Orla de Atalaia neste final de semana, e no Centro da cidade, em comemora\u00e7\u00e3o aos 170 anos de Aracaju. Os ve\u00edculos sair\u00e3o de quatro pontos estrat\u00e9gicos da capital e estar\u00e3o devidamente identificados com o letreiro &#8220;Anivers\u00e1rio de 170 anos de Aracaju&#8221;.<\/p>\n\n\n\n<p>Os pontos de embarque ser\u00e3o: Orla do Porto Dantas, Final de Linha do Bugio, Final de Linha do Augusto Franco e Orla P\u00f4r do Sol. Os \u00f4nibus sair\u00e3o desses locais em hor\u00e1rios escalonados, entre 15h25 e 16h20, levando os passageiros at\u00e9 a Orla de Atalaia e, no dia 17, para a pra\u00e7a Fausto Cardoso, no Centro, inclusive alguns \u00f4nibus ter\u00e3o ar-condicionado.<\/p>\n\n\n\n<p>Para o retorno, os ve\u00edculos estar\u00e3o dispon\u00edveis a partir das 23h, garantindo que todos possam voltar com tranquilidade aos seus bairros de origem. Al\u00e9m disso, os \u00f4nibus que sa\u00edrem da Orla do Porto Dantas e do Final de Linha do Bugio far\u00e3o uma parada na Pra\u00e7a Fausto Cardoso para embarque de passageiros.<\/p>\n\n\n\n<p>A prefeita Em\u00edlia Corr\u00eaa destacou a import\u00e2ncia da iniciativa para garantir o acesso da popula\u00e7\u00e3o \u00e0s comemora\u00e7\u00f5es. &#8220;Queremos que todos os aracajuanos possam participar dessa grande celebra\u00e7\u00e3o dos 170 anos da nossa cidade. Por isso, disponibilizamos \u00f4nibus gratuitos saindo de v\u00e1rios pontos da capital, garantindo acesso aos shows na Orla de Atalaia. Nosso compromisso \u00e9 com o bem-estar da popula\u00e7\u00e3o, e essa \u00e9 mais uma iniciativa para tornar essa festa ainda mais inclusiva e especial.&#8221;<\/p>\n\n\n\n<p>A medida busca proporcionar mais conforto e seguran\u00e7a para os aracajuanos, incentivando a participa\u00e7\u00e3o da popula\u00e7\u00e3o nas festividades que celebram a hist\u00f3ria e a cultura da capital sergipana.<\/p>\n\n\n\n<p>Texto e foto AAN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Aracaju vai disponibilizar \u00f4nibus gratuitos para facilitar o acesso da popula\u00e7\u00e3o aos shows que acontecem na Orla de Atalaia neste final de semana, e no Centro da cidade, em comemora\u00e7\u00e3o aos 170 anos de Aracaju. Os ve\u00edculos sair\u00e3o de quatro pontos estrat\u00e9gicos da capital e estar\u00e3o devidamente identificados com o letreiro &#8220;Anivers\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,12,3],"tags":[],"class_list":["post-450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-agora","category-policia"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=450"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/450\/revisions"}],"predecessor-version":[{"id":452,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/450\/revisions\/452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/451"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}