{"id":5132,"date":"2025-04-25T04:35:02","date_gmt":"2025-04-25T07:35:02","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5132"},"modified":"2025-04-25T04:35:05","modified_gmt":"2025-04-25T07:35:05","slug":"igh-sera-o-novo-gestor-da-maternidade-lourdes-nogueira","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/25\/igh-sera-o-novo-gestor-da-maternidade-lourdes-nogueira\/","title":{"rendered":"IGH ser\u00e1 o novo gestor da Maternidade Lourdes Nogueira"},"content":{"rendered":"\n<p>Nesta quinta-feira, 24, a prefeita de Aracaju, Em\u00edlia Corr\u00eaa, anunciou a assinatura do contrato com o Instituto de Gest\u00e3o e Humaniza\u00e7\u00e3o (IGH), nova organiza\u00e7\u00e3o social respons\u00e1vel pela administra\u00e7\u00e3o da Maternidade Municipal Lourdes Nogueira. A mudan\u00e7a ocorre ap\u00f3s o Instituto Nacional de Tecnologia e Sa\u00fade (INTS), atual gestor da unidade, solicitar a rescis\u00e3o contratual no final de mar\u00e7o.<\/p>\n\n\n\n<p>Segundo a secret\u00e1ria municipal da Sa\u00fade, D\u00e9bora Leite, o processo de transi\u00e7\u00e3o j\u00e1 come\u00e7a imediatamente, com total compromisso da gest\u00e3o em garantir a continuidade e a qualidade dos servi\u00e7os prestados \u00e0s gestantes e colaboradores. \u201cDesde o primeiro momento em que recebemos o pedido de rescis\u00e3o, nosso foco foi assegurar que a assist\u00eancia n\u00e3o fosse interrompida. Todos os servi\u00e7os ser\u00e3o mantidos, e a popula\u00e7\u00e3o pode ficar tranquila quanto a isso\u201d, afirmou.<\/p>\n\n\n\n<p>ECONOMIA<br>Al\u00e9m da continuidade dos atendimentos, o novo contrato representa uma importante economia para os cofres p\u00fablicos. Com valor mensal de R$ 5,5 milh\u00f5es (em compara\u00e7\u00e3o aos R$ 6,8 milh\u00f5es pagos anteriormente), a nova parceria com o IGH vai gerar uma redu\u00e7\u00e3o mensal de R$ 1,3 milh\u00e3o. Considerando os 32 meses restantes do contrato original, que se encerraria em dezembro de 2027, a economia total ultrapassa os R$ 42 milh\u00f5es.<\/p>\n\n\n\n<p>Outro ponto destacado pela secret\u00e1ria \u00e9 a d\u00edvida herdada da gest\u00e3o anterior com o INTS. \u201cFirmamos um acordo para o pagamento de R$ 17,6 milh\u00f5es referentes \u00e0 d\u00edvida deixada pela administra\u00e7\u00e3o passada. J\u00e1 em maio, ser\u00e1 paga uma primeira parcela de R$ 8 milh\u00f5es, seguida de oito parcelas de R$ 1,2 milh\u00e3o\u201d, explicou D\u00e9bora.<\/p>\n\n\n\n<p>A prefeita Em\u00edlia Corr\u00eaa lamentou que quase R$ 18 milh\u00f5es, que poderiam ser investidos em melhorias na rede municipal, estejam sendo destinados ao pagamento de d\u00e9bitos da gest\u00e3o anterior. \u201cMesmo diante dessas dificuldades, estamos firmes em nosso compromisso com a sa\u00fade da popula\u00e7\u00e3o de Aracaju. Esta \u00e9 uma conquista importante, e em breve teremos outras boas not\u00edcias para compartilhar\u201d, destacou.<\/p>\n\n\n\n<p>O processo emergencial de sele\u00e7\u00e3o contou com o interesse de sete institui\u00e7\u00f5es, das quais tr\u00eas apresentaram propostas efetivas. O IGH foi selecionado ap\u00f3s an\u00e1lise t\u00e9cnica e financeira criteriosa, refor\u00e7ando o compromisso da atual gest\u00e3o com a responsabilidade e a efici\u00eancia na administra\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Sobre o IGH<br>O Instituto de Gest\u00e3o e Humaniza\u00e7\u00e3o (IGH) \u00e9 uma entidade sem fins lucrativos que surgiu h\u00e1 15 anos da iniciativa de profissionais especializados na \u00e1rea da sa\u00fade, motivados pela necessidade de aprimorar a gest\u00e3o dos servi\u00e7os p\u00fablicos de sa\u00fade. Seu foco est\u00e1 na aplica\u00e7\u00e3o de pr\u00e1ticas modernas de gest\u00e3o capazes de potencializar os resultados das unidades que administra.<\/p>\n\n\n\n<p>Com sede em Salvador (BA), o IGH atua em diversas regi\u00f5es do pa\u00eds, sendo respons\u00e1vel pela gest\u00e3o de importantes equipamentos de sa\u00fade, como o Hospital Estadual e Maternidade Nossa Senhora de Lourdes (HEMNSL), em Goi\u00e1s, e a Maternidade Prof. Jos\u00e9 Maria de Magalh\u00e3es Netto, em Salvador, refer\u00eancia em alto risco obst\u00e9trico e neonatal. Esta \u00faltima possui o certificado ONA 3, Acreditado com Excel\u00eancia, concedido pela Organiza\u00e7\u00e3o Nacional de Acredita\u00e7\u00e3o (ONA), reconhecendo seu compromisso com a seguran\u00e7a do paciente, a melhoria cont\u00ednua e a excel\u00eancia na assist\u00eancia materno-infantil.<\/p>\n\n\n\n<p>ASCOM\/SMS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quinta-feira, 24, a prefeita de Aracaju, Em\u00edlia Corr\u00eaa, anunciou a assinatura do contrato com o Instituto de Gest\u00e3o e Humaniza\u00e7\u00e3o (IGH), nova organiza\u00e7\u00e3o social respons\u00e1vel pela administra\u00e7\u00e3o da Maternidade Municipal Lourdes Nogueira. A mudan\u00e7a ocorre ap\u00f3s o Instituto Nacional de Tecnologia e Sa\u00fade (INTS), atual gestor da unidade, solicitar a rescis\u00e3o contratual no final [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,8],"tags":[],"class_list":["post-5132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-letreiro","category-saude"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5132"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5132\/revisions"}],"predecessor-version":[{"id":5134,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5132\/revisions\/5134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5133"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}