{"id":5203,"date":"2025-04-25T10:42:29","date_gmt":"2025-04-25T13:42:29","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5203"},"modified":"2025-04-25T10:42:30","modified_gmt":"2025-04-25T13:42:30","slug":"ricardo-marques-orienta-populacao-a-evitar-descarte-irregular-do-lixo-em-aracaju","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/25\/ricardo-marques-orienta-populacao-a-evitar-descarte-irregular-do-lixo-em-aracaju\/","title":{"rendered":"Ricardo Marques orienta popula\u00e7\u00e3o a evitar descarte irregular do lixo em Aracaju"},"content":{"rendered":"\n<p>O vice-prefeito de Aracaju, Ricardo Marques, esteve na Zona Norte de Aracaju e flagrou o descarte irregular de lixo em diversas regi\u00f5es e pediu o apoio da popula\u00e7\u00e3o para evitar a pr\u00e1tica que prejudica o meio ambiente.<\/p>\n\n\n\n<p>\u201cAo lado da prefeita Em\u00edlia Corr\u00eaa, cheguei na gest\u00e3o com muitos desafios para melhorar a cidade, um deles \u00e9 o recolhimento do lixo que ainda n\u00e3o \u00e9 licitado, \u00e9 feito apenas atrav\u00e9s de contratos emergenciais, mas em breve vamos concretizar essa regulariza\u00e7\u00e3o fazendo a licita\u00e7\u00e3o. Aracaju \u00e9 uma cidade linda e merece estar sempre limpa e a popula\u00e7\u00e3o deve ajudar tamb\u00e9m. Recebi muitas den\u00fancias de descarte irregular do lixo e pude conferir de perto e pe\u00e7o que todos colaborem\u201d, apela o vice-prefeito.<\/p>\n\n\n\n<p>Ricardo Marques caminha diariamente nas ruas da capital e pede ajuda da popula\u00e7\u00e3o para manter a cidade limpa. \u201cSabemos das dificuldades que enfrentamos, mas com a ajuda de todos fica mais f\u00e1cil. Por exemplo: voc\u00ea sabia que a Prefeitura, por meio da Emsurb , disponibiliza servi\u00e7os gratuitos para facilitar o descarte correto do lixo?\u201d.<\/p>\n\n\n\n<p>A Opera\u00e7\u00e3o Cata-Treco recolhe m\u00f3veis velhos, sof\u00e1s e outros objetos que n\u00e3o servem mais. Tem tamb\u00e9m os Ecopontos espalhados pela cidade, onde \u00e9 poss\u00edvel deixar entulhos e res\u00edduos volumosos de forma segura e ambientalmente correta.<\/p>\n\n\n\n<p>Para solicitar o Cata-Treco, \u00e9 simples: Ligue para (79) 3021-9914 ou (79) 3021-9908 (Ouvidoria). Ou envie um e-mail para ouvidoria.emsurb@aracaju.se.gov.br<\/p>\n\n\n\n<p>\u201cManter Aracaju limpa \u00e9 uma responsabilidade de todos n\u00f3s! Vamos juntos cuidar de nossa Aracaju\u201d, vibra Ricardo Marques.<\/p>\n\n\n\n<p>Por Fredson Navarro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O vice-prefeito de Aracaju, Ricardo Marques, esteve na Zona Norte de Aracaju e flagrou o descarte irregular de lixo em diversas regi\u00f5es e pediu o apoio da popula\u00e7\u00e3o para evitar a pr\u00e1tica que prejudica o meio ambiente. \u201cAo lado da prefeita Em\u00edlia Corr\u00eaa, cheguei na gest\u00e3o com muitos desafios para melhorar a cidade, um deles [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,6,2],"tags":[],"class_list":["post-5203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5203"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203\/revisions"}],"predecessor-version":[{"id":5205,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5203\/revisions\/5205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5204"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}