{"id":5249,"date":"2025-04-25T14:27:45","date_gmt":"2025-04-25T17:27:45","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5249"},"modified":"2025-04-25T14:27:46","modified_gmt":"2025-04-25T17:27:46","slug":"prefeita-emilia-participa-de-forum-da-cnt-e-anuncia-envio-de-pl-para-aquisicao-de-novos-onibus-pelo-pac","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/25\/prefeita-emilia-participa-de-forum-da-cnt-e-anuncia-envio-de-pl-para-aquisicao-de-novos-onibus-pelo-pac\/","title":{"rendered":"Prefeita Em\u00edlia participa de F\u00f3rum da CNT e anuncia envio de PL para aquisi\u00e7\u00e3o de novos \u00f4nibus pelo PAC"},"content":{"rendered":"\n<p>A Prefeita de Aracaju, Em\u00edlia Corr\u00eaa, participou, nesta quinta-feira, 25, do F\u00f3rum CNT de Debates Regional, etapa Alagoas\/Sergipe promovido pela Confedera\u00e7\u00e3o Nacional do Transporte (CNT). Com o tema \u201cCaminhos para o Fortalecimento do Transporte no Nordeste e no Brasil\u201d, o evento reuniu autoridades, parlamentares, empres\u00e1rios e representantes do setor para discutir solu\u00e7\u00f5es e investimentos voltados \u00e0 mobilidade urbana na regi\u00e3o.<\/p>\n\n\n\n<p>Durante o encontro, realizado com o objetivo de estreitar o relacionamento entre o Sistema Transporte e o setor produtivo e promover o di\u00e1logo com as autoridades sobre as demandas regionais, a prefeita Em\u00edlia anunciou que vai enviar um projeto de lei para C\u00e2mara de Vereadores que pede autoriza\u00e7\u00e3o para contratar uma opera\u00e7\u00e3o de cr\u00e9dito junto \u00e0 Caixa Econ\u00f4mica Federal dentro do Programa Pr\u00f3-Transporte &#8211; PAC Refrota &#8211; para adquirir novos \u00f4nibus.<\/p>\n\n\n\n<p>Em sua fala, a gestora destacou que o transporte coletivo foi uma das demandas mais apontadas pela popula\u00e7\u00e3o, ao lado da sa\u00fade, como setores que n\u00e3o funcionavam e que, por isso, desde o in\u00edcio do mandato, a gest\u00e3o tem assumido com responsabilidade os desafios de dar uma cara nova para a mobilidade urbana. \u201cAssumimos o compromisso com o povo de Aracaju de melhorar o transporte p\u00fablico da nossa cidade. Ainda no primeiro m\u00eas, adotamos medidas urgentes para garantir mais qualidade na presta\u00e7\u00e3o do servi\u00e7o. Mantivemos a tarifa congelada em R$ 4,50. Demos um passo importante com a san\u00e7\u00e3o da Lei 6.146\/2025 que permite a aquisi\u00e7\u00e3o dos primeiros \u00f4nibus el\u00e9tricos da hist\u00f3ria da capital, al\u00e9m dos carregadores e de uma usina fotovoltaica que garantir\u00e1 sustentabilidade ao sistema. J\u00e1 iniciamos a renova\u00e7\u00e3o da frota com a nova empresa e tamb\u00e9m celebramos a chegada dos primeiros \u00f4nibus com ar-condicionado, wi-fi, carregadores de celular e elevadores para garantir a acessibilidade\u201d.<\/p>\n\n\n\n<p>\u201cAgora, estamos avan\u00e7ando ainda mais. Hoje mesmo assinarei um projeto de lei que vamos enviar para o Legislativo que pede autoriza\u00e7\u00e3o \u00e0 C\u00e2mara de Vereadores para contratar uma opera\u00e7\u00e3o de cr\u00e9dito com a Caixa Econ\u00f4mica Federal, no valor de R$ 136 milh\u00f5es, dentro do Programa Pr\u00f3-Transporte &#8211; PAC Refrota. Esse valor ser\u00e1 destinado \u00e0 aquisi\u00e7\u00e3o de aproximadamente 136 \u00f4nibus modelo Euro 6, mais modernos e sustent\u00e1veis, que emitem 70% menos poluentes. S\u00e3o a\u00e7\u00f5es concretas que demonstram nosso compromisso com a moderniza\u00e7\u00e3o do transporte e com a qualidade de vida da popula\u00e7\u00e3o\u201d, destacou Em\u00edlia.<\/p>\n\n\n\n<p>O F\u00f3rum contou com a presen\u00e7a do ministro do Transportes, Renan Filho e do ministro da Secretaria-Geral da Presid\u00eancia, M\u00e1rcio Macedo, al\u00e9m do vice-governador de Sergipe, Zezinho Sobral, de parlamentares, representantes do setor empresarial e o presidente da CNT, Vander Costa. As discuss\u00f5es evidenciaram a import\u00e2ncia de investimentos estruturantes para o fortalecimento do transporte no Nordeste, com foco na realidade e nas necessidades locais.<\/p>\n\n\n\n<p>Foto: Ronald Almeida\/Secom PMA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeita de Aracaju, Em\u00edlia Corr\u00eaa, participou, nesta quinta-feira, 25, do F\u00f3rum CNT de Debates Regional, etapa Alagoas\/Sergipe promovido pela Confedera\u00e7\u00e3o Nacional do Transporte (CNT). Com o tema \u201cCaminhos para o Fortalecimento do Transporte no Nordeste e no Brasil\u201d, o evento reuniu autoridades, parlamentares, empres\u00e1rios e representantes do setor para discutir solu\u00e7\u00f5es e investimentos voltados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,2],"tags":[],"class_list":["post-5249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5249"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5249\/revisions"}],"predecessor-version":[{"id":5251,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5249\/revisions\/5251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5250"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}