{"id":5838,"date":"2025-04-30T15:49:44","date_gmt":"2025-04-30T18:49:44","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5838"},"modified":"2025-04-30T15:49:45","modified_gmt":"2025-04-30T18:49:45","slug":"prefeitura-disponibiliza-servico-de-combate-ao-descarte-irregular-em-prol-da-consciencia-ambiental","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/04\/30\/prefeitura-disponibiliza-servico-de-combate-ao-descarte-irregular-em-prol-da-consciencia-ambiental\/","title":{"rendered":"Prefeitura disponibiliza servi\u00e7o de combate ao descarte irregular em prol da consci\u00eancia ambiental"},"content":{"rendered":"\n<p>Prefeitura disponibiliza servi\u00e7o de combate ao descarte irregular em prol da consci\u00eancia ambiental<\/p>\n\n\n\n<p>Mesmo com a presen\u00e7a de um ecoponto a poucos metros de dist\u00e2ncia, moradores do bairro 17 de Mar\u00e7o continuam descartando res\u00edduos volumosos de forma irregular, assim como pessoas de outras localidades da capital, pr\u00e1tica que causa preju\u00edzos ao meio ambiente e onera os servi\u00e7os p\u00fablicos. A situa\u00e7\u00e3o foi registrada nesta quarta-feira, 30, quando a equipe operacional da Empresa Municipal de Servi\u00e7os Urbanos (Emsurb) esteve no local para realizar a a\u00e7\u00e3o de limpeza.<\/p>\n\n\n\n<p>O flagrante ocorreu em uma das ruas do bairro 17 de Mar\u00e7o, em local pr\u00f3ximo ao Ponto de Entrega Volunt\u00e1ria de Res\u00edduos Volumosos. Na localidade, era poss\u00edvel ver restos de m\u00f3veis, peda\u00e7os de madeira e outros materiais descartados diretamente sobre o solo. O que chama aten\u00e7\u00e3o \u00e9 que, a poucos metros dali, existe uma estrutura adequada para receber esse tipo de res\u00edduo de forma segura e ambientalmente correta.<\/p>\n\n\n\n<p>&#8220;Mesmo com todos os servi\u00e7os oferecidos, o descarte irregular ainda \u00e9 um desafio. Precisamos refor\u00e7ar a conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o, pois al\u00e9m de prejudicar o meio ambiente, essa pr\u00e1tica causa transtornos como alagamentos e riscos \u00e0 sa\u00fade p\u00fablica&#8221;, afirma o diretor operacional da Emsurb, Elder Muniz.<\/p>\n\n\n\n<p>Cerca de 150 pontos de descarte irregular s\u00e3o limpos semanalmente em Aracaju. Essa pr\u00e1tica representa n\u00e3o apenas um risco ambiental, por contaminar o solo e atrair vetores de doen\u00e7as, como tamb\u00e9m gera custos significativos aos cofres p\u00fablicos com a limpeza e remo\u00e7\u00e3o desses materiais.<\/p>\n\n\n\n<p>A orienta\u00e7\u00e3o \u00e9 clara: lugar de res\u00edduo volumoso \u00e9 no ecoponto. A popula\u00e7\u00e3o pode e deve utilizar esses espa\u00e7os, contribuindo para a preserva\u00e7\u00e3o da cidade e do meio ambiente.<\/p>\n\n\n\n<p>Foto: Ascom Emsurb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prefeitura disponibiliza servi\u00e7o de combate ao descarte irregular em prol da consci\u00eancia ambiental Mesmo com a presen\u00e7a de um ecoponto a poucos metros de dist\u00e2ncia, moradores do bairro 17 de Mar\u00e7o continuam descartando res\u00edduos volumosos de forma irregular, assim como pessoas de outras localidades da capital, pr\u00e1tica que causa preju\u00edzos ao meio ambiente e onera [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6,10],"tags":[],"class_list":["post-5838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letreiro","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5838"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5838\/revisions"}],"predecessor-version":[{"id":5840,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5838\/revisions\/5840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5839"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}