{"id":594,"date":"2025-03-18T04:49:49","date_gmt":"2025-03-18T07:49:49","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=594"},"modified":"2025-03-18T04:49:49","modified_gmt":"2025-03-18T07:49:49","slug":"na-romaria-do-senhor-dos-passos-armando-batalha-da-passos-importantes-para-voltar-a-cena-politica","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/03\/18\/na-romaria-do-senhor-dos-passos-armando-batalha-da-passos-importantes-para-voltar-a-cena-politica\/","title":{"rendered":"Na romaria do Senhor dos Passos, Armando Batalha d\u00e1 passos importantes para voltar \u00e0 cena pol\u00edtica"},"content":{"rendered":"\n<p>Abra\u00e7ado ao Senador La\u00e9rcio Oliveira, ex-prefeito caminha pela cidade e \u00e9 recebido com festa pelos moradores de S\u00e3o Crist\u00f3v\u00e3o<\/p>\n\n\n\n<p>Na prociss\u00e3o de Nosso Senhor dos Passos, realizada no \u00faltimo domingo em S\u00e3o Crist\u00f3v\u00e3o, uma movimenta\u00e7\u00e3o na Pra\u00e7a do Carmo tamb\u00e9m chamou aten\u00e7\u00e3o de todos que foram \u00e0 Cidade-M\u00e3e para acompanhar a maior romaria do estado, que atrai fi\u00e9is dos quatro cantos de Sergipe. Na Casa Amarela, pertencente \u00e0 fam\u00edlia Batalha, Armando, ex-prefeito da 4\u00aa cidade mais antiga do Brasil e seu filho, o deputado estadual Neto Batalha, foram os grandes anfitri\u00f5es de romeiros, amigos e uma grande comitiva de lideran\u00e7as pol\u00edticas e comunit\u00e1rias.<\/p>\n\n\n\n<p>Como de costume, a penit\u00eancia dos milhares de devotos da f\u00e9 cat\u00f3lica diante do encontro da Virgem Maria e seu filho Jesus foi o ponto culminante da tradi\u00e7\u00e3o secular que toma as ruas da cidade hist\u00f3rica. Mas, ao mesmo tempo, n\u00e3o passou despercebido a maneira como o ex-prefeito Armando Batalha foi recebido pelos s\u00e3o-cristovenses.&nbsp; Por onde passou, Armando foi calorosamente recebido pelos fi\u00e9is e moradores, demonstrando que sua presen\u00e7a na pol\u00edtica continua forte e respeitada.<\/p>\n\n\n\n<p>Abra\u00e7ados \u00e0s duas gera\u00e7\u00f5es de Batalhas, tamb\u00e9m caminharam o Senador La\u00e9rcio Oliveira e seu sobrinho, o vereador de Aracaju Levi Oliveira. Tamb\u00e9m marcaram presen\u00e7a o presidente do PSB da capital e Secret\u00e1rio de Estado da Sa\u00fade, Cl\u00e1udio Mitidieri, o ex-vereador e candidato a prefeito de S\u00e3o Crist\u00f3v\u00e3o em 2024, Diego Prado, entre outras importantes lideran\u00e7as pol\u00edticas.<\/p>\n\n\n\n<p>Sem d\u00favida alguma, a presen\u00e7a de Armando Batalha na romaria deste ano demonstra que, ao contr\u00e1rio do que muita gente tenta fazer crer, o ex-prefeito mant\u00e9m uma forte conex\u00e3o com o povo de S\u00e3o Crist\u00f3v\u00e3o e sinaliza que seu nome segue com for\u00e7a no cen\u00e1rio pol\u00edtico. S\u00f3 n\u00e3o v\u00ea quem n\u00e3o quer.<\/p>\n\n\n\n<p>Foto assessoria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abra\u00e7ado ao Senador La\u00e9rcio Oliveira, ex-prefeito caminha pela cidade e \u00e9 recebido com festa pelos moradores de S\u00e3o Crist\u00f3v\u00e3o Na prociss\u00e3o de Nosso Senhor dos Passos, realizada no \u00faltimo domingo em S\u00e3o Crist\u00f3v\u00e3o, uma movimenta\u00e7\u00e3o na Pra\u00e7a do Carmo tamb\u00e9m chamou aten\u00e7\u00e3o de todos que foram \u00e0 Cidade-M\u00e3e para acompanhar a maior romaria do estado, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,6,2],"tags":[],"class_list":["post-594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=594"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/594\/revisions"}],"predecessor-version":[{"id":596,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/594\/revisions\/596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/595"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}