{"id":5971,"date":"2025-05-02T09:15:16","date_gmt":"2025-05-02T12:15:16","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5971"},"modified":"2025-05-02T09:15:17","modified_gmt":"2025-05-02T12:15:17","slug":"comite-operacional-de-aracaju-intensifica-acoes-preventivas-diante-de-previsao-de-chuvas","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/02\/comite-operacional-de-aracaju-intensifica-acoes-preventivas-diante-de-previsao-de-chuvas\/","title":{"rendered":"Comit\u00ea Operacional de Aracaju intensifica a\u00e7\u00f5es preventivas diante de previs\u00e3o de chuvas"},"content":{"rendered":"\n<p>A Prefeitura de Aracaju, por meio do Comit\u00ea Operacional (COA), est\u00e1 com equipes mobilizadas e executando a\u00e7\u00f5es preventivas em diversos pontos da cidade. As atividades ocorrem em articula\u00e7\u00e3o com a Emsurb, Emurb e Defesa Civil, seguindo o plano de conting\u00eancia com foco na preven\u00e7\u00e3o e resposta r\u00e1pida a poss\u00edveis ocorr\u00eancias, especialmente em \u00e1reas com hist\u00f3rico de alagamentos.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es foram intensificadas a partir desta quinta-feira, com a desobstru\u00e7\u00e3o da rede de drenagem na orla do bairro Porto Dantas, utilizando maquin\u00e1rio pesado. Na sexta-feira, os trabalhos incluem a limpeza de bocas de lobo nos bairros Centro, Salgado Filho, avenida Francisco Porto, Santa Maria e Lamar\u00e3o, al\u00e9m da limpeza de vala de drenagem no Morro do Valadares, no Santa Maria.<\/p>\n\n\n\n<p>Durante o fim de semana, as equipes estar\u00e3o de prontid\u00e3o nas zonas Norte, Sul e Central, com retroescavadeira em estado de aten\u00e7\u00e3o. Os servi\u00e7os de poda e limpeza p\u00fablica tamb\u00e9m atuar\u00e3o em regime de plant\u00e3o.<\/p>\n\n\n\n<p>A Defesa Civil informa que todas as coordenadorias envolvidas est\u00e3o mobilizadas para atendimento imediato em caso de necessidade. Isso inclui as \u00e1reas de limpeza p\u00fablica, res\u00edduos s\u00f3lidos, transporte e poda. A popula\u00e7\u00e3o deve acompanhar os canais oficiais da Prefeitura para atualiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>A Defesa Civil de Aracaju emitiu alerta de chuva fraca \u00e0 moderada, com possibilidade de raios, trov\u00f5es e ventos fortes nas pr\u00f3ximas 72 horas. Em caso de emerg\u00eancia, ligue 199.<\/p>\n\n\n\n<p>Texto e foto AAN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Aracaju, por meio do Comit\u00ea Operacional (COA), est\u00e1 com equipes mobilizadas e executando a\u00e7\u00f5es preventivas em diversos pontos da cidade. As atividades ocorrem em articula\u00e7\u00e3o com a Emsurb, Emurb e Defesa Civil, seguindo o plano de conting\u00eancia com foco na preven\u00e7\u00e3o e resposta r\u00e1pida a poss\u00edveis ocorr\u00eancias, especialmente em \u00e1reas com hist\u00f3rico [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-5971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5971"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5971\/revisions"}],"predecessor-version":[{"id":5973,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5971\/revisions\/5973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5972"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}