{"id":5985,"date":"2025-05-02T10:06:56","date_gmt":"2025-05-02T13:06:56","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=5985"},"modified":"2025-05-02T10:06:57","modified_gmt":"2025-05-02T13:06:57","slug":"se-438-rodovia-que-desabou-em-capela-sera-reconstruida-em-seis-meses","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/02\/se-438-rodovia-que-desabou-em-capela-sera-reconstruida-em-seis-meses\/","title":{"rendered":"SE-438: rodovia que desabou em Capela ser\u00e1 reconstru\u00edda em seis meses"},"content":{"rendered":"\n<p>O Governo de Sergipe, atrav\u00e9s do Departamento Estadual de Infraestrutura Rodovi\u00e1ria de Sergipe (DER\/SE), j\u00e1 iniciou os servi\u00e7os de reconstru\u00e7\u00e3o da rodovia SE-438, popularmente conhecida como rodovia Santa Clara, no munic\u00edpio de Capela. Com investimento total de mais de R$ 6 milh\u00f5es, o projeto de revitaliza\u00e7\u00e3o \u00e9 abrangente e inclui a constru\u00e7\u00e3o de uma ponte.<\/p>\n\n\n\n<p>A estrutura ter\u00e1 dimens\u00f5es de 10 metros de largura por 21 metros de comprimento, visando garantir maior seguran\u00e7a e fluidez no tr\u00e1fego. Al\u00e9m da constru\u00e7\u00e3o da ponte, a obra contemplar\u00e1 a recupera\u00e7\u00e3o da terraplenagem e a pavimenta\u00e7\u00e3o de um trecho de aproximadamente 500 metros da SE-438, precisamente entre os quil\u00f4metros 2,60 e 3,085.<\/p>\n\n\n\n<p>&#8220;A reconstru\u00e7\u00e3o da rodovia Santa Clara \u00e9 uma demonstra\u00e7\u00e3o do compromisso do Governo do Estado com a melhoria da infraestrutura vi\u00e1ria, visando proporcionar mais seguran\u00e7a e conforto para a popula\u00e7\u00e3o sergipana. Estamos empenhados em entregar uma rodovia totalmente revitalizada e segura para todos os usu\u00e1rios&#8221;, afirma o diretor-presidente do DER\/SE, Anderson das Neves.<\/p>\n\n\n\n<p>Com o prazo de conclus\u00e3o previsto em 180 dias, o diretor t\u00e9cnico Igor Albuquerque destaca a agilidade dos servi\u00e7os para que a obra seja entregue em breve. &#8220;Nossas equipes j\u00e1 est\u00e3o mobilizadas e vamos trabalhar com celeridade, mas sem abrir m\u00e3o da qualidade, para que os servi\u00e7os de constru\u00e7\u00e3o desta ponte e a revitaliza\u00e7\u00e3o dessa rodovia, t\u00e3o importante para o escoamento da produ\u00e7\u00e3o e o acesso aos servi\u00e7os essenciais, sejam conclu\u00eddos o mais breve poss\u00edvel&#8221;, destaca.<\/p>\n\n\n\n<p>Rotas alternativas durante a execu\u00e7\u00e3o da obra<\/p>\n\n\n\n<p>Para atenuar o impacto da interdi\u00e7\u00e3o da rodovia SE-438 durante o per\u00edodo de execu\u00e7\u00e3o dos servi\u00e7os, o DER\/SE informa que as seguintes vias poder\u00e3o ser utilizadas como rotas alternativas:<\/p>\n\n\n\n<p>SE-339: Ligando o Povoado Pirunga a Capela.<\/p>\n\n\n\n<p>SE-226: Acesso a Capela via BR-101, passando pelo Povoado Miranda.<\/p>\n\n\n\n<p>SE-339: Ligando Capela a Nossa Senhora das Dor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo de Sergipe, atrav\u00e9s do Departamento Estadual de Infraestrutura Rodovi\u00e1ria de Sergipe (DER\/SE), j\u00e1 iniciou os servi\u00e7os de reconstru\u00e7\u00e3o da rodovia SE-438, popularmente conhecida como rodovia Santa Clara, no munic\u00edpio de Capela. Com investimento total de mais de R$ 6 milh\u00f5es, o projeto de revitaliza\u00e7\u00e3o \u00e9 abrangente e inclui a constru\u00e7\u00e3o de uma ponte. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,7],"tags":[],"class_list":["post-5985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5985"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5985\/revisions"}],"predecessor-version":[{"id":5987,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5985\/revisions\/5987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/5986"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}