{"id":7852,"date":"2025-05-19T15:17:02","date_gmt":"2025-05-19T18:17:02","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=7852"},"modified":"2025-05-19T15:17:04","modified_gmt":"2025-05-19T18:17:04","slug":"inscricoes-abertas-pss-da-educacao-de-socorro-oferece-mais-de-150-vagas","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/19\/inscricoes-abertas-pss-da-educacao-de-socorro-oferece-mais-de-150-vagas\/","title":{"rendered":"Inscri\u00e7\u00f5es abertas: PSS da Educa\u00e7\u00e3o de Socorro oferece mais de 150 vagas"},"content":{"rendered":"\n<p>Interessados t\u00eam at\u00e9 o dia 26 de maio para realizar a inscri\u00e7\u00e3o<\/p>\n\n\n\n<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado (PSS) para profissionais da Educa\u00e7\u00e3o, realizado pela Prefeitura de Nossa Senhora do Socorro, por meio da Secretaria Municipal da Administra\u00e7\u00e3o (Semad) e da Secretaria Municipal da Educa\u00e7\u00e3o (Semed). Conforme estabelecido no edital, as inscri\u00e7\u00f5es v\u00e3o desta segunda-feira, 19, at\u00e9 o dia 26 de maio, e devem ser feitas atrav\u00e9s do site da Semed.<\/p>\n\n\n\n<p>Ao total, s\u00e3o mais de 150 vagas dispon\u00edveis, distribu\u00eddas entre professores substitutos, assistente administrativo, psic\u00f3logo, assistente social, assistente cuidador e auxiliar t\u00e9cnico em educa\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>As vagas s\u00e3o para contrata\u00e7\u00e3o imediata e cadastro reserva, para atua\u00e7\u00e3o na Semed e nas unidades da rede municipal de Socorro. A remunera\u00e7\u00e3o varia entre R$ 1.518,00 e R$ 4.867,77, a depender do cargo.<\/p>\n\n\n\n<p>De acordo com o edital, o PSS contar\u00e1 com uma \u00fanica fase, que compreende a avalia\u00e7\u00e3o documental, curricular de t\u00edtulos e experi\u00eancias profissionais apresentados pelos candidatos, e pericial, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio. A data prevista para a homologa\u00e7\u00e3o do resultado final \u00e9 18 de junho, segundo o cronograma.<\/p>\n\n\n\n<p>Foto: Juracy Feitosa<\/p>\n\n\n\n<p>Fonte: Assessoria de comunica\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interessados t\u00eam at\u00e9 o dia 26 de maio para realizar a inscri\u00e7\u00e3o Est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado (PSS) para profissionais da Educa\u00e7\u00e3o, realizado pela Prefeitura de Nossa Senhora do Socorro, por meio da Secretaria Municipal da Administra\u00e7\u00e3o (Semad) e da Secretaria Municipal da Educa\u00e7\u00e3o (Semed). Conforme estabelecido no edital, as inscri\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,6,7],"tags":[],"class_list":["post-7852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7852"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7852\/revisions"}],"predecessor-version":[{"id":7854,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7852\/revisions\/7854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/7853"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}