{"id":7887,"date":"2025-05-20T04:30:00","date_gmt":"2025-05-20T07:30:00","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=7887"},"modified":"2025-05-20T04:30:01","modified_gmt":"2025-05-20T07:30:01","slug":"prefeitura-de-aracaju-levara-varios-servicos-ao-santos-dumont-por-meio-do-giro-fundat","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/20\/prefeitura-de-aracaju-levara-varios-servicos-ao-santos-dumont-por-meio-do-giro-fundat\/","title":{"rendered":"Prefeitura de Aracaju levar\u00e1 v\u00e1rios servi\u00e7os ao Santos Dumont por meio do Giro Fundat"},"content":{"rendered":"\n<p>A Prefeitura de Aracaju, por interm\u00e9dio da Funda\u00e7\u00e3o Municipal de Forma\u00e7\u00e3o para o Trabalho (Fundat), promover\u00e1, no dia 24 de maio, a 4\u00aa edi\u00e7\u00e3o do Giro Fundat. O evento, que tem o objetivo de fomentar o cuidado, a inclus\u00e3o e qualifica\u00e7\u00e3o social, levar\u00e1 diversos servi\u00e7os e atividades gratuitas \u00e0 popula\u00e7\u00e3o do bairro Santos Dumont.<\/p>\n\n\n\n<p>O 4\u00aa Giro Fundat ocorrer\u00e1 das 8h ao meio-dia, na Unidade de Qualifica\u00e7\u00e3o Profissional (UQP) da Rua Sargento Brasiliano, e contar\u00e1 com atendimentos para qualifica\u00e7\u00e3o, cadastro de curr\u00edculo para vagas de emprego, cadastro de empresas para capta\u00e7\u00e3o de m\u00e3o de obra, atendimento ao microempreendedor individual &#8211; MEI, emiss\u00e3o da Carteira de Identidade Nacional (CIN) e muito mais.<\/p>\n\n\n\n<p>Em sua nova edi\u00e7\u00e3o, o Giro Fundat avan\u00e7a com os servi\u00e7os ofertados \u00e0 popula\u00e7\u00e3o e promove uma programa\u00e7\u00e3o diversificada.<\/p>\n\n\n\n<p>Dentre os demais servi\u00e7os, est\u00e3o:<\/p>\n\n\n\n<p>&#8211; Roda de conversa jur\u00eddica<\/p>\n\n\n\n<p>&#8211; Orienta\u00e7\u00e3o Crediamigo<\/p>\n\n\n\n<p>&#8211; PROCON<\/p>\n\n\n\n<p>&#8211; Orienta\u00e7\u00e3o Nutricional<\/p>\n\n\n\n<p>&#8211; Teste r\u00e1pido para HIV, S\u00edfilis e Hepatite B e C<\/p>\n\n\n\n<p>&#8211; Atendimento em sa\u00fade bucal e orienta\u00e7\u00f5es preventivas<\/p>\n\n\n\n<p>&#8211; Atendimento veterin\u00e1rio com vacina antirr\u00e1bica<\/p>\n\n\n\n<p>A 4\u00aa edi\u00e7\u00e3o do Giro Fundat refor\u00e7a o compromisso da Prefeitura e da Funda\u00e7\u00e3o com a promo\u00e7\u00e3o do bem-estar, ampliando o acesso a servi\u00e7os essenciais para a popula\u00e7\u00e3o. N\u00e3o perca essa oportunidade e participe!<\/p>\n\n\n\n<p>Ascom Fundat<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Aracaju, por interm\u00e9dio da Funda\u00e7\u00e3o Municipal de Forma\u00e7\u00e3o para o Trabalho (Fundat), promover\u00e1, no dia 24 de maio, a 4\u00aa edi\u00e7\u00e3o do Giro Fundat. O evento, que tem o objetivo de fomentar o cuidado, a inclus\u00e3o e qualifica\u00e7\u00e3o social, levar\u00e1 diversos servi\u00e7os e atividades gratuitas \u00e0 popula\u00e7\u00e3o do bairro Santos Dumont. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,10],"tags":[],"class_list":["post-7887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7887"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7887\/revisions"}],"predecessor-version":[{"id":7889,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7887\/revisions\/7889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/7888"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}