{"id":7893,"date":"2025-05-20T05:06:07","date_gmt":"2025-05-20T08:06:07","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=7893"},"modified":"2025-05-20T05:06:08","modified_gmt":"2025-05-20T08:06:08","slug":"alese-realiza-palestra-sobre-procedimentos-iniciais-em-ocorrencia-com-artefatos","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/20\/alese-realiza-palestra-sobre-procedimentos-iniciais-em-ocorrencia-com-artefatos\/","title":{"rendered":"Alese realiza palestra sobre \u2018Procedimentos Iniciais em Ocorr\u00eancia com Artefatos"},"content":{"rendered":"\n<p>Na manh\u00e3 desta segunda-feira (19), a Assembleia Legislativa de Sergipe (Alese) realizou uma palestra com o tema \u2018Procedimentos Iniciais em Ocorr\u00eancia com Artefatos Explosivos\u2019. A palestra aconteceu por meio do Gabinete de Seguran\u00e7a Institucional da Casa.<\/p>\n\n\n\n<p>Diante do aumento de ocorr\u00eancias envolvendo artefatos explosivos em \u00e1reas urbanas e rurais, \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica t\u00eam intensificado os procedimentos iniciais para garantir a prote\u00e7\u00e3o da popula\u00e7\u00e3o e das equipes envolvidas. A abordagem em situa\u00e7\u00f5es desse tipo exige extrema cautela, envolvendo isolamento imediato da \u00e1rea, acionamento do esquadr\u00e3o antibombas e rigorosa avalia\u00e7\u00e3o t\u00e9cnica antes de qualquer interven\u00e7\u00e3o.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2024-08-30-as-10.02.31_1ad1e471-e1725024587311-283x300.jpg\" srcset=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2024-08-30-as-10.02.31_1ad1e471-e1725024587311-283x300.jpg 283w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/Imagem-do-WhatsApp-de-2024-08-30-as-10.02.31_1ad1e471-e1725024587311.jpg 662w\" alt=\"\" width=\"283\" height=\"300\"><\/p>\n\n\n\n<p id=\"caption-attachment-167101\">Tenente-Coronel Jonatas<\/p>\n\n\n\n<p>O tenente-coronel Jonatas, comandante do Gabinete de Seguran\u00e7a Institucional da Assembleia Legislativa de Sergipe (GSI\/Alese), destacou a import\u00e2ncia da qualifica\u00e7\u00e3o t\u00e9cnica dos militares que integram sua equipe por meio de um programa cont\u00ednuo de capacita\u00e7\u00e3o. \u201cEsse projeto \u00e9 voltado para os policiais e bombeiros militares que integram o GSI e faz parte de um programa de capacita\u00e7\u00e3o t\u00e9cnica continuada, onde trazemos profissionais com expertise relevante para enriquecer o conhecimento da equipe. Hoje, de forma especial, contamos com a presen\u00e7a do comandante do BOPE, Major Weniston, que trouxe uma abordagem essencial sobre procedimentos iniciais em ocorr\u00eancias com artefatos explosivos \u2014 uma tem\u00e1tica sens\u00edvel e imprescind\u00edvel para o contexto da Alese, que frequentemente recebe autoridades como o vice-presidente da Rep\u00fablica e governadores. Nosso objetivo \u00e9 preparar ainda mais nossos agentes para garantir a seguran\u00e7a institucional com efici\u00eancia e conhecimento t\u00e9cnico.\u201d<\/p>\n\n\n\n<p>O primeiro passo nesses casos \u00e9 assegurar o afastamento de civis e a preserva\u00e7\u00e3o do per\u00edmetro, respeitando uma dist\u00e2ncia segura que varia conforme o tipo de artefato identificado. Equipes especializadas s\u00e3o respons\u00e1veis por analisar visualmente o objeto suspeito, utilizando equipamentos como rob\u00f4s, detectores e c\u00e2meras remotas para minimizar o risco de detona\u00e7\u00e3o acidental. Nenhum contato f\u00edsico \u00e9 permitido at\u00e9 que o artefato seja classificado como seguro ou devidamente neutralizado.<\/p>\n\n\n\n<p>A atua\u00e7\u00e3o coordenada entre Pol\u00edcia Militar, Corpo de Bombeiros, Defesa Civil e, quando necess\u00e1rio, Ex\u00e9rcito Brasileiro, \u00e9 essencial para o sucesso da opera\u00e7\u00e3o. Al\u00e9m disso, treinamentos cont\u00ednuos e campanhas de orienta\u00e7\u00e3o \u00e0 popula\u00e7\u00e3o sobre como agir diante de objetos suspeitos t\u00eam sido refor\u00e7ados, buscando reduzir riscos e agilizar as respostas em casos reais. A efici\u00eancia nos primeiros procedimentos pode ser decisiva para evitar trag\u00e9dias e garantir a seguran\u00e7a coletiva.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.34-AM-1-300x200.jpeg\" srcset=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.34-AM-1-300x200.jpeg 300w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.34-AM-1-1024x682.jpeg 1024w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.34-AM-1-768x512.jpeg 768w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.34-AM-1.jpeg 1280w\" alt=\"\" width=\"300\" height=\"200\"><\/p>\n\n\n\n<p id=\"caption-attachment-167094\">Major Weniston<\/p>\n\n\n\n<p>O palestrante Major Weniston destacou a import\u00e2ncia da capacita\u00e7\u00e3o sobre ocorr\u00eancias com artefatos explosivos, enfatizando a relev\u00e2ncia do tema para a seguran\u00e7a p\u00fablica. \u201cEssa iniciativa \u00e9 extremamente importante porque trata de um tema sens\u00edvel e recorrente no nosso estado. Estamos falando de procedimentos iniciais em ocorr\u00eancias envolvendo artefatos explosivos. No ano passado, infelizmente, tivemos a morte de uma crian\u00e7a por causa de uma bomba caseira, e este ano j\u00e1 houve novas apreens\u00f5es. \u00c9 uma situa\u00e7\u00e3o que oferece risco real \u00e0 popula\u00e7\u00e3o e exige preparo. Essa instru\u00e7\u00e3o \u00e9 um primeiro passo para orientar sobre como agir at\u00e9 a chegada do Batalh\u00e3o de Opera\u00e7\u00f5es Especiais, que conta com t\u00e9cnicos especializados. Embora o per\u00edodo junino aumente o acesso a explosivos, esse \u00e9 um tema que exige aten\u00e7\u00e3o durante todo o ano.\u201d<\/p>\n\n\n\n<p>O Major Reis que participou da capacita\u00e7\u00e3o destacou a relev\u00e2ncia da iniciativa de capacita\u00e7\u00e3o promovida pelo Gabinete de Seguran\u00e7a Institucional da Alese, ressaltando seu impacto direto na prepara\u00e7\u00e3o dos profissionais da seguran\u00e7a.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.46-AM-300x200.jpeg\" srcset=\"https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.46-AM-300x200.jpeg 300w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.46-AM-1024x682.jpeg 1024w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.46-AM-768x512.jpeg 768w, https:\/\/al.se.leg.br\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-19-at-11.07.46-AM.jpeg 1280w\" alt=\"\" width=\"300\" height=\"200\"><\/p>\n\n\n\n<p id=\"caption-attachment-167093\">Major Reis<\/p>\n\n\n\n<p>\u201cParabenizo o presidente da Casa, Jeferson Andrade (PSD) e o coronel Jonatas por essa iniciativa de trazer pessoas capacitadas para nos instruir. Essa capacita\u00e7\u00e3o \u00e9 fundamental para que nossos policiais tenham, ao menos, uma no\u00e7\u00e3o de como agir em situa\u00e7\u00f5es delicadas, como ocorr\u00eancias com artefatos explosivos.\u201d<\/p>\n\n\n\n<p>Por D\u00e9bora Nepomuceno Marques &#8211; Foto: Jadilson Sim\u00f5es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (19), a Assembleia Legislativa de Sergipe (Alese) realizou uma palestra com o tema \u2018Procedimentos Iniciais em Ocorr\u00eancia com Artefatos Explosivos\u2019. A palestra aconteceu por meio do Gabinete de Seguran\u00e7a Institucional da Casa. Diante do aumento de ocorr\u00eancias envolvendo artefatos explosivos em \u00e1reas urbanas e rurais, \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica t\u00eam intensificado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,2],"tags":[],"class_list":["post-7893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7893"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7893\/revisions"}],"predecessor-version":[{"id":7895,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7893\/revisions\/7895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/7894"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}