{"id":8897,"date":"2025-05-28T06:02:06","date_gmt":"2025-05-28T09:02:06","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=8897"},"modified":"2025-05-28T06:02:07","modified_gmt":"2025-05-28T09:02:07","slug":"sindmuse-conquista-vitoria-sanfoneiros-vao-tocar-no-sao-joao-de-aracaju","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/28\/sindmuse-conquista-vitoria-sanfoneiros-vao-tocar-no-sao-joao-de-aracaju\/","title":{"rendered":"SINDMUSE conquista vit\u00f3ria: sanfoneiros v\u00e3o tocar no S\u00e3o Jo\u00e3o de Aracaju"},"content":{"rendered":"\n<p>Nesta quarta-feira, dia 28 de maio, \u00e0s 10hs da manh\u00e3, a dire\u00e7\u00e3o do Forr\u00f3 Caju vai se reunir com a prefeita Em\u00edlia Corr\u00eaa para definir como ser\u00e1 a participa\u00e7\u00e3o dos sanfoneiros na programa\u00e7\u00e3o de S\u00e3o Jo\u00e3o de Aracaju.<\/p>\n\n\n\n<p>A audi\u00eancia marcada \u00e9 vit\u00f3ria da luta dos sanfoneiros e do SINDMUSE (Sindicato dos M\u00fasicos de Sergipe) que realizaram protesto na C\u00e2mara de Vereadores de Aracaju na manh\u00e3 desta ter\u00e7a-feira, dia 27\/5, contra a exclus\u00e3o de m\u00fasicos de Aracaju da programa\u00e7\u00e3o do Forr\u00f3 Caju 2025. A Central \u00danica dos Trabalhadores (CUT\/SE) participou da manifesta\u00e7\u00e3o representada pelo diretor Jo\u00e3o Fonseca.<\/p>\n\n\n\n<p>Al\u00e9m dos protestos ao longo da semana, foram v\u00e1rias as entrevistas concedidas na m\u00eddia sergipana para expor a situa\u00e7\u00e3o dos sanfoneiros de Aracaju que passam o ano esperando o S\u00e3o Jo\u00e3o e n\u00e3o est\u00e3o na programa\u00e7\u00e3o do Forr\u00f3 Caju 2025.<\/p>\n\n\n\n<p>A exclus\u00e3o na programa\u00e7\u00e3o do Forr\u00f3 Caju 2025 foi o tema do di\u00e1logo travado por trabalhadores da m\u00fasica, sanfoneiros e dirigentes sindicais do SINDMUSE com vereadores e vereadoras de Aracaju nesta ter\u00e7a-feira, dia 27 de maio.<\/p>\n\n\n\n<p>O sanfoneiro Juraci Cardoso Sousa que tem mais de 15 anos de Forr\u00f3 Caju revelou que \u00e9 a primeira vez que fica fora da programa\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp;\u201cEstamos brigando para que os vereadores entendam e a prefeita reveja sua atitude e nos coloque pra tocar num bairro. Os trios P\u00e9 de Serra est\u00e3o sendo desvalorizados na nossa casa. Essa atitude de incluir os sanfoneiros vai ser boa para a economia da nossa Aracaju, para que o dinheiro circule aqui\u201d, declarou Juraci.<\/p>\n\n\n\n<p>Por interm\u00e9dio da vereadora S\u00f4nia Meire (Psol), os sanfoneiros e o SINDMUSE chegaram a ser recebidos por Ricardo Vasconselos, presidente da C\u00e2mara de Aracaju, que viabilizou o di\u00e1logo com o presidente da Funcaju.<\/p>\n\n\n\n<p>\u201cSa\u00edmos aqui da C\u00e2mara com a garantia de que os sanfoneiros e m\u00fasicos de Aracaju v\u00e3o tocar no S\u00e3o Jo\u00e3o. Amanh\u00e3 o di\u00e1logo da prefeita com a dire\u00e7\u00e3o do Forr\u00f3 Caju ser\u00e1 para encontrar a melhor forma de inserir os m\u00fasicos na programa\u00e7\u00e3o. Foi uma jornada cansativa de luta, mas estamos satisfeitos com o resultado. S\u00f3 a luta alcan\u00e7a vit\u00f3rias. Digo para todos os m\u00fasicos de Sergipe que venham para a luta e venham construir o SINDMUSE com a gente porque \u00e9 atrav\u00e9s da uni\u00e3o que podemos mostrar o nosso valor art\u00edstico e profissional\u201d, declarou Tonico Saraiva, presidente do SINDMUSE.<\/p>\n\n\n\n<p>Texto e foto Iracema Corso<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, dia 28 de maio, \u00e0s 10hs da manh\u00e3, a dire\u00e7\u00e3o do Forr\u00f3 Caju vai se reunir com a prefeita Em\u00edlia Corr\u00eaa para definir como ser\u00e1 a participa\u00e7\u00e3o dos sanfoneiros na programa\u00e7\u00e3o de S\u00e3o Jo\u00e3o de Aracaju. A audi\u00eancia marcada \u00e9 vit\u00f3ria da luta dos sanfoneiros e do SINDMUSE (Sindicato dos M\u00fasicos de Sergipe) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[],"class_list":["post-8897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8897"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8897\/revisions"}],"predecessor-version":[{"id":8899,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8897\/revisions\/8899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/8898"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}