{"id":9003,"date":"2025-05-28T15:45:32","date_gmt":"2025-05-28T18:45:32","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9003"},"modified":"2025-05-28T15:45:32","modified_gmt":"2025-05-28T18:45:32","slug":"mpf-acompanha-politicas-publicas-para-reducao-da-mortalidade-materna-e-neonatal-no-estado-de-sergipe","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/28\/mpf-acompanha-politicas-publicas-para-reducao-da-mortalidade-materna-e-neonatal-no-estado-de-sergipe\/","title":{"rendered":"MPF acompanha pol\u00edticas p\u00fablicas para redu\u00e7\u00e3o da mortalidade materna e neonatal no estado de Sergipe"},"content":{"rendered":"\n<p>O Minist\u00e9rio P\u00fablico Federal em Sergipe acompanha desde 2023 as pol\u00edticas p\u00fablicas para a redu\u00e7\u00e3o dos \u00edndices de mortalidade materna e neonatal em Sergipe. \u201cNesse per\u00edodo, em \u00e2mbito estadual, acompanhamos as atividades do Comit\u00ea Estadual de Preven\u00e7\u00e3o da Mortalidade Materna, Infantil e Fetal e provocamos a retomada do Comit\u00ea em \u00e2mbito municipal\u201d, explica o procurador da Rep\u00fablica \u00cdgor Miranda.<\/p>\n\n\n\n<p>Segundo o procurador, o Comit\u00ea Municipal retoma as reuni\u00f5es peri\u00f3dicas nesta quinta-feira, 29\/05, para debate t\u00e9cnico de casos concretos, com o respeito ao sigilo dos dados pessoais dos pacientes.<\/p>\n\n\n\n<p>\u201cNeste Dia Mundial de Luta pela Sa\u00fade das Mulheres e de Preven\u00e7\u00e3o da Mortalidade Materna, 28 de maio, temos muito a refletir. N\u00e3o basta diminuir a mortalidade materna. \u00c9 preciso que tenhamos uma experi\u00eancia positiva de pr\u00e9 e p\u00f3s gesta\u00e7\u00e3o, bem como, de nascimento em Sergipe\u201d, conclui \u00cdgor Miranda.<\/p>\n\n\n\n<p>Cremese &#8211; Para avaliar as poss\u00edveis causas evit\u00e1veis e refletir propostas de melhorias na pol\u00edtica de sa\u00fade, o MPF est\u00e1 contando com apoio t\u00e9cnico do Conselho Regional de Medicina de Sergipe (Cremese).<\/p>\n\n\n\n<p>Inspe\u00e7\u00e3o &#8211; Em novembro de 2024, o MPF e o Cremese realizaram inspe\u00e7\u00e3o na Maternidade Nossa Senhora de Lourdes, em Aracaju (SE), como parte da investiga\u00e7\u00e3o sobre o aumento de 19,5% da mortalidade infantil no estado, registrado em 2023. Leia mais sobre a inspe\u00e7\u00e3o aqui.<\/p>\n\n\n\n<p>Assessoria de Comunica\u00e7\u00e3o &#8211; Imagem: Canva<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Federal em Sergipe acompanha desde 2023 as pol\u00edticas p\u00fablicas para a redu\u00e7\u00e3o dos \u00edndices de mortalidade materna e neonatal em Sergipe. \u201cNesse per\u00edodo, em \u00e2mbito estadual, acompanhamos as atividades do Comit\u00ea Estadual de Preven\u00e7\u00e3o da Mortalidade Materna, Infantil e Fetal e provocamos a retomada do Comit\u00ea em \u00e2mbito municipal\u201d, explica o procurador [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,8],"tags":[],"class_list":["post-9003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-saude"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9003"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9003\/revisions"}],"predecessor-version":[{"id":9005,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9003\/revisions\/9005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9004"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}