{"id":9204,"date":"2025-05-30T06:57:49","date_gmt":"2025-05-30T09:57:49","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9204"},"modified":"2025-05-30T06:57:50","modified_gmt":"2025-05-30T09:57:50","slug":"projeto-babybel-leva-atendimento-adulto-e-pediatrico-ao-instituto-joanna-de-angelis-em-sua-3a-edicao","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/30\/projeto-babybel-leva-atendimento-adulto-e-pediatrico-ao-instituto-joanna-de-angelis-em-sua-3a-edicao\/","title":{"rendered":"Projeto Babybel leva atendimento adulto e pedi\u00e1trico ao Instituto Joanna de \u00c2ngelis, em sua 3\u00aa edi\u00e7\u00e3o"},"content":{"rendered":"\n<p>Nesta quarta-feira, 28, o Hospital e Maternidade Santa Isabel realizou a 3\u00aa edi\u00e7\u00e3o do projeto Babybel, uma a\u00e7\u00e3o social voltada ao cuidado e acolhimento de crian\u00e7as e adultos em situa\u00e7\u00e3o de vulnerabilidade. A iniciativa ocorreu no Instituto Joanna de \u00c2ngelis, localizado no bairro Santa Maria, em Aracaju, e ofereceu uma programa\u00e7\u00e3o especial com atendimentos m\u00e9dicos pedi\u00e1tricos e adultos, atividades l\u00fadicas e distribui\u00e7\u00e3o de brinquedos.<\/p>\n\n\n\n<p>Seis m\u00e9dicas participaram da a\u00e7\u00e3o, oferecendo atendimentos nas \u00e1reas de pediatria e cl\u00ednica m\u00e9dica. A equipe tamb\u00e9m contou com profissionais de nutri\u00e7\u00e3o, odontologia e enfermagem. A manh\u00e3 foi marcada por triagens nutricionais, a\u00e7\u00e3o educativa de sa\u00fade bucal com abordagem l\u00fadica, lanches preparados pela equipe de nutri\u00e7\u00e3o e brincadeiras com pinturas organizadas pela equipe de enfermagem.<\/p>\n\n\n\n<p>As crian\u00e7as se divertiram com a animada presen\u00e7a da mascote do Hospital, Maria, e do famoso personagem Chase, da Patrulha Canina, que garantiram muitos sorrisos. A solidariedade tamb\u00e9m esteve presente com a doa\u00e7\u00e3o de brinquedos realizada por alunos do Centro de Estudos do Hospital, distribu\u00eddos para as crian\u00e7as atendidas no local.<\/p>\n\n\n\n<p>A diretora t\u00e9cnica do HMSI, Dra. Bianca Xavier, que tamb\u00e9m \u00e9 pediatra e esteve presente na a\u00e7\u00e3o, destacou a import\u00e2ncia do projeto para ampliar o acesso \u00e0 sa\u00fade de qualidade:<\/p>\n\n\n\n<p>&#8220;Trouxemos o nosso projeto Babybel, que \u00e9 um projeto que vem circulando as comunidades de Aracaju levando sa\u00fade, levando a equipe multidisciplinar do Hospital Maternidade Santa Isabel com atendimento de pediatria. Hoje n\u00f3s trouxemos cl\u00ednica m\u00e9dica, nutri\u00e7\u00e3o, odontologia, enfermagem&#8230; ent\u00e3o tudo pra facilitar o acesso da comunidade \u00e0 sa\u00fade de qualidade a esse instituto de grande relev\u00e2ncia, que acolhe crian\u00e7as em vulnerabilidade e que, com a equipe dele, consegue dar amor, dar carinho, dar cuidado, e a gente veio ajudar um pouquinho a amenizar esse sofrimento.&#8221;<\/p>\n\n\n\n<p>O presidente do Instituto Joanna de \u00c2ngelis, Alexandre Conrado, tamb\u00e9m expressou sua gratid\u00e3o pela iniciativa: &#8220;Voc\u00eas trouxeram cuidado, voc\u00eas trouxeram carinho, voc\u00eas trouxeram aconchego junto de todo o profissionalismo que envolveu essa a\u00e7\u00e3o. Eu quero parabenizar o Hospital Santa Isabel, eu quero agradecer do fundo do cora\u00e7\u00e3o essa a\u00e7\u00e3o do projeto Babybel do Hospital Santa Isabel. Memorize esse nome, porque isso \u00e9 muito importante. \u00c9 o hospital indo \u00e0 comunidade, conhecendo e ouvindo os seus pacientes de uma maneira muito positiva.&#8221;<\/p>\n\n\n\n<p>Com o projeto Babybel, o Hospital e Maternidade Santa Isabel refor\u00e7a seu compromisso com a sa\u00fade, a solidariedade e o bem-estar social, levando atendimento humanizado e acolhimento a quem mais precisa.<\/p>\n\n\n\n<p>Texto e foto Marielle Rocha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, 28, o Hospital e Maternidade Santa Isabel realizou a 3\u00aa edi\u00e7\u00e3o do projeto Babybel, uma a\u00e7\u00e3o social voltada ao cuidado e acolhimento de crian\u00e7as e adultos em situa\u00e7\u00e3o de vulnerabilidade. A iniciativa ocorreu no Instituto Joanna de \u00c2ngelis, localizado no bairro Santa Maria, em Aracaju, e ofereceu uma programa\u00e7\u00e3o especial com atendimentos m\u00e9dicos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-9204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9204"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9204\/revisions"}],"predecessor-version":[{"id":9206,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9204\/revisions\/9206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9205"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}