{"id":9229,"date":"2025-05-30T10:00:55","date_gmt":"2025-05-30T13:00:55","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9229"},"modified":"2025-05-30T10:00:56","modified_gmt":"2025-05-30T13:00:56","slug":"fundat-confira-as-vagas-de-emprego-disponiveis-nesta-sexta-feira-em-aracaju-4","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/30\/fundat-confira-as-vagas-de-emprego-disponiveis-nesta-sexta-feira-em-aracaju-4\/","title":{"rendered":"Fundat: Confira as vagas de emprego dispon\u00edveis nesta sexta-feira em Aracaju"},"content":{"rendered":"\n<p>A Funda\u00e7\u00e3o Municipal de Forma\u00e7\u00e3o para o Trabalho (Fundat) divulga novas vagas de emprego que ser\u00e3o disponibilizadas nesta sexta-feira (30) para a popula\u00e7\u00e3o aracajuana.<\/p>\n\n\n\n<p>Os interessados em candidatar-se \u00e0s vagas precisam se cadastrar ou atualizar o curr\u00edculo na sede da Fundat, localizada no cal\u00e7ad\u00e3o da rua Jo\u00e3o Pessoa, 127, Centro, portando carteira de trabalho, RG, CPF e curr\u00edculo.<\/p>\n\n\n\n<p>O hor\u00e1rio de funcionamento do \u00f3rg\u00e3o \u00e9 de segunda a sexta-feira, das 7h \u00e0s 17h.<\/p>\n\n\n\n<p>VAGAS PARA AMPLA CONCORR\u00caNCIA:<\/p>\n\n\n\n<p>AUXILIAR DE DEP\u00d3SITO<\/p>\n\n\n\n<p>Ensino M\u00e9dio Completo<\/p>\n\n\n\n<p>Com experi\u00eancia comprovada em CTPS<\/p>\n\n\n\n<p>Empresa localizada no bairro Centro<\/p>\n\n\n\n<p>A\u00c7OUGUEIRO<\/p>\n\n\n\n<p>N\u00e3o Alfabetizado<\/p>\n\n\n\n<p>Com experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Empresa localizada no bairro Atalaia<\/p>\n\n\n\n<p>VENDEDOR<\/p>\n\n\n\n<p>Ensino M\u00e9dio Completo<\/p>\n\n\n\n<p>Com de experi\u00eancia comprovada em CTPS<\/p>\n\n\n\n<p>Ambos os sexos<\/p>\n\n\n\n<p>Idade m\u00ednima 22 anos<\/p>\n\n\n\n<p>Empresa localizada no bairro Centro<\/p>\n\n\n\n<p>AUXILIAR DE VENDAS<\/p>\n\n\n\n<p>Alfabetizado<\/p>\n\n\n\n<p>Com experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Possuir CNH B<\/p>\n\n\n\n<p>Empresa localizada no bairro Get\u00falio Vargas<\/p>\n\n\n\n<p>MARKETING DIGITAL<\/p>\n\n\n\n<p>Ensino M\u00e9dio Completo<\/p>\n\n\n\n<p>Com experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Possuir CNH B<\/p>\n\n\n\n<p>Empresa localizada no bairro Get\u00falio Vargas<\/p>\n\n\n\n<p>POLIDOR DE AUTOM\u00d3VEIS<\/p>\n\n\n\n<p>N\u00e3o Alfabetizado<\/p>\n\n\n\n<p>Com experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Empresa localizada no bairro Get\u00falio Vargas<\/p>\n\n\n\n<p>MOTO BOY<\/p>\n\n\n\n<p>N\u00e3o Alfabetizado<\/p>\n\n\n\n<p>Sem experi\u00eancia<\/p>\n\n\n\n<p>Vaga afirmativa para mulheres<\/p>\n\n\n\n<p>Empresa localizada no bairro Santa Maria<\/p>\n\n\n\n<p>PROFESSOR DE DESIGN GR\u00c1FICO<\/p>\n\n\n\n<p>Ensino Superior Cursando<\/p>\n\n\n\n<p>Sem experi\u00eancia<\/p>\n\n\n\n<p>Ambos os sexos<\/p>\n\n\n\n<p>Empresa localizada no bairro Centro<\/p>\n\n\n\n<p>PROFESSOR DE LIBRAS<\/p>\n\n\n\n<p>Ensino Superior Cursando<\/p>\n\n\n\n<p>Com experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Ambos os sexos<\/p>\n\n\n\n<p>Empresa localizada no bairro Centro<\/p>\n\n\n\n<p>CONTROLADOR DE TR\u00c1FEGO I<\/p>\n\n\n\n<p>Ensino M\u00e9dio Completo<\/p>\n\n\n\n<p>Com 6 meses experi\u00eancia sem comprova\u00e7\u00e3o em CTPS<\/p>\n\n\n\n<p>Ambos os sexos<\/p>\n\n\n\n<p>Empresa localizada no bairro Ponto Novo<\/p>\n\n\n\n<p>VAGAS PARA PCD (Pessoa Com Defici\u00eancia):<\/p>\n\n\n\n<p>AUXILIAR ADMINISTRATIVO<\/p>\n\n\n\n<p>Ensino M\u00e9dio Completo<\/p>\n\n\n\n<p>Sem experi\u00eancia<\/p>\n\n\n\n<p>Ambos os sexos<\/p>\n\n\n\n<p>Empresa localizada no bairro S\u00e3o Jos\u00e9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Funda\u00e7\u00e3o Municipal de Forma\u00e7\u00e3o para o Trabalho (Fundat) divulga novas vagas de emprego que ser\u00e3o disponibilizadas nesta sexta-feira (30) para a popula\u00e7\u00e3o aracajuana. Os interessados em candidatar-se \u00e0s vagas precisam se cadastrar ou atualizar o curr\u00edculo na sede da Fundat, localizada no cal\u00e7ad\u00e3o da rua Jo\u00e3o Pessoa, 127, Centro, portando carteira de trabalho, RG, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6,10],"tags":[],"class_list":["post-9229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letreiro","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9229"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9229\/revisions"}],"predecessor-version":[{"id":9231,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9229\/revisions\/9231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9230"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}