{"id":9299,"date":"2025-05-30T16:18:17","date_gmt":"2025-05-30T19:18:17","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9299"},"modified":"2025-05-30T16:18:17","modified_gmt":"2025-05-30T19:18:17","slug":"ivan-leite-recebe-preito-de-gratidao-rotaria-do-distrito-4391-de-aracaju","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/30\/ivan-leite-recebe-preito-de-gratidao-rotaria-do-distrito-4391-de-aracaju\/","title":{"rendered":"Ivan Leite recebe Preito de Gratid\u00e3o Rot\u00e1ria do Distrito 4391 de Aracaju"},"content":{"rendered":"\n<p>Na noite do \u00faltimo dia 29 deste m\u00eas, o ex-prefeito e ex-deputado, Ivan Leite, esteve recebendo justa homenagem do Rotary Club de Aracaju, Distrito 4391, durante a 6\u00aa Conferencia Distrital Aracaju, que destaca como tema \u201cA Magia do Rotary\u201d, prosseguir\u00e1 at\u00e9 o dia 1\u00ba de junho, no Centro de Conven\u00e7\u00f5es AM Malls Sergipe.<\/p>\n\n\n\n<p>O Rotary Club de Aracaju, Distrito 4391, \u00e9 dirigido pelo rotariano Jorge Carvalho do Nascimento, atual Governar do referido Distrito, que funciona na capital sergipana h\u00e1 91 anos.<\/p>\n\n\n\n<p>O rotariano e empres\u00e1rio de Est\u00e2ncia, Ivan Leite (que \u00e9 fundador do Rotary Club de Est\u00e2ncia, que no dia 27 do corrente completou 40 anos de atividade), recebeu das m\u00e3os do senhor Jorge Carvalho, Governador do Distrito 4391 do Rotary International, o Diploma intitulado \u201cPreito de Gratid\u00e3o Rot\u00e1ria\u201d.<\/p>\n\n\n\n<p>O Diploma Preito de Gratid\u00e3o Rot\u00e1ria, apresenta os seguintes dizeres: \u201cconcedendo-lhe o Diploma do Preito de Gratid\u00e3o Rot\u00e1ria, em reconhecimento aos bons servi\u00e7os prestados como fundador, doador e colaborador ativo das atividades do Rotary Club de Est\u00e2ncia\u201d.<\/p>\n\n\n\n<p>Rotary Club<\/p>\n\n\n\n<p>O Rotary Club \u00e9 um clube de servi\u00e7os fundado nos EUA e presente em todo o mundo. Ao&nbsp;&nbsp; mesmo tempo que \u00e9 uma organiza\u00e7\u00e3o internacional voltada para compreens\u00e3o e conc\u00f3rdia universal, \u00e9 tamb\u00e9m um movimento de est\u00edmulo para a\u00e7\u00f5es comunit\u00e1rias e \u00e9ticas. O Club re\u00fane fam\u00edlias com afinidades e que compartilham momentos de companheirismo e de trabalho voltado para a comunidade.<\/p>\n\n\n\n<p>O Rotary tem como objetivo principal estimular e fomentar o ideal de servir como base de todo o empreendimento digno. Para tanto, o Club apoia e promove o desenvolvimento do companheirismo como elemento capaz de proporcionar oportunidades de servir e a melhoria da comunidade pela conduta exemplar na vida de cada rotariano.<\/p>\n\n\n\n<p>Rotary Club de Aracaju<\/p>\n\n\n\n<p>O Rotary Club de Aracaju, que est\u00e1 completando 91 anos, se reuniu pela primeira vez na noite de 4 de dezembro de 1934, no restaurante do Hotel Marozzi, quando 29 l\u00edderes da vida sergipana fundaram o clube, tendo como padrinho o Rotary Club da Bahia. Na reuni\u00e3o estavam presentes Moraes Sarmento, governador do Distrito 72 do Rotary International que inclu\u00eda, dentre outros, o territ\u00f3rio dos estados de Sergipe e Bahia.<\/p>\n\n\n\n<p>Lauro Borba, do Rotary Club do Recife, importante lideran\u00e7a do rotarismo brasileiro durante a primeira metade do s\u00e9culo XX, tamb\u00e9m compareceu. Jaime Tavares representou o Rotary Club da Bahia. O primeiro clube de Rotary a funcionar em Sergipe foi reconhecido pelo Rotary International no dia 11 de abril de 1935.<\/p>\n\n\n\n<p>O Rotary \u00e9 uma rede internacional de clubes com dedica\u00e7\u00e3o a presta\u00e7\u00e3o de servi\u00e7os com um grande n\u00famero de profissionais envolvidos. Em Aracaju, o clube tem 91 anos e foi fundado no dia 4 de dezembro de 1934.<\/p>\n\n\n\n<p>Fundado em 1905, o Rotary conta com mais de 1 milh\u00e3o de pessoas envolvidas nas a\u00e7\u00f5es, sendo divididas em 33 mil clubes, al\u00e9m dos distritos, totalizando 571 espalhados pelos pa\u00edses.<\/p>\n\n\n\n<p>\u00c9 bom lembrar que esse clube re\u00fane pessoas volunt\u00e1rias que contribuem com o que podem, querem e sabem fazer para ajudar o pr\u00f3ximo.<\/p>\n\n\n\n<p>Por Magno de Jesus<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite do \u00faltimo dia 29 deste m\u00eas, o ex-prefeito e ex-deputado, Ivan Leite, esteve recebendo justa homenagem do Rotary Club de Aracaju, Distrito 4391, durante a 6\u00aa Conferencia Distrital Aracaju, que destaca como tema \u201cA Magia do Rotary\u201d, prosseguir\u00e1 at\u00e9 o dia 1\u00ba de junho, no Centro de Conven\u00e7\u00f5es AM Malls Sergipe. O Rotary [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-9299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9299"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9299\/revisions"}],"predecessor-version":[{"id":9301,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9299\/revisions\/9301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9300"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}