{"id":9305,"date":"2025-05-30T16:44:06","date_gmt":"2025-05-30T19:44:06","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9305"},"modified":"2025-05-30T16:44:08","modified_gmt":"2025-05-30T19:44:08","slug":"programa-primeiro-emprego-do-governo-do-estado-realiza-aula-inaugural-para-mais-200-jovens-sergipanos","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/05\/30\/programa-primeiro-emprego-do-governo-do-estado-realiza-aula-inaugural-para-mais-200-jovens-sergipanos\/","title":{"rendered":"Programa Primeiro Emprego do governo do estado realiza aula inaugural para mais 200 jovens sergipanos"},"content":{"rendered":"\n<p>Mais 200 jovens sergipanos iniciam suas jornadas de aprendizado no Programa Primeiro Emprego (PPE). Nesta sexta-feira, 30, o Governo de Sergipe, por meio da Secretaria de Estado do Trabalho, Emprego e Empreendedorismo (Seteem), realizou aula inaugural de 17 diferentes cursos. A solenidade contou com a presen\u00e7a do governador do estado F\u00e1bio Mitidieri e de v\u00e1rias outras autoridades.<\/p>\n\n\n\n<p>Realizada durante a manh\u00e3, no audit\u00f3rio da biblioteca p\u00fablica Epiphanio D\u00f3ria, em Aracaju, a a\u00e7\u00e3o tamb\u00e9m acolheu e orientou os novos selecionados do programa, que capacita e direciona para a experi\u00eancia profissional pr\u00e1tica em diferentes empresas parceiras. Nestas novas turmas s\u00e3o elas: Hiper Carnes, Petrox, Grupo Tabajara, Rede Alpha, Brauna, Bombom, Agape Sistemas, Fasitec, Fasouto e os restaurantes Parati, Sal e Brasa e Maria Farinha. Os alunos se capacitar\u00e3o em \u00e1reas de A\u00e7ougueiro, Ajudante de Gar\u00e7om, Atendente de Loja, Auxiliar de Dep\u00f3sito, Barman, Cozinheiro, Cumin, Empacotador, Frentista, Gar\u00e7om, Marceneiro, Operador de Caixa, Pedreiro, Recepcionista, Repositor, Servi\u00e7os Gerais e Operador de Centro de Distribui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para J\u00falio Nascimento, de 20 anos, que vai fazer o curso de frentista, \u00e9 apenas o come\u00e7o no mundo do trabalho. Ele \u00e9 da cidade de Pirambu, mas veio para a capital estudar e, agora, j\u00e1 sonha em trabalhar. \u201cA nossa expectativa \u00e9 abra\u00e7ar a oportunidade, que \u00e9 fundamental para a gente. Como eu sou do interior, vai tamb\u00e9m me auxiliar nos estudos, para me manter\u201d, contou.<\/p>\n\n\n\n<p>Sensa\u00e7\u00e3o semelhante sentiu a participante Maria Eduarda, que, segundo ela, est\u00e1 experimentando o que chamou de \u201cvirada de chave\u201d imensa em sua vida. \u201cEstava em busca de uma oportunidade e n\u00e3o encontrava at\u00e9 o edital do Primeiro Emprego, quando eu fui selecionada e fiquei muito feliz, porque \u00e9 uma coisa que nem todos os jovens, por si, conseguem ter, \u00e9 mais dif\u00edcil. Minha expectativa \u00e9 grande e espero muito que eu consiga atingir todos os objetivos, que eu consiga realizar meus sonhos. Todos os jovens querem conquistar suas coisas e muitos n\u00e3o t\u00eam oportunidade, mas hoje, o programa est\u00e1 abrindo portas. \u00c9 uma coisa que \u00e9 maravilhosa, \u00e9 um sentimento bom\u201d, relatou satisfeita.<\/p>\n\n\n\n<p>A aula inaugural teve a participa\u00e7\u00e3o de jovens egressos, que j\u00e1 fizeram parte do PPE e hoje se encontram trabalhando por conta da iniciativa do governo estadual. Ap\u00f3s a fala de um deles, o governador F\u00e1bio Mitidieri fez as suas considera\u00e7\u00f5es. \u201cFico muito grato quando ou\u00e7o esse tipo de depoimento, porque a gente faz tudo isso para eles. Eles aqui est\u00e3o empolgados por trabalhar e ter uma oportunidade, conseguir o seu sustento, que muitas vezes \u00e9 tamb\u00e9m o sustento da sua fam\u00edlia. Ent\u00e3o \u00e9 importante isso, mostrar que o caminho \u00e9 atrav\u00e9s do trabalho, atrav\u00e9s da qualifica\u00e7\u00e3o, e a gente tem conseguido isso aqui, com programas como esse, o Primeiro Emprego e o Qualifica Sergipe\u201d, disse diante do audit\u00f3rio lotado.<\/p>\n\n\n\n<p>Capacita\u00e7\u00e3o<\/p>\n\n\n\n<p>O PPE \u00e9 realizado em parceria com o Servi\u00e7o Nacional de Aprendizagem Comercial (Senac\/SE), respons\u00e1vel por construir a trilha de conhecimento te\u00f3rico, e conta tamb\u00e9m com a participa\u00e7\u00e3o essencial de empresas privadas para o est\u00e1gio pr\u00e1tico. Ao final do per\u00edodo, as empresas se comprometem a absorver, no m\u00ednimo, 30% dos concluintes com o emprego registrado em carteira.<\/p>\n\n\n\n<p>\u201cHoje n\u00f3s temos turmas do Senac, um grande parceiro nesse processo de qualifica\u00e7\u00e3o profissionalizante, sobretudo do di\u00e1logo constru\u00eddo com o setor privado, que s\u00e3o important\u00edssimos dentro do programa. N\u00f3s qualificamos a m\u00e3o de obra de acordo com a necessidade do setor privado, que \u00e9 o nosso parceiro e assina a carteira dos jovens, um grande objetivo do programa. N\u00f3s sabemos que o emprego tem um papel social muito forte, porque tira o jovem da situa\u00e7\u00e3o de vulnerabilidade, permite o seu ingresso no mercado de trabalho, e a qualifica\u00e7\u00e3o profissionalizante catalisa esse processo, pois permite que o trabalhador possa almejar um sal\u00e1rio melhor e melhor qualidade de vida\u201d, analisa o secret\u00e1rio de Estado do Trabalho, Emprego e Empreendedorismo, Jorge Teles.<\/p>\n\n\n\n<p>Ap\u00f3s a solenidade, os novos selecionados tiveram uma palestra motivacional com a professora Cleciane Alves, com o tema &#8220;Do sonho \u00e0 conquista: qualifica\u00e7\u00e3o como passo decisivo para o sucesso no mercado de trabalho&#8221;, al\u00e9m de orienta\u00e7\u00f5es passadas pela coordena\u00e7\u00e3o do PPE. Lan\u00e7ado em agosto de 2023, o programa tamb\u00e9m garante bolsa financeira durante seis meses, para auxiliar na manuten\u00e7\u00e3o do participante em sala de aula. As turmas de hoje foram selecionadas por meio do Edital n\u00ba 01\/2025, publicado no portal da Seteem<\/p>\n\n\n\n<p>Presen\u00e7as<\/p>\n\n\n\n<p>Dentre as autoridades presentes, estiveram o diretor de Trabalho e Emprego do MTE, Bruno Motta, o senador La\u00e9rcio Oliveira, o presidente do Fonset, Vladyson Viana, a deputada Katarina Feitosa, o vereador Levi Oliveira, a superintende de Estado da Juventude, Anne Livianne, o diretor pedag\u00f3gico do Senac, Adalberto Trindade, al\u00e9m de integrantes do F\u00f3rum Nacional de Secret\u00e1rios do Trabalho, que est\u00e3o na capital sergipana participando de assembleia do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p>Fotos: Reinaldo Moura<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais 200 jovens sergipanos iniciam suas jornadas de aprendizado no Programa Primeiro Emprego (PPE). Nesta sexta-feira, 30, o Governo de Sergipe, por meio da Secretaria de Estado do Trabalho, Emprego e Empreendedorismo (Seteem), realizou aula inaugural de 17 diferentes cursos. A solenidade contou com a presen\u00e7a do governador do estado F\u00e1bio Mitidieri e de v\u00e1rias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,6,2],"tags":[],"class_list":["post-9305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-letreiro","category-politica"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9305"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9305\/revisions"}],"predecessor-version":[{"id":9307,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9305\/revisions\/9307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9306"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}