{"id":9456,"date":"2025-06-02T09:38:28","date_gmt":"2025-06-02T12:38:28","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9456"},"modified":"2025-06-02T09:38:29","modified_gmt":"2025-06-02T12:38:29","slug":"com-vista-privilegiada-do-palco-360-graus-camarote-do-jobim-se-destaca-no-arraia-do-povo","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/02\/com-vista-privilegiada-do-palco-360-graus-camarote-do-jobim-se-destaca-no-arraia-do-povo\/","title":{"rendered":"Com vista privilegiada do palco 360 graus, camarote do Jobim se destaca no Arrai\u00e1 do Povo"},"content":{"rendered":"\n<p>O Arrai\u00e1 do Povo, um dos maiores festejos juninos do Brasil, j\u00e1 come\u00e7ou na Orla da Atalaia, em Aracaju, e promete 30 dias de muita m\u00fasica, cultura e tradi\u00e7\u00e3o nordestina. Em meio a essa celebra\u00e7\u00e3o, o camarote do Jobim surge como uma op\u00e7\u00e3o premium para quem busca conforto, boa gastronomia e uma vista privilegiada do palco 360 graus.&nbsp;<\/p>\n\n\n\n<p>Localizado em um ponto estrat\u00e9gico da arena de shows, o camarote oferece diferentes op\u00e7\u00f5es de ingressos para atender a diversos p\u00fablicos: desde ingressos individuais at\u00e9 lounges para seis pessoas, equipados com sof\u00e1 e mesa bistr\u00f4, al\u00e9m de mesas bistr\u00f4s separadas. Essa variedade proporciona flexibilidade para grupos de amigos, casais ou fam\u00edlias que desejam aproveitar o melhor do S\u00e3o Jo\u00e3o com comodidade.<\/p>\n\n\n\n<p>O Jobim, conhecido por sua culin\u00e1ria brasileira com toques cariocas e ambiente acolhedor, leva para o camarote a mesma excel\u00eancia que o consagrou em Aracaju. Com diversas bebidas e petiscos deliciosos, o card\u00e1pio \u00e9 um convite \u00e0 celebra\u00e7\u00e3o dos sabores nacionais. Al\u00e9m da gastronomia de qualidade, o camarote do Jobim proporciona uma experi\u00eancia completa com atendimento diferenciado e uma atmosfera que combina o melhor da festa junina com o conforto de um espa\u00e7o exclusivo.<\/p>\n\n\n\n<p>Para mais informa\u00e7\u00f5es sobre ingressos e reservas no camarote do Jobim o link \u00e9 o<\/p>\n\n\n\n<p>https:\/\/www.outgo.com.br\/loungejobim e o instagram \u00e9 o @jobim.aju<\/p>\n\n\n\n<p>Texto e foto Martins Assessoria de Comunica\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Arrai\u00e1 do Povo, um dos maiores festejos juninos do Brasil, j\u00e1 come\u00e7ou na Orla da Atalaia, em Aracaju, e promete 30 dias de muita m\u00fasica, cultura e tradi\u00e7\u00e3o nordestina. Em meio a essa celebra\u00e7\u00e3o, o camarote do Jobim surge como uma op\u00e7\u00e3o premium para quem busca conforto, boa gastronomia e uma vista privilegiada do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,7],"tags":[],"class_list":["post-9456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9456"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9456\/revisions"}],"predecessor-version":[{"id":9458,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9456\/revisions\/9458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9457"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}