{"id":9487,"date":"2025-06-02T12:37:49","date_gmt":"2025-06-02T15:37:49","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9487"},"modified":"2025-06-02T12:37:49","modified_gmt":"2025-06-02T15:37:49","slug":"participacao-de-sergipe-na-bnt-mercosul-2025-e-elogiada-pelo-publico-participante","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/02\/participacao-de-sergipe-na-bnt-mercosul-2025-e-elogiada-pelo-publico-participante\/","title":{"rendered":"Participa\u00e7\u00e3o de Sergipe na BNT Mercosul 2025 \u00e9 elogiada pelo p\u00fablico participante"},"content":{"rendered":"\n<p>Sergipe fez bonito na BNT Mercosul, realizada entre os dias 30 e 31 de maio, em Balne\u00e1rio Cambori\u00fa, no estado de Santa Catarina. Uma das principais feiras de neg\u00f3cios tur\u00edsticos do Brasil, o evento reuniu cerca de 6,5 mil agentes de viagens e profissionais do turismo no Expocentro J\u00falio Tedesco. O estande sergipano com 50 metros quadrados foi bastante visitado e encantou o p\u00fablico ao exaltar os atrativos tur\u00edsticos, como as belezas naturais, a deliciosa gastronomia e a rica cultura, com destaque para os festejos juninos. A a\u00e7\u00e3o foi promovida pelo Governo de Sergipe, por meio da Secretaria de Estado do Turismo (Setur), em parceria com a Associa\u00e7\u00e3o Brasileira da Ind\u00fastria de Hot\u00e9is de Sergipe (ABIH\/SE).<\/p>\n\n\n\n<p>Os profissionais se surpreenderam, ainda, com o fato de a gest\u00e3o estadual promover, gratuitamente, 60 dias ininterruptos de forr\u00f3, de 30 de maio a 27 de julho. Al\u00e9m disso, eles se mostraram impressionados com o Arrai\u00e1 do Povo e a Vila do Forr\u00f3 acontecerem na Orla da Atalaia, considerada a mais bonita e mais bem-equipada do pa\u00eds, proporcionando que os festejos juninos sergipanos sejam os mais aconchegantes \u00e0 beira-mar do Brasil. Vale destacar, ainda, que o Governo de Sergipe tamb\u00e9m apoia as festas desse per\u00edodo em todo o estado.<\/p>\n\n\n\n<p>De acordo com a secret\u00e1ria-executiva da Setur, Daniela Mesquita, participar, mais uma vez, da BNT Mercosul foi uma oportunidade de mostrar ao Sul do Brasil o que Sergipe tem de melhor: as belezas naturais, a gastronomia, a cultura e, principalmente, os 60 dias de forr\u00f3 \u00e0 beira-mar. \u201cSergipe fez bonito na BNT Mercosul. Somos o estado mais acolhedor do Brasil e com um potencial tur\u00edstico gigante. Temos cultura vibrante, gastronomia rica, povo acolhedor e belezas naturais que encantam o mundo. Tamb\u00e9m temos nossas festas juninas, que s\u00e3o um espet\u00e1culo \u00e0 parte. Sergipe convida o Brasil e o mundo a viverem essa experi\u00eancia inesquec\u00edvel!\u201d, ressalta.<\/p>\n\n\n\n<p>As pessoas que passaram pelo estande e os agentes que participaram da capacita\u00e7\u00e3o promovida pela equipe Setur-ABIH\/SE ficaram encantados e surpresos com as riquezas que o estado tem a oferecer, o que se pode fazer no destino. A agente de viagens Elite Appelt, da Meridian Tour, de Florian\u00f3polis, foi uma delas. No auge dos seus 25 anos de atua\u00e7\u00e3o no ramo, afirma que ficou encantada pela beleza do estande, que, segundo ela, t\u00e3o bem retratou a identidade sergipana. Ressaltou, ainda, o fato de Sergipe ser um destino muito diferente do que ela e os colegas vivenciam na regi\u00e3o sulista. \u201cDiante de tantas belezas apresentadas, a gente precisa explorar mais Sergipe. Precisamos mandar os clientes para l\u00e1, tamb\u00e9m. Inclusive, como ainda n\u00e3o conhe\u00e7o o destino, gostaria de conhecer ainda este ano\u201d, declara.<\/p>\n\n\n\n<p>Com 20 anos de experi\u00eancia no ramo, a propriet\u00e1ria da Sol Tur Turismo, Ros\u00e2ngela Grassmann K\u00fclzer, de Canoas (RS), foi s\u00f3 elogios a Sergipe, destino que j\u00e1 conhece. Segundo ela, ali\u00e1s, est\u00e1 se organizando para trazer mais um grupo ao estado. \u201cAdorei a hospitalidade do povo sergipano em primeiro lugar. A comida \u00e9 deliciosa, adoro a castanha. E tem os lugares incr\u00edveis que conheci. Sergipe est\u00e1 sendo mais divulgado no mercado de turismo, como podemos ver aqui na BNT. Como agente de viagem, j\u00e1 pretendo levar mais grupos para Sergipe, mostrando o quanto o lugar \u00e9 bonito. Ent\u00e3o, se torna uma facilidade para n\u00f3s vendermos o destino\u201d, assegura.<\/p>\n\n\n\n<p>Foto: Pietro Lobo\/Setur<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sergipe fez bonito na BNT Mercosul, realizada entre os dias 30 e 31 de maio, em Balne\u00e1rio Cambori\u00fa, no estado de Santa Catarina. Uma das principais feiras de neg\u00f3cios tur\u00edsticos do Brasil, o evento reuniu cerca de 6,5 mil agentes de viagens e profissionais do turismo no Expocentro J\u00falio Tedesco. O estande sergipano com 50 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,7],"tags":[],"class_list":["post-9487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9487"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9487\/revisions"}],"predecessor-version":[{"id":9489,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9487\/revisions\/9489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9488"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}