{"id":9557,"date":"2025-06-03T05:10:16","date_gmt":"2025-06-03T08:10:16","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9557"},"modified":"2025-06-03T05:10:16","modified_gmt":"2025-06-03T08:10:16","slug":"segundona-do-turista-encanta-sergipanos-e-turistas-com-apresentacao","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/03\/segundona-do-turista-encanta-sergipanos-e-turistas-com-apresentacao\/","title":{"rendered":"Segundona do Turista encanta sergipanos e turistas com apresenta\u00e7\u00e3o"},"content":{"rendered":"\n<p>A primeira edi\u00e7\u00e3o de junho da Segundona do Turista deu o tom do m\u00eas mais festivo do ano com muito forr\u00f3 arrasta-p\u00e9, anima\u00e7\u00e3o e valoriza\u00e7\u00e3o da cultura popular. Nesta segunda-feira, 2, a centen\u00e1ria Rua S\u00e3o Jo\u00e3o, no bairro Industrial, em Aracaju, reuniu fam\u00edlias, amigos e turistas em torno das tradi\u00e7\u00f5es juninas. O evento \u00e9 uma realiza\u00e7\u00e3o do Governo de Sergipe, por meio da Funda\u00e7\u00e3o de Cultura e Arte Aperip\u00ea (Funcap).<\/p>\n\n\n\n<p>Como um dos destaques do calend\u00e1rio cultural sergipano, a Segundona do Turista vai acontecer semanalmente durante o m\u00eas de junho e julho, em sintonia com as festividades de S\u00e3o Jo\u00e3o.&nbsp; A iniciativa \u00e9 realizada em parceria com o Centro Social e Cultural S\u00e3o Jo\u00e3o de Deus, e conta com o apoio das secretarias de Estado do Turismo (Setur), do Trabalho, Emprego e Empreendedorismo (Seteem), e de Comunica\u00e7\u00e3o Social (Secom).&nbsp; Al\u00e9m de celebrar a cultura popular, o evento movimenta a economia local, fortalece o turismo e gera oportunidades para empreendedores na tradicional Rua S\u00e3o Jo\u00e3o.<\/p>\n\n\n\n<p>Encantamento<\/p>\n\n\n\n<p>Da Venezuela, a contadora Marice Ramirez, de 28 anos, que est\u00e1 viajando pelo Brasil, se disse encantada com a cultura do \u2018pa\u00eds do forr\u00f3\u2019. &#8220;Estou amando esse clima festivo. Tudo muito animado, cheio de m\u00fasica e de dan\u00e7a. Nunca tinha visto uma festa assim, com tanta alegria. Quero aproveitar cada cantinho de Aracaju antes de voltar pra casa, mas at\u00e9 l\u00e1, pretendo dan\u00e7ar forr\u00f3 todos os dias&#8221;, afirmou.<\/p>\n\n\n\n<p>Curtindo em fam\u00edlia, o casal Gleize Santos e Valter Santos trouxe a filha Maria Luzia de dois anos para aproveitar a Segundona do Turista. Para Gleize, essa \u00e9 uma tradi\u00e7\u00e3o que precisa ser passada de gera\u00e7\u00e3o em gera\u00e7\u00e3o. \u201cViver a Rua de S\u00e3o Jo\u00e3o \u00e9 tradi\u00e7\u00e3o. Se n\u00e3o vier pra c\u00e1, \u00e9 como se o per\u00edodo junino n\u00e3o valesse. Poder trazer a nossa filha aqui \u00e9 maravilhoso, resgata ra\u00edzes e criamos mem\u00f3rias inesquec\u00edveis\u201d, disse.<\/p>\n\n\n\n<p>Economia<\/p>\n\n\n\n<p>Estreando como ambulante na Rua do Turista, com uma barraca de espetinho, Aline Carla destaca a import\u00e2ncia de manter vivas as tradi\u00e7\u00f5es culturais do espa\u00e7o. &#8220;Essa \u00e9 a minha primeira vez aqui vendendo, e estou muito feliz em fazer parte desse movimento. A Rua do Turista tem uma hist\u00f3ria linda, e ver esse resgate acontecendo \u00e9 bom pra gente que trabalha e tamb\u00e9m para quem vem aproveitar. O Governo do Estado est\u00e1 de parab\u00e9ns por essa iniciativa&#8221;, ressaltou.<\/p>\n\n\n\n<p>J\u00e1 para a ambulante Ang\u00e9lica de Melo, que vende pipoca durante o evento, a expectativa \u00e9 que o movimento da Segundona do Turista deste ano supere o da edi\u00e7\u00e3o anterior. \u201cAno passado foi muito bom, teve bastante movimento. Mas este ano, desde o come\u00e7o, eu j\u00e1 percebi que as vendas melhoraram bastante. O p\u00fablico est\u00e1 mais animado, tem mais gente circulando e comprando. A gente se prepara para esse momento, ent\u00e3o \u00e9 muito gratificante ver o retorno positivo\u201d, avaliou.<\/p>\n\n\n\n<p>Programa\u00e7\u00e3o<\/p>\n\n\n\n<p>Nesta segunda-feira, a programa\u00e7\u00e3o foi aberta pelo artista sergipano Ivanildo do Acordeon, acompanhado do Trio Cristalino, que animou o p\u00fablico com um repert\u00f3rio de forr\u00f3 tradicional. \u201cEstou sem palavras com essa energia maravilhosa. N\u00e3o imaginei que o espa\u00e7o pudesse lotar e fiquei surpreso. O S\u00e3o Jo\u00e3o tradicional \u00e9 a nossa ess\u00eancia, \u00e9 a nossa vida\u201d, expressou o artista.<\/p>\n\n\n\n<p>Em seguida, o grupo de quadrilha junina Assum Preto, da Grande Aracaju, encantou o p\u00fablico no quadrilh\u00f3dromo com sua apresenta\u00e7\u00e3o repleta de m\u00fasica, coreografia e a tradicional magia das festas juninas. Com mais de 35 anos de hist\u00f3ria, o grupo reafirmou sua trajet\u00f3ria de dedica\u00e7\u00e3o \u00e0 cultura popular.<\/p>\n\n\n\n<p>Fundador e marcador da tradicional quadrilha junina Assum Preto, Genicleudo Melo enfatizou a import\u00e2ncia cultural e econ\u00f4mica do movimento junino no Brasil. Segundo ele, os grupos de quadrilha n\u00e3o apenas representam uma express\u00e3o art\u00edstica popular, mas tamb\u00e9m desempenham um papel estrat\u00e9gico no fortalecimento do turismo local. \u201cA quadrilha junina j\u00e1 n\u00e3o \u00e9 apenas um atrativo complementar do turismo, ela se consolidou como um produto tur\u00edstico de valor, que movimenta a economia, gera empregos e encanta o p\u00fablico com sua beleza, criatividade e tradi\u00e7\u00e3o&#8221;, explicou.<\/p>\n\n\n\n<p>O encerramento do evento ficou por conta da banda Capunga do Forr\u00f3, que levantou o p\u00fablico com um repert\u00f3rio animado e cheio de arrasta-p\u00e9. \u201cH\u00e1 16 anos na estrada, e \u00e9 sempre uma satisfa\u00e7\u00e3o ver as pessoas felizes e dan\u00e7ando o aut\u00eantico forr\u00f3 nordestino. Fico com um friozinho na barriga toda vez que subo no palco, mas quando o p\u00fablico interage e se diverte, a ansiedade vira alegria e toma conta do meu cora\u00e7\u00e3o\u201d, contou Capunga do Forr\u00f3, entusiasmado.<\/p>\n\n\n\n<p>Segundona do Turista<\/p>\n\n\n\n<p>A Segundona do Turista busca valorizar artistas locais e levar a cultura sergipana a diferentes regi\u00f5es do estado. O evento acontece \u00e0s segundas-feiras e segue com programa\u00e7\u00e3o at\u00e9 dezembro, com shows de forr\u00f3, quadrilhas juninas e apresenta\u00e7\u00f5es de grupos folcl\u00f3ricos e parafolcl\u00f3ricos.<\/p>\n\n\n\n<p>Foto: Erick O&#8217;Hara<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A primeira edi\u00e7\u00e3o de junho da Segundona do Turista deu o tom do m\u00eas mais festivo do ano com muito forr\u00f3 arrasta-p\u00e9, anima\u00e7\u00e3o e valoriza\u00e7\u00e3o da cultura popular. Nesta segunda-feira, 2, a centen\u00e1ria Rua S\u00e3o Jo\u00e3o, no bairro Industrial, em Aracaju, reuniu fam\u00edlias, amigos e turistas em torno das tradi\u00e7\u00f5es juninas. O evento \u00e9 uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-9557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-noticias"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9557"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9557\/revisions"}],"predecessor-version":[{"id":9559,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9557\/revisions\/9559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9558"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}