{"id":9578,"date":"2025-06-03T07:04:19","date_gmt":"2025-06-03T10:04:19","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9578"},"modified":"2025-06-03T07:04:21","modified_gmt":"2025-06-03T10:04:21","slug":"consulta-a-locais-da-prova-objetiva-do-concurso-para-gestor-governamental-esta-disponivel","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/03\/consulta-a-locais-da-prova-objetiva-do-concurso-para-gestor-governamental-esta-disponivel\/","title":{"rendered":"Consulta a locais da prova objetiva do concurso para gestor governamental est\u00e1 dispon\u00edvel"},"content":{"rendered":"\n<p>Os inscritos no concurso p\u00fablico realizado pelo Governo do Estado para o cargo de especialista em pol\u00edticas p\u00fablicas e gest\u00e3o governamental (EPPGG) podem acessar, a partir desta segunda-feira, 2, no endere\u00e7o eletr\u00f4nico conhecimento.fgv.br\/concursos\/seadse25, o cart\u00e3o de confirma\u00e7\u00e3o de inscri\u00e7\u00e3o para conhecer os locais de realiza\u00e7\u00e3o da prova objetiva, que ser\u00e1 aplicada no pr\u00f3ximo domingo, 8 de junho. Conduzido pela Secretaria de Estado da Administra\u00e7\u00e3o (Sead) e organizado pela Funda\u00e7\u00e3o Get\u00falio Vargas (FGV), o certame vai selecionar profissionais para o provimento de sete vagas e forma\u00e7\u00e3o de cadastro reserva do quadro de pessoal da Administra\u00e7\u00e3o Estadual. &nbsp;<\/p>\n\n\n\n<p>O concurso para EPPGG de Sergipe, cargo cujo subs\u00eddio inicial \u00e9 de R$ 12,4 mil, est\u00e1 dividido em duas etapas. Na primeira delas, o candidato classificado na prova objetiva, dentro do limite estabelecido no edital, ser\u00e1 convocado para a prova discursiva e de t\u00edtulos. Por fim, os classificados na primeira etapa, dentro do quantitativo previamente definido, ser\u00e3o convocados para o curso de forma\u00e7\u00e3o, tamb\u00e9m de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, que constitui a segunda etapa da sele\u00e7\u00e3o.<\/p>\n\n\n\n<p>Conforme o cronograma previsto, a divulga\u00e7\u00e3o do gabarito preliminar da prova objetiva ser\u00e1 realizada no dia 10 de junho, e os candidatos poder\u00e3o interpor recursos nos dias 11 e 12. O gabarito definitivo e o resultado preliminar da prova objetiva ser\u00e3o divulgados no dia 7 de julho. A convoca\u00e7\u00e3o para a prova discursiva ser\u00e1 divulgada no dia 22 de julho, mesma data em que ocorrer\u00e1 a divulga\u00e7\u00e3o do resultado definitivo da prova objetiva. A prova discursiva est\u00e1 programada para 3 de agosto.<\/p>\n\n\n\n<p>Para a secret\u00e1ria de Estado da Administra\u00e7\u00e3o, Lucivanda Nunes, o concurso \u00e9 parte do processo de reestrutura\u00e7\u00e3o de carreiras e de recomposi\u00e7\u00e3o do quadro de pessoal do Estado, desenvolvido pelo Governo de Sergipe para aprimorar os servi\u00e7os prestados \u00e0 popula\u00e7\u00e3o. \u201cO gestor governamental ocupa uma fun\u00e7\u00e3o estrat\u00e9gica e fundamental na Administra\u00e7\u00e3o Estadual, atuando na elabora\u00e7\u00e3o e implementa\u00e7\u00e3o das pol\u00edticas p\u00fablicas desenvolvidas pelo governo para melhorar a qualidade de vida dos sergipanos\u201d, ressalta.<\/p>\n\n\n\n<p>Institu\u00edda pela Lei estadual n\u00ba 4.302\/2000, a carreira de EPPGG \u00e9 t\u00edpica de Estado e essencial ao aperfei\u00e7oamento da gest\u00e3o e da governan\u00e7a na Administra\u00e7\u00e3o Estadual. S\u00e3o \u00e1reas t\u00edpicas da atua\u00e7\u00e3o dos gestores governamentais, dentre outras, planejamento governamental, or\u00e7amento p\u00fablico, finan\u00e7as, gest\u00e3o de pessoas, contrata\u00e7\u00f5es p\u00fablicas, patrim\u00f4nio, elabora\u00e7\u00e3o legislativa, gest\u00e3o de projetos e inova\u00e7\u00e3o.<\/p>\n\n\n\n<p>Foto: Ascom\/Sead<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os inscritos no concurso p\u00fablico realizado pelo Governo do Estado para o cargo de especialista em pol\u00edticas p\u00fablicas e gest\u00e3o governamental (EPPGG) podem acessar, a partir desta segunda-feira, 2, no endere\u00e7o eletr\u00f4nico conhecimento.fgv.br\/concursos\/seadse25, o cart\u00e3o de confirma\u00e7\u00e3o de inscri\u00e7\u00e3o para conhecer os locais de realiza\u00e7\u00e3o da prova objetiva, que ser\u00e1 aplicada no pr\u00f3ximo domingo, 8 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9579,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,7],"tags":[],"class_list":["post-9578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9578"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9578\/revisions"}],"predecessor-version":[{"id":9580,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9578\/revisions\/9580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9579"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}