{"id":9590,"date":"2025-06-03T08:19:43","date_gmt":"2025-06-03T11:19:43","guid":{"rendered":"https:\/\/espacolivresergipe.com.br\/?p=9590"},"modified":"2025-06-03T08:19:44","modified_gmt":"2025-06-03T11:19:44","slug":"governo-do-estado-fomenta-e-promove-futebol-amador-com-1o-copa-serigy","status":"publish","type":"post","link":"https:\/\/espacolivresergipe.com.br\/index.php\/2025\/06\/03\/governo-do-estado-fomenta-e-promove-futebol-amador-com-1o-copa-serigy\/","title":{"rendered":"Governo do Estado fomenta e promove futebol amador com 1\u00ba Copa Serigy"},"content":{"rendered":"\n<p>Com o objetivo de fortalecer o esporte como instrumento de inclus\u00e3o social e valorizar talentos locais, o Governo de Sergipe vai promover a 1\u00ba Copa Serigy entre os meses de agosto e outubro deste ano. A expectativa \u00e9 que o evento tenha dura\u00e7\u00e3o de 10 finais de semana, com disputas nas categorias masculina e feminina, refor\u00e7ando o compromisso com a inclus\u00e3o e equidade de g\u00eanero no futebol.<\/p>\n\n\n\n<p>Respons\u00e1vel por executar a competi\u00e7\u00e3o, a Secretaria de Estado do Esporte e Lazer (Seel) ir\u00e1 fornecer uniformes oficiais para atletas e \u00e1rbitros, al\u00e9m de distribuir materiais esportivos como bolas e redes. A Seel tamb\u00e9m atua diretamente na organiza\u00e7\u00e3o estrutural e log\u00edstica do campeonato de futebol amador, que deve reunir sele\u00e7\u00f5es dos 75 munic\u00edpios sergipanos. A secretaria visa assegurar que o torneio ocorra com qualidade, seguran\u00e7a e amplo acesso para todos os munic\u00edpios envolvidos. O investimento previsto para a realiza\u00e7\u00e3o do evento \u00e9 de R$ 1 milh\u00e3o.<\/p>\n\n\n\n<p>Todos os munic\u00edpios poder\u00e3o inscrever sele\u00e7\u00f5es, sendo obrigat\u00f3ria a participa\u00e7\u00e3o de equipes femininas como crit\u00e9rio para a entrada na competi\u00e7\u00e3o. A exig\u00eancia tem o intuito de garantir a presen\u00e7a ativa das mulheres no futebol amador estadual.<\/p>\n\n\n\n<p>J\u00e1 abertas, as inscri\u00e7\u00f5es s\u00e3o gratuitas e podem ser realizadas pela plataforma digital PlacarSoft, por meio do site da Seel (se.gov.br\/seel\/copa_serigy) at\u00e9 15 de julho. Um indicado por cada munic\u00edpio, nomeado pelo chefe do executivo municipal ficar\u00e1 respons\u00e1vel por todo o processo de inscri\u00e7\u00e3o e gerenciamento durante a realiza\u00e7\u00e3o do torneio. Cada equipe dever\u00e1 inscrever 25 atletas, com 50% dos jogadores entre 16 e 20 anos na categoria masculina. No feminino, a idade m\u00ednima tamb\u00e9m ser\u00e1 de 16 anos, mas n\u00e3o haver\u00e1 limite de idade. Para representar a cidade, a pessoa jogadora precisa comprovar a resid\u00eancia no munic\u00edpio.<\/p>\n\n\n\n<p>A Copa ser\u00e1 dividida em 8 regionais, com sedes ainda a serem definidas. Cada partida contar\u00e1 com equipe de socorristas, seguran\u00e7a especializada e apoio log\u00edstico coordenado entre munic\u00edpios e o Estado.<\/p>\n\n\n\n<p>Premia\u00e7\u00e3o<\/p>\n\n\n\n<p>A premia\u00e7\u00e3o da 1\u00ba Copa Serigy consistir\u00e1 na entrega de trof\u00e9us e medalhas para os dois melhores colocados de cada regional; pr\u00eamios para campe\u00e3o, vice e terceiro colocados da Supercopa Estadual; e trof\u00e9us especiais para melhor t\u00e9cnico, artilheiro e melhor goleiro.<\/p>\n\n\n\n<p>Foto: Igor Matias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de fortalecer o esporte como instrumento de inclus\u00e3o social e valorizar talentos locais, o Governo de Sergipe vai promover a 1\u00ba Copa Serigy entre os meses de agosto e outubro deste ano. A expectativa \u00e9 que o evento tenha dura\u00e7\u00e3o de 10 finais de semana, com disputas nas categorias masculina e feminina, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,6,7],"tags":[],"class_list":["post-9590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letreiro","category-sergipe"],"_links":{"self":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9590"}],"version-history":[{"count":1,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions"}],"predecessor-version":[{"id":9592,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9590\/revisions\/9592"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media\/9591"}],"wp:attachment":[{"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/espacolivresergipe.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}